{"id":36565,"date":"2026-05-08T10:43:55","date_gmt":"2026-05-08T16:43:55","guid":{"rendered":"https:\/\/brakkeconsulting.com\/?p=36565"},"modified":"2026-05-08T10:43:55","modified_gmt":"2026-05-08T16:43:55","slug":"this-week-in-animal-health-earnings-reports-dominate-the-news","status":"publish","type":"post","link":"https:\/\/brakkeconsulting.com\/pt\/this-week-in-animal-health-earnings-reports-dominate-the-news\/","title":{"rendered":"Esta semana em sa\u00fade animal: os relat\u00f3rios de resultados financeiros dominam as not\u00edcias."},"content":{"rendered":"<p>***********************************<br \/>\n<strong>Brakke Consulting&#039;s\u00a0<\/strong><br \/>\n<strong>Not\u00edcias e notas sobre sa\u00fade animal para 8 de maio de 2026<br \/>\n<\/strong><em>Copyright \u00a9 Brakke Consulting<\/em><br \/>\n<em>Editora: Christine Merle DVM, MBA, CVPM<\/em><em>\u202f<\/em><br \/>\n************************************<\/p>\n<p>NAS NOTICIAS:<br \/>\n<u>Brakke Consultoria<br \/>\n<\/u>Estudo de Entrega Domiciliar de Medicamentos para Animais de Estima\u00e7\u00e3o em 2026<u><br \/>\n<\/u>Hist\u00f3rias de Talento: Li\u00e7\u00f5es de Branding para Vencer a Concorr\u00eancia na \u00c1rea de Recrutamento<u><\/p>\n<p>Ganhar not\u00edcias<br \/>\n<\/u>Cencora (Sa\u00fade Animal MWI)<br \/>\nJardim central e animal de estima\u00e7\u00e3o<br \/>\nColgate-Palmolive (Hill&#039;s Pet Nutrition)<br \/>\nElanco<br \/>\nFreshpet<br \/>\nLaborat\u00f3rios IDEXX<br \/>\nFibro<br \/>\nZoetis<br \/>\nZomedica<\/p>\n<p><u>Not\u00edcias da empresa<\/u><br \/>\nAniVC<br \/>\nFundo de Busca Aurica (SP)<br \/>\nbimeda<br \/>\ndsm-firmenich (EMEA)<br \/>\nDigitalis Ventures<br \/>\nTerras agr\u00edcolas (Nova Zel\u00e2ndia)<br \/>\nGalante<br \/>\nGeneral Mills<br \/>\nCrian\u00e7a de Ouro<br \/>\nNutri\u00e7\u00e3o para animais de estima\u00e7\u00e3o da Hill&#039;s<br \/>\nHomewardVet<br \/>\nsa\u00fade jaguar<br \/>\nOrion Corporation<br \/>\nSabores para animais de estima\u00e7\u00e3o<br \/>\nPetMade<br \/>\nFibro<br \/>\nRigi Capital (SP)<br \/>\nDiana da Super (SP)<br \/>\nTechion (Nova Zel\u00e2ndia)<br \/>\nTravv<br \/>\nTecnologias VAXA<\/p>\n<p><u>Not\u00edcias sobre sa\u00fade animal<br \/>\n<\/u>Global<br \/>\nReino Unido<br \/>\nEstados Unidos<\/p>\n<p>************************************<br \/>\n<strong>Divulga\u00e7\u00e3o de Lucros da Empresa<\/strong><\/p>\n<ul>\n<li><strong>Cencora<\/strong><span data-contrast=\"auto\">A empresa reportou receita de US$ 78,4 bilh\u00f5es no segundo trimestre do ano fiscal de 2026, um aumento de US$ 3,81 trilh\u00f5es em rela\u00e7\u00e3o ao mesmo per\u00edodo do ano anterior. A MWI Animal Health, que faz parte do segmento &quot;Outros&quot; e agora \u00e9 contabilizada como &quot;mantida para venda&quot;, contribuiu para o aumento de US$ 1,11 trilh\u00e3o nesse segmento.<\/span><a href=\"https:\/\/investor.cencora.com\/news\/news-details\/2026\/Cencora-Reports-Fiscal-2026-Second-Quarter-Results\/default.aspx\"><em>comunicado de imprensa da empresa<\/em><\/a>)<span data-ccp-props=\"{}\"><br \/>\n<\/span><\/li>\n<li><strong>Jardim central e animal de estima\u00e7\u00e3o<\/strong><span data-contrast=\"auto\">A Central registrou seu segundo trimestre fiscal de 2026 com vendas l\u00edquidas superiores a US$ 1,5 bilh\u00e3o nos primeiros seis meses. Ao final do trimestre, a Central iniciou um novo neg\u00f3cio de distribui\u00e7\u00e3o de produtos para animais de estima\u00e7\u00e3o com a Phillips Pet Food &amp; Supplies.<\/span><a href=\"https:\/\/ir.central.com\/news-events\/press-releases\/detail\/479\/central-garden-pet-announces-record-q2-fiscal-2026\"><em>comunicado de imprensa da empresa<\/em><\/a>)<span data-ccp-props=\"{}\"><br \/>\n<\/span><\/li>\n<li><span data-contrast=\"auto\"> <strong>Colgate Palmolive\u00a0<\/strong><\/span><span data-contrast=\"auto\">A Hill&#039;s divulgou seus resultados do primeiro trimestre de 2026, refletindo um aumento de 8,41 trilh\u00f5es de d\u00f3lares nas vendas l\u00edquidas em compara\u00e7\u00e3o com o mesmo per\u00edodo do ano anterior. Seu neg\u00f3cio de Nutri\u00e7\u00e3o para Animais de Estima\u00e7\u00e3o contribuiu com 1,4 trilh\u00e3o de d\u00f3lares em lucro operacional, um aumento de 8,1 trilh\u00f5es de d\u00f3lares em rela\u00e7\u00e3o ao mesmo per\u00edodo do ano anterior.<\/span><a href=\"https:\/\/investor.colgatepalmolive.com\/static-files\/45a3017f-e0af-44aa-9590-fd37f3a7fd96\"><em>comunicado de imprensa da empresa<\/em><\/a>)<span data-ccp-props=\"{}\"><br \/>\n<\/span><\/li>\n<li><span data-contrast=\"auto\"> <strong>Elanco<\/strong><\/span><span data-contrast=\"auto\">A empresa divulgou seus resultados do primeiro trimestre de 2026, com receita de 1,371 bilh\u00e3o de d\u00f3lares, refletindo um crescimento de 15,3 bilh\u00f5es de d\u00f3lares (crescimento org\u00e2nico de 1,03 bilh\u00e3o de d\u00f3lares em moeda constante) em rela\u00e7\u00e3o ao mesmo per\u00edodo do ano anterior. O crescimento foi impulsionado tanto pela Sa\u00fade Animal (1,23 bilh\u00e3o de d\u00f3lares) quanto pela \u00e1rea de Animais de Fazenda (1,83 bilh\u00e3o de d\u00f3lares). A empresa tamb\u00e9m elevou suas proje\u00e7\u00f5es para o ano todo e suas metas de receita com inova\u00e7\u00e3o.<\/span><a href=\"https:\/\/investor.elanco.com\/press-releases\/press-releases-details\/2026\/Elanco-Animal-Health-Reports-First-Quarter-2026-Results\/default.aspx\"><em>comunicado de imprensa da empresa<\/em><\/a>)<span data-ccp-props=\"{}\"><br \/>\n<\/span><\/li>\n<li><span data-contrast=\"auto\"> <strong>Freshpet<\/strong><\/span><span data-contrast=\"auto\">A empresa divulgou seus resultados do primeiro trimestre de 2026, com um aumento de 13,11% nas vendas l\u00edquidas, atingindo 1,4 trilh\u00e3o de d\u00f3lares. A receita l\u00edquida atingiu 297,6 milh\u00f5es de d\u00f3lares em compara\u00e7\u00e3o com o mesmo per\u00edodo do ano anterior. A empresa tamb\u00e9m atualizou sua proje\u00e7\u00e3o para o ano todo, com crescimento das vendas l\u00edquidas na faixa de 8,1 a 1,1 trilh\u00e3o de d\u00f3lares.<\/span><a href=\"https:\/\/investors.freshpet.com\/news-releases\/news-release-details\/freshpet-inc-reports-first-quarter-2026-financial-results\"><em>comunicado de imprensa da empresa<\/em><\/a>)<\/li>\n<li><strong>IDEXX<\/strong>anunciou seus resultados do primeiro trimestre de 2026 com receita de 1,141 bilh\u00e3o, representando um aumento de 1,11 bilh\u00e3o de crescimento org\u00e2nico em rela\u00e7\u00e3o ao mesmo per\u00edodo do ano anterior. O crescimento foi impulsionado pelo grupo de Animais de Companhia, liderado por seu laborat\u00f3rio interno de diagn\u00f3sticos recorrentes, o VetLab (<a href=\"https:\/\/ir.idexx.com\/news-events\/press-releases\/detail\/408\/idexx-laboratories-announces-first-quarter-results\"><em>comunicado de imprensa da empresa<\/em><\/a>)<span data-ccp-props=\"{}\"><br \/>\n<\/span><\/li>\n<li><span data-contrast=\"auto\"> <strong>Fibro Sa\u00fade Animal<\/strong><\/span><span data-contrast=\"auto\">A empresa divulgou seus resultados do terceiro trimestre fiscal de 2026, com vendas l\u00edquidas de US$ 383,5 milh\u00f5es ($), um aumento de US$ 101,3T em rela\u00e7\u00e3o ao mesmo per\u00edodo do ano anterior. As vendas foram impulsionadas pela \u00e1rea de Sa\u00fade Animal, que atingiu US$ 291,2 milh\u00f5es ($), um aumento de US$ 131,3T em rela\u00e7\u00e3o ao ano anterior. A proje\u00e7\u00e3o para o ano fiscal de 2026 foi atualizada para refletir um crescimento de US$ 141,3T.<\/span><a href=\"https:\/\/investors.pahc.com\/press-releases\/press-release-details\/2026\/Phibro-Animal-Health-Corporation-Reports-Third-Quarter-Results-Updates-Financial-Guidance\/default.aspx\"><em>comunicado de imprensa da empresa<\/em><\/a>)<span data-ccp-props=\"{}\">\u00a0<\/span><\/li>\n<li><strong>Zoetis<\/strong><span data-contrast=\"auto\">A empresa anunciou seus resultados do primeiro trimestre de 2026, com receita de US$ 1,4 trilh\u00e3o, refletindo um crescimento de US$ 3,1 trilh\u00e3o em rela\u00e7\u00e3o ao mesmo per\u00edodo do ano anterior. Um mercado competitivo nas vendas de produtos para animais de companhia nos EUA levou a uma queda de US$ 3,1 trilh\u00e3o, enquanto o crescimento de US$ 3,1 trilh\u00e3o nas vendas de produtos para animais de produ\u00e7\u00e3o n\u00e3o conseguiu impedir uma queda geral de US$ 3,1 trilh\u00e3o na receita do segmento dos EUA em rela\u00e7\u00e3o ao mesmo per\u00edodo do ano anterior.<\/span><a href=\"https:\/\/investor.zoetis.com\/news\/news-details\/2026\/Zoetis-Announces-First-Quarter-2026-Results\/default.aspx\"><em>comunicado de imprensa da empresa<\/em><\/a>)<span data-ccp-props=\"{}\"><br \/>\n<\/span><\/li>\n<li><strong>Zomedica<\/strong><span data-contrast=\"auto\">A empresa divulgou seus resultados do primeiro trimestre de 2026 com $8,8 milh\u00f5es, um crescimento de 35% em rela\u00e7\u00e3o ao mesmo per\u00edodo do ano anterior. $2M dessa receita veio do segmento de neg\u00f3cios de Servi\u00e7os de Desenvolvimento.<\/span><a href=\"https:\/\/feeds.issuerdirect.com\/news-release.html?newsid=6805687552682694&amp;symbol=ZOM,ZOMDF\"><em>comunicado de imprensa da empresa<\/em><\/a>)<span data-ccp-props=\"{}\">\u00a0<\/span><\/li>\n<\/ul>\n<p>************************************<br \/>\n<strong>Brakke Consulting\/Trone Research and Consulting<br \/>\n<\/strong><strong>Estudo de entrega em domic\u00edlio de medicamentos para animais de estima\u00e7\u00e3o<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-36514\" src=\"https:\/\/brakkeconsulting.com\/wp-content\/uploads\/2026\/05\/PMHD-Study-300x200.png\" alt=\"\" width=\"300\" height=\"200\" \/><br \/>\n<\/strong><\/p>\n<p>Chegando no in\u00edcio do outono de 2026: Pr\u00e9-vendas j\u00e1 dispon\u00edveis.<\/p>\n<p>As vendas online de medicamentos para animais de estima\u00e7\u00e3o est\u00e3o crescendo rapidamente e, hoje em dia, os donos de animais t\u00eam mais op\u00e7\u00f5es do que nunca na hora de escolher onde comprar. Mas, nesse mercado em constante evolu\u00e7\u00e3o e altamente competitivo, algumas quest\u00f5es importantes permanecem: quem est\u00e1 capturando essa receita, como as cl\u00ednicas veterin\u00e1rias est\u00e3o se adaptando e o que influencia as decis\u00f5es dos donos de animais?<\/p>\n<p>O estudo &quot;Entrega Domiciliar de Medicamentos para Animais de Estima\u00e7\u00e3o 2026&quot;, desenvolvido pela Brakke Consulting e pela Trone Research &amp; Consulting, traz as respostas. Baseado em mais de uma d\u00e9cada de pesquisa, este estudo abrangente oferece uma vis\u00e3o fundamentada em dados sobre o cen\u00e1rio da entrega domiciliar, tanto da perspectiva do veterin\u00e1rio quanto do dono do animal de estima\u00e7\u00e3o.<\/p>\n<p>Com base em pesquisas com 400 veterin\u00e1rios e 1.200 donos de animais de estima\u00e7\u00e3o nos EUA, o estudo oferece informa\u00e7\u00f5es estatisticamente confi\u00e1veis sobre comportamento de compra, desempenho dos canais de distribui\u00e7\u00e3o e press\u00f5es competitivas. Ele explora tend\u00eancias importantes, como modelos de assinatura e entrega autom\u00e1tica, fideliza\u00e7\u00e3o de clientes, conformidade e a crescente influ\u00eancia de varejistas online e novos participantes do mercado.<\/p>\n<p>Os principais insights incluem:<\/p>\n<ul>\n<li>Prefer\u00eancias dos donos de animais de estima\u00e7\u00e3o e fatores que influenciam a compra<\/li>\n<li>Como as cl\u00ednicas est\u00e3o protegendo suas receitas e se adaptando \u00e0 concorr\u00eancia online.<\/li>\n<li>Onde as vendas de medicamentos com receita est\u00e3o sendo mantidas ou perdidas<\/li>\n<li>O impacto da telemedicina e a evolu\u00e7\u00e3o dos modelos de servi\u00e7o.<\/li>\n<li>Compara\u00e7\u00f5es de refer\u00eancia para acompanhar a evolu\u00e7\u00e3o do mercado<\/li>\n<\/ul>\n<p>O produto final \u00e9 um relat\u00f3rio abrangente em PowerPoint com mais de 100 p\u00e1ginas, contendo an\u00e1lises de especialistas e recomenda\u00e7\u00f5es pr\u00e1ticas para apoiar estrat\u00e9gias de marketing, desenvolvimento de produtos e crescimento.<\/p>\n<p>Com pre\u00e7o de $19.000, o estudo inclui uma consulta de uma hora com um consultor s\u00eanior da TRC. Pedidos feitos at\u00e9 15 de maio (com pagamento at\u00e9 15 de junho) recebem um desconto de $1.000, com um desconto adicional de $500 para compradores anteriores.<\/p>\n<p>Para obter mais informa\u00e7\u00f5es sobre o estudo de entrega domiciliar de medicamentos para animais de estima\u00e7\u00e3o, entre em contato com Doug Barton. <a href=\"mailto:dbarton@troneresearch.com\">dbarton@troneresearch.com<\/a>. Para encomendar,\u00a0<a href=\"https:\/\/brakkeconsulting.com\/wp-content\/uploads\/2026\/04\/Final-2026-Home-Delivery-Study-Order-Form.pdf\">Clique aqui.<\/a><\/p>\n<p>************************************<br \/>\n<strong>Comunicados de not\u00edcias da empresa<\/strong><\/p>\n<ul>\n<li><strong>Nutri\u00e7\u00e3o para animais de estima\u00e7\u00e3o da Hill&#039;s\u00a0<\/strong>lan\u00e7ou seu primeiro\u00a0<a href=\"https:\/\/www.hillsvet.com\/felinehealth\">Relat\u00f3rio do Mundo dos Gatinhos<\/a>, um guia baseado em evid\u00eancias para equipes veterin\u00e1rias e tutores de animais de estima\u00e7\u00e3o. (<a href=\"https:\/\/www.prnewswire.com\/news-releases\/blueprint-for-a-lifetime-hills-world-of-the-kitten-report-supports-veterinary-teams--pet-parents-in-navigating-the-critical-first-year-302761354.html\"><em>comunicado de imprensa da empresa<\/em><\/a>)<\/li>\n<li><strong>General Mills<\/strong>Anunciou a promo\u00e7\u00e3o de Dana McNabb ao cargo de Diretora de Opera\u00e7\u00f5es (COO). Ela assumir\u00e1 a responsabilidade por todos os segmentos operacionais, somando-se \u00e0s suas fun\u00e7\u00f5es atuais de lideran\u00e7a nas \u00e1reas de Varejo na Am\u00e9rica do Norte e Pet na Am\u00e9rica do Norte.<a href=\"https:\/\/investors.generalmills.com\/press-releases\/press-release-details\/2026\/General-Mills-Names-Dana-McNabb-Chief-Operating-Officer\/default.aspx\"><em>comunicado de imprensa da empresa<\/em><\/a>)<\/li>\n<li><strong>Fibro Sa\u00fade Animal<\/strong>lan\u00e7ou uma plataforma de solu\u00e7\u00f5es sustent\u00e1veis para toda a empresa, incluindo o lan\u00e7amento do Verratain Verified Sustainable Solutions, uma linha de produtos lan\u00e7ada por meio de uma parceria estrat\u00e9gica com\u00a0<strong>Tecnologias VAXA<\/strong>, um material de alimenta\u00e7\u00e3o para microalgas de baixo carbono e alto valor que possibilita a descarboniza\u00e7\u00e3o da cadeia de suprimentos. (<a href=\"https:\/\/investors.pahc.com\/press-releases\/press-release-details\/2026\/Phibro-Animal-Health-Corporation-Launches-Companywide-Sustainable-Solutions-Platform-Introduces-VERRATAIN-Verified-Sustainability-Solutions-Through-Strategic-VAXA-Technologies-Partnership\/default.aspx\"><em>comunicado de imprensa da empresa)<\/em><\/a><\/li>\n<li>A FDA anunciou a aprova\u00e7\u00e3o do Tessie (solu\u00e7\u00e3o oral de tasiprimidina) para o tratamento da avers\u00e3o a ru\u00eddos e ansiedade de separa\u00e7\u00e3o em c\u00e3es. O produto foi patrocinado por\u00a0<strong>Orion Corporation<\/strong>com sede na Finl\u00e2ndia.<a href=\"https:\/\/www.fda.gov\/animal-veterinary\/cvm-updates\/fda-approves-first-drug-treat-noise-aversion-and-separation-anxiety-dogs\"><em>gov<\/em><\/a>)<\/li>\n<li><strong>Galante\u00a0<\/strong>A empresa anunciou que obteve aprova\u00e7\u00e3o condicional ampliada da FDA-CVM para sua terapia com c\u00e9lulas-tronco para osteoartrite (OA) canina, com previs\u00e3o de aprova\u00e7\u00e3o condicional em 2028. Tamb\u00e9m anunciou resultados positivos de um estudo cl\u00ednico piloto com a terapia.<a href=\"https:\/\/www.gallant.com\/news\/gallant-advances-canine-osteoarthritis-iv-delivered-stem-cell-therapy-with-promising-pilot-data-and-expanded-fda-conditional-approval-pathway-eligibility\/\"><em>comunicado de imprensa da empresa<\/em><\/a>)<\/li>\n<li><strong>bimeda\u00a0<\/strong>Anunciou a disponibilidade nos EUA do Gastrobim (omeprazol) para o tratamento de \u00falcera g\u00e1strica em equinos.<strong>(<\/strong><a href=\"https:\/\/www.bimedaus.com\/news\/bimeda-announces-u-s-availability-of-gastrobimtm-omeprazole-the-first-and-only-fda-approved-bioequivalent-to-gastrogard-omeprazole-for-equine-gastric-ulcer-treatment\"><em>comunicado de imprensa da empresa<\/em><\/a><strong>)<\/strong><\/li>\n<li><strong>Sabores para animais de estima\u00e7\u00e3o\u00a0<\/strong>Anunciou a nomea\u00e7\u00e3o do Dr. Loic Le Hir de Fallois, PhD, como Diretor Executivo Interino.<a href=\"https:\/\/www.petfoodindustry.com\/news-newsletters\/pet-food-news\/news\/15824468\/pet-flavors-names-interim-ceo\"><em>com<\/em><\/a><em>)<\/em><\/li>\n<li><strong>Sa\u00fade Jaguar\u00a0<\/strong>Anunciou o lan\u00e7amento planejado do Neonorm Dog, um produto \u00e0 base de plantas, sem necessidade de receita m\u00e9dica, para auxiliar na forma\u00e7\u00e3o normal das fezes, hidrata\u00e7\u00e3o intestinal e sa\u00fade do intestino.<a href=\"https:\/\/jaguarhealth.gcs-web.com\/news-releases\/news-release-details\/jaguar-health-expands-neonorm-franchise-introduction-neonorm-dog\"><em>comunicado de imprensa da empresa<\/em><\/a>)<\/li>\n<li><strong>HomewardVet,\u00a0<\/strong>Uma franquia de servi\u00e7os veterin\u00e1rios m\u00f3veis encerrou suas atividades em 30 de abril.<a href=\"https:\/\/news.vin.com\/default.aspx?pid=210&amp;Id=13269551&amp;f5=1\"><em>vin.com<\/em><\/a>)<\/li>\n<li><strong>PetMade\u00a0<\/strong>Lan\u00e7ou uma linha de suplementos para suporte cardiovascular para c\u00e3es, aprovados por veterin\u00e1rios.<a href=\"https:\/\/www.morningstar.com\/news\/pr-newswire\/20260501ln48944\/petmade-formulates-veterinarian-approved-dog-supplements-for-heart-health-featuring-coq10-and-omega-3s\"><em>com<\/em><\/a>)<\/li>\n<li><strong>Crian\u00e7a de Ouro<\/strong>, um sistema de alimentos frescos, lan\u00e7ou suas f\u00f3rmulas de alimentos frescos desenvolvidas por uma nutricionista veterin\u00e1ria certificada e um chef.<a href=\"https:\/\/www.forbes.com\/sites\/forbes-personal-shopper\/2026\/05\/01\/dog-food-brand-golden-child-debuts-with-veterinary-nutritionist-designed-meals\/\"><em>com<\/em><\/a>)<\/li>\n<li><strong>Travv<\/strong>, uma plataforma de diagn\u00f3stico veterin\u00e1rio baseada em IA que integra sistemas de informa\u00e7\u00e3o radiol\u00f3gica, ferramentas de gest\u00e3o de imagem e laborat\u00f3rio, recebeu $1.6M em financiamento inicial de\u00a0<strong>Digitalis Ventures<\/strong>e\u00a0<strong>AniVC<\/strong>. (<a href=\"https:\/\/journalrecord.com\/2026\/05\/07\/travv-secures-seed-funding-ai-veterinary-diagnostics\/\"><em>com<\/em><\/a>)<\/li>\n<li>EMEA - Um servi\u00e7o de diagn\u00f3stico para produtores av\u00edcolas, o SciTell Microbiome Analytics, foi lan\u00e7ado pela empresa.\u00a0<strong>dsm-firmenich<\/strong>Nutri\u00e7\u00e3o e sa\u00fade animal para a Europa, Oriente M\u00e9dio e \u00c1sia.<a href=\"https:\/\/www.feedstuffs.com\/poultry\/dsm-firmenich-launches-poultry-gut-health-diagnostic-service\"><em>com<\/em><\/a>)<\/li>\n<li>Nova Zel\u00e2ndia<strong>terras agr\u00edcolas\u00a0<\/strong>firmou uma parceria estrat\u00e9gica exclusiva com<strong>Technion,\u00a0<\/strong>Uma desenvolvedora de plataforma de diagn\u00f3stico animal, que fornece aos seus clientes informa\u00e7\u00f5es independentes sobre doen\u00e7as e sa\u00fade animal.<a href=\"https:\/\/www.farmersweekly.co.nz\/markets\/farmlands-and-fecpak-in-animal-health-partnership\/#google_vignette\"><em>co.nz<\/em><\/a>)<\/li>\n<li>SP-\u00a0<strong>Rigi Capital<\/strong>e coinvestimento\u00a0<strong>Fundo de Busca Aurica<\/strong>\u00a0adquiriram\u00a0<strong>Diana da Super,<\/strong>\u00a0Desenvolve, fabrica e comercializa medicamentos e suplementos para animais de produ\u00e7\u00e3o em mais de 30 pa\u00edses.<a href=\"https:\/\/capital-riesgo.es\/en\/articles\/rigi-capital-together-with-a-group-of-investors-led-by-aurica-search-fund-acquires-super-s-diana\/\"><em>capital-riesgo.es<\/em><\/a>)<\/li>\n<\/ul>\n<p><strong>*********************************************<br \/>\n<\/strong><strong>Rastreador de Pre\u00e7os de A\u00e7\u00f5es de Sa\u00fade Animal<\/strong><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-36567 size-full\" src=\"https:\/\/brakkeconsulting.com\/wp-content\/uploads\/2026\/05\/5.8.26-Stock-Table.jpg\" alt=\"\" width=\"631\" height=\"651\" srcset=\"https:\/\/brakkeconsulting.com\/wp-content\/uploads\/2026\/05\/5.8.26-Stock-Table.jpg 631w, https:\/\/brakkeconsulting.com\/wp-content\/uploads\/2026\/05\/5.8.26-Stock-Table-480x495.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 631px, 100vw\" \/><\/p>\n<p><strong>*********************************************<\/strong><br \/>\n<strong>Brakke Consultoria<br \/>\n<\/strong><strong>Hist\u00f3rias de Talento: Li\u00e7\u00f5es de Branding para Vencer a Concorr\u00eancia na \u00c1rea de Recrutamento<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-35875\" src=\"https:\/\/brakkeconsulting.com\/wp-content\/uploads\/2025\/12\/Tails-of-Talent-Picture.jpg\" alt=\"\" width=\"267\" height=\"164\" srcset=\"https:\/\/brakkeconsulting.com\/wp-content\/uploads\/2025\/12\/Tails-of-Talent-Picture.jpg 267w, https:\/\/brakkeconsulting.com\/wp-content\/uploads\/2025\/12\/Tails-of-Talent-Picture-18x12.jpg 18w\" sizes=\"(max-width: 267px) 100vw, 267px\" \/><\/p>\n<p><strong>Datas e hor\u00e1rios dos webinars:<\/strong><br \/>\n<strong>2 de junho<\/strong>\u00a0| 11:00 - 12:00<br \/>\n<strong>4 de junho\u00a0<\/strong>| 14h00 \u2013 15h00<br \/>\n<strong>**Todas as datas est\u00e3o no fuso hor\u00e1rio EST**<\/strong><\/p>\n<p>No competitivo setor de sa\u00fade animal atual, atrair os melhores talentos vai al\u00e9m dos an\u00fancios de vagas \u2014 come\u00e7a com a forma como sua organiza\u00e7\u00e3o \u00e9 percebida.<\/p>\n<p>Na \u00e1rea da sa\u00fade animal, a guerra por talentos n\u00e3o se vence com an\u00fancios de vagas, mas sim com a percep\u00e7\u00e3o. Tudo come\u00e7a com a forma como o mercado enxerga a sua empresa. Junte-se a n\u00f3s em uma sess\u00e3o repleta de insights que mostrar\u00e1 por que empresas com marcas fortes e confi\u00e1veis atraem consistentemente os melhores candidatos, reduzem o tempo de contrata\u00e7\u00e3o e aumentam a reten\u00e7\u00e3o a longo prazo. Usando dados recentes e exemplos reais do setor, nossos especialistas experientes ir\u00e3o gui\u00e1-lo na avalia\u00e7\u00e3o da reputa\u00e7\u00e3o da marca da sua organiza\u00e7\u00e3o e elev\u00e1-la ao n\u00edvel desejado pelos melhores talentos. Em vez de correr atr\u00e1s de candidatos, aprenda a posicionar sua empresa como o lugar onde eles querem estar.<\/p>\n<p><strong>Apresentado por:\u00a0<\/strong><\/p>\n<ul>\n<li><strong>Jeff Santosuosso<\/strong> \u2013 Recrutador Executivo \u2013 Brakke Consulting<\/li>\n<li><strong>Jake Yarbrough<\/strong>\u00a0\u2013 Diretor de Grupo \u2013 Schaefer Advertising<\/li>\n<\/ul>\n<p>Esta sess\u00e3o \u00e9 uma oportunidade valiosa para repensar sua estrat\u00e9gia de recrutamento e posicionar sua empresa como um destino para os melhores talentos.<\/p>\n<p>Esperamos v\u00ea-lo(a) l\u00e1 e ajud\u00e1-lo(a) a vencer a competi\u00e7\u00e3o de talentos.<\/p>\n<p><a href=\"https:\/\/forms.gle\/8mQbfXbAJUuKdCfX9\">Clique aqui para se cadastrar<\/a>, Esta sess\u00e3o representa um investimento valioso para o futuro da sua estrat\u00e9gia de recrutamento.<\/p>\n<p>Por favor, envie um e-mail.\u00a0<a href=\"mailto:amcdavid@brakkeconsulting.com?subject=Tails%20of%20Talent%20-%20VMX%2FWVC%20Presentation\">Amanda McDavid<\/a> ou ligue para 336-396-3916 para obter ajuda com o cadastro.<\/p>\n<p>Estamos ansiosos para ajud\u00e1-lo(a) a vencer a competi\u00e7\u00e3o de talentos.<\/p>\n<p>***********************************<br \/>\n<strong>Not\u00edcias de Sa\u00fade Animal<\/strong><\/p>\n<ul>\n<li>EUA - SEMANA NACIONAL DOS ANIMAIS DE ESTIMA\u00c7\u00c3O - A Associa\u00e7\u00e3o Americana de Medicina Veterin\u00e1ria (AVMA) celebrou a Semana Nacional dos Animais de Estima\u00e7\u00e3o de 3 a 9 de maio de 2026, com o tema deste ano: &quot;Felicidade \u00e9 um animal de estima\u00e7\u00e3o saud\u00e1vel&quot;.<a href=\"https:\/\/www.dvm360.com\/view\/avma-marks-national-pet-week-as-us-pet-ownership-reaches-77-5-million-households\"><em>com<\/em><\/a>)<\/li>\n<li>EUA - CERTIFICADO DE SA\u00daDE CARD\u00cdACA - A Associa\u00e7\u00e3o de Medicina Veterin\u00e1ria Felina anunciou o lan\u00e7amento de seu Certificado de Sa\u00fade Card\u00edaca, um programa educacional para veterin\u00e1rios com o objetivo de aprimorar o atendimento card\u00edaco em gatos.<a href=\"https:\/\/catvets.com\/news\/heart-health-certificate\/\"><em>comunicado de imprensa da associa\u00e7\u00e3o<\/em><\/a>)<\/li>\n<li>TOMADA DE DECIS\u00d5ES VETERIN\u00c1RIAS NOS EUA - A\u00a0<a href=\"https:\/\/avmajournals.avma.org\/view\/journals\/javma\/aop\/javma.25.12.0845\/javma.25.12.0845.xml\">estudo de levantamento<\/a>Um artigo publicado no Journal of the American Veterinary Medical Association descreve os fatores, incluindo as restri\u00e7\u00f5es financeiras dos clientes, que influenciam as recomenda\u00e7\u00f5es de tratamento relacionadas \u00e0 dermatite at\u00f3pica canina.<a href=\"https:\/\/www.dvm360.com\/view\/canine-atopic-dermatitis-survey-reveals-how-financial-constraints-shape-veterinary-decision-making\"><em>com<\/em><\/a>)<\/li>\n<li>EUA - PSEUDORABIUS - O USDA confirmou a presen\u00e7a de pseudorrabia em uma pequena granja comercial de su\u00ednos em Iowa. O rastreamento indicou que a bact\u00e9ria veio de placas contaminadas de uma granja ao ar livre no Texas. Este \u00e9 o primeiro caso conhecido de pseudorrabia em su\u00ednos comerciais desde 2004.<a href=\"https:\/\/www.aphis.usda.gov\/news\/agency-announcements\/usda-confirms-pseudorabies-swine-herds-iowa-texas\"><em>comunicado de imprensa do governo<\/em><\/a>)<\/li>\n<li>CAMINHOS DE CARREIRA NA \u00c1REA DA SA\u00daDE NOS EUA - Um acordo de articula\u00e7\u00e3o de admiss\u00f5es entre a Midwestern University e a Bradley University garantir\u00e1 oportunidades de entrevistas de admiss\u00e3o para candidatos qualificados da Bradley nos programas de p\u00f3s-gradua\u00e7\u00e3o e profissionais da Midwestern University, incluindo medicina veterin\u00e1ria.<a href=\"https:\/\/www.midwestern.edu\/news-stories\/midwestern-university-and-bradley-university-establish-new-articulation-agreement\"><em>edu)<\/em><\/a><\/li>\n<li>EUA - RADIOLOGIA VETERIN\u00c1RIA DE IA - A\u00a0<a href=\"https:\/\/avmajournals.avma.org\/view\/journals\/javma\/aop\/javma.25.10.0691\/javma.25.10.0691.xml\">estudo piloto<\/a>Um estudo publicado no AVMA Journal of Veterinary Medicine, que revelou defici\u00eancias na interpreta\u00e7\u00e3o, gerou discuss\u00f5es entre pesquisadores e diversas plataformas.<a href=\"https:\/\/news.vin.com\/default.aspx?pid=210&amp;Id=13256349&amp;f5=1\"><em>vin.com<\/em><\/a>)<\/li>\n<li>GLOBAL - HANTAV\u00cdRUS - Um navio de cruzeiro que partiu da Argentina, fazendo diversas paradas em v\u00e1rios pa\u00edses, foi associado a v\u00e1rios casos de hantav\u00edrus. A Organiza\u00e7\u00e3o Mundial da Sa\u00fade est\u00e1 monitorando e avaliando o risco global.<a href=\"https:\/\/www.who.int\/emergencies\/disease-outbreak-news\/item\/2026-DON599\"><em>int<\/em><\/a>)<\/li>\n<li>Reino Unido - Doen\u00e7a Periodontal Canina - Um novo modelo de avalia\u00e7\u00e3o de risco que utiliza tecnologia preditiva para identificar c\u00e3es com alto risco de desenvolver doen\u00e7a periodontal foi recentemente desenvolvido.\u00a0<a href=\"https:\/\/www.frontiersin.org\/journals\/veterinary-science\/articles\/10.3389\/fvets.2026.1781228\/full\">Publicados<\/a>Dos cientistas do Waltham Petcare Science Institute. (<a href=\"https:\/\/www.prnewswire.com\/news-releases\/a-first-for-companion-animals-ai-supported-risk-assessment-will-provide-early-warning-of-periodontal-disease-in-dogs-302752041.html\"><em>Comunicado de imprensa<\/em><\/a>)<\/li>\n<\/ul>\n<p>************************************<br \/>\n<strong>Ponto de vista da Brakke Consulting<\/strong><\/p>\n<p><span data-contrast=\"auto\">Nas \u00faltimas d\u00e9cadas, o desempenho financeiro das principais empresas de sa\u00fade animal tem sido impulsionado pelo segmento de mercado de animais de companhia. Ser\u00e1 que vamos nos juntar a Marty McFly e ir em frente?\u00a0<\/span><a href=\"https:\/\/en.wikipedia.org\/wiki\/Back_to_the_Future\"><i><span data-contrast=\"none\">De Volta para o Futuro<\/span><\/i><\/a><span data-contrast=\"auto\">\u00a0Onde o segmento de pecu\u00e1ria impulsiona o desempenho? Parece que esse \u00e9 o caso do primeiro trimestre de 2026, j\u00e1 que Merck, Elanco e Zoetis registraram fortes taxas de crescimento no setor pecu\u00e1rio.\u00a0<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:160,&quot;335559739&quot;:160,&quot;335559740&quot;:278}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Em 2025, pela primeira vez em muitos anos, o segmento de pecu\u00e1ria cresceu mais r\u00e1pido do que o segmento de animais de companhia nas maiores empresas de sa\u00fade animal. A Merck e a Elanco relataram que, no primeiro trimestre de 2026, seus segmentos de pecu\u00e1ria cresceram +81 trilh\u00f5es de d\u00f3lares e +131 trilh\u00f5es de d\u00f3lares, respectivamente (ajustados pela varia\u00e7\u00e3o cambial), o dobro das taxas de crescimento de seus neg\u00f3cios com animais de companhia. A Zoetis tamb\u00e9m acaba de divulgar seus resultados do primeiro trimestre de 2026, com o segmento de pecu\u00e1ria apresentando um crescimento de +121 trilh\u00f5es de d\u00f3lares (ajustado pela varia\u00e7\u00e3o cambial e desinvestimentos), enquanto o segmento de animais de companhia apresentou queda. Isso ocorreu mesmo com o rebanho bovino dos EUA atingindo, em janeiro de 2026, o menor n\u00edvel em 75 anos, com 86 milh\u00f5es de cabe\u00e7as. Um relat\u00f3rio da Piper Sandler mencionou que, em 2025, o n\u00famero de vacas de corte caiu para os n\u00edveis mais baixos desde 1961. O n\u00famero de bezerros em 2025 diminuiu 21% e o de bovinos em confinamento caiu 31%, indicando que uma expans\u00e3o do rebanho bovino n\u00e3o \u00e9 prov\u00e1vel antes de 2028, se \u00e9 que ocorrer\u00e1. De onde vir\u00e1 o crescimento com esses n\u00fameros em decl\u00ednio?\u00a0<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:160,&quot;335559739&quot;:160,&quot;335559740&quot;:278}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Bem, isso deve vir dos produtores que est\u00e3o percebendo o valor de utilizar tratamentos preventivos, como vacinas, aditivos medicinais para ra\u00e7\u00e3o e produtos nutricionais especiais de alta qualidade para proteger a sa\u00fade de seus valiosos investimentos. Al\u00e9m disso, os mercados internacionais est\u00e3o fortes e em crescimento, especialmente na Am\u00e9rica Latina e na \u00c1sia. Al\u00e9m dos tratamentos preventivos, o investimento e o uso de solu\u00e7\u00f5es tecnol\u00f3gicas para o manejo da sa\u00fade do rebanho est\u00e3o se consolidando. As empresas com linhas de produtos pecu\u00e1rios globais fortes devem apresentar bom desempenho ao longo do ano. Vamos ver se o DeLorean do Dr. Brown, com seu capacitor de fluxo, continuar\u00e1 viajando pelo resto de 2026. Se o primeiro trimestre de 2026 serve de indica\u00e7\u00e3o, parece que sim.\u00a0<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:160,&quot;335559739&quot;:160,&quot;335559740&quot;:278}\">\u00a0<\/span><\/p>\n<p><i><span data-contrast=\"auto\">Randy Freides<\/span><\/i><span data-ccp-props=\"{&quot;335559738&quot;:160}\"><br \/>\n<\/span>************************************<br \/>\n<b>Sua vis\u00e3o<\/p>\n<p><\/b><span data-contrast=\"auto\">Na semana passada, perguntamos como voc\u00ea participou pessoalmente do investimento em inova\u00e7\u00e3o em sa\u00fade animal: como investidor anjo, investindo em empresas individuais de sa\u00fade animal, em grandes corpora\u00e7\u00f5es com divis\u00f5es de sa\u00fade animal ou no ETF de Cuidados com Animais de Estima\u00e7\u00e3o. 161 mil dos respondentes n\u00e3o gerenciaram seus investimentos pessoalmente; os demais investiram de diferentes maneiras. 35 mil investiram de uma \u00fanica forma, sendo 55 mil como investidores anjo. 26 mil investiram de duas maneiras, com 73 mil investindo tanto em empresas individuais quanto em grandes corpora\u00e7\u00f5es. Por fim, 23 mil investiram fortemente de tr\u00eas maneiras, sendo 83 mil como investidores anjo, al\u00e9m de empresas individuais e grandes corpora\u00e7\u00f5es.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Esta semana, complementando a perspectiva de Randy Freides, vamos tentar prever o futuro do setor de sa\u00fade animal. No passado, os segmentos de animais de companhia e de animais de produ\u00e7\u00e3o\/aves pareciam divergir \u2014 um deles capturando uma parcela crescente dos investimentos em pesquisa e desenvolvimento e crescendo mais rapidamente. Agora, os animais de produ\u00e7\u00e3o est\u00e3o superando os animais de companhia e compensando os resultados mais lentos dos animais de companhia. O que isso significa a longo prazo? Ser\u00e1 que uma divis\u00e3o est\u00e1 por vir? <a href=\"https:\/\/www.surveymonkey.com\/r\/5K89LLK\">Nossa pergunta desta semana: daqui a cinco anos, as grandes empresas de sa\u00fade animal com ambos os segmentos ir\u00e3o se desfazer de um deles? O neg\u00f3cio ser\u00e1 dividido?<\/a><\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:160,&quot;335559739&quot;:160,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>*********************************** Not\u00edcias e Notas sobre Sa\u00fade Animal da Brakke Consulting - 8 de maio de 2026 Copyright \u00a9 Brakke Consulting Editora: Christine Merle DVM, MBA, CVPM ************************************ NAS NOT\u00cdCIAS: Estudo da Brakke Consulting sobre Entrega Domiciliar de Medicamentos para Animais de Estima\u00e7\u00e3o em 2026 Hist\u00f3rias de Talentos: Li\u00e7\u00f5es de Branding para Vencer a Conquista de Talentos Not\u00edcias sobre Resultados Cencora (MWI Animal Health) Central Garden and Pet Colgate-Palmolive (Hill&#039;s Pet Nutrition) Elanco Freshpet IDEXX Laboratories Phibro Zoetis Zomedica Not\u00edcias das Empresas AniVC Aurica Search Fund (SP) Bimeda dsm-firmenich (EMEA) Digitalis Ventures Farmland (NZ) Gallant General Mills Golden Child Hill&#039;s Pet Nutrition HomewardVet Jaguar Health Orion Corporation Pet Flavors PetMade Phibro Rigi Capital (SP) Super&#039;s Diana (SP) Techion (NZ) Travv VAXA Technologies Not\u00edcias sobre Sa\u00fade Animal Global Reino Unido Estados Unidos Divulga\u00e7\u00e3o de Resultados das Empresas: A Cencora reportou receita de US$ 78,4 bilh\u00f5es no segundo trimestre do ano fiscal de 2026, um aumento de US$ 3,81 trilh\u00f5es em rela\u00e7\u00e3o ao mesmo per\u00edodo do ano anterior. A MWI Animal Health, que faz parte do segmento &quot;Outros&quot; e agora \u00e9 contabilizada como &quot;mantida para venda&quot;, contribuiu para um aumento de US$ 11 trilh\u00f5es nesse segmento. (comunicado de imprensa da empresa) A Central Garden and Pet registrou vendas l\u00edquidas superiores a US$ 1,5 bilh\u00e3o no segundo trimestre do ano fiscal de 2026 nos primeiros seis meses. Ao final do trimestre, a Central iniciou um novo neg\u00f3cio de distribui\u00e7\u00e3o de produtos para animais de estima\u00e7\u00e3o com a Phillips Pet Food &amp; Supplies. (comunicado de imprensa da empresa) A Colgate Palmolive divulgou seus resultados do primeiro trimestre de 2026, refletindo um aumento de US$ 8,41 trilh\u00f5es nas vendas l\u00edquidas em compara\u00e7\u00e3o com o mesmo per\u00edodo do ano anterior. Seu neg\u00f3cio Hill&#039;s Pet Nutrition contribuiu com US$ 280 milh\u00f5es em lucro operacional, um aumento de US$ 81 trilh\u00f5es em rela\u00e7\u00e3o ao mesmo per\u00edodo do ano anterior. (Comunicado de imprensa da empresa) A Elanco divulgou seus resultados do primeiro trimestre de 2026, com receita de 1.371 milh\u00f5es de d\u00f3lares, refletindo um<\/p>\n<div class=\"view-full-post\"><a href=\"https:\/\/brakkeconsulting.com\/pt\/this-week-in-animal-health-earnings-reports-dominate-the-news\/\" class=\"view-full-post-btn\">Ver postagem completa<\/a><\/div>\n<p>;<\/p>","protected":false},"author":19,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"class_list":["post-36565","post","type-post","status-publish","format-standard","hentry","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>News from Brakke Consulting<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/brakkeconsulting.com\/pt\/this-week-in-animal-health-earnings-reports-dominate-the-news\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"News from Brakke Consulting\" \/>\n<meta property=\"og:description\" content=\"*********************************** Brakke Consulting&#8217;s\u00a0 Animal Health News &amp; Notes for\u00a0May 8, 2026 Copyright \u00a9 Brakke Consulting Editor: Christine Merle DVM, MBA, CVPM\u202f ************************************ IN THE NEWS: Brakke Consulting 2026 Pet Medications Home Delivery Study Tails of Talent: Branding Lessons to Win the Talent Game Earning News Cencora\u00a0(MWI\u00a0Animal Health) Central Garden and Pet Colgate-Palmolive (Hill\u2019s Pet Nutrition) Elanco Freshpet IDEXX Laboratories Phibro Zoetis Zomedica Company News AniVC Aurica Search Fund (SP) Bimeda dsm-firmenich\u00a0(EMEA) Digitalis Ventures Farmland (NZ) Gallant General Mills Golden Child Hill\u2019s Pet Nutrition HomewardVet Jaguar Health Orion Corporation Pet Flavors PetMade Phibro Rigi Capital (SP) Super\u2019s Diana (SP) Techion\u00a0(NZ) Travv VAXA Technologies Animal Health\u00a0News Global United Kingdom United States ************************************ Company Earnings Releases Cencorareported\u00a0the\u00a0second quarter of fiscal 2026\u00a0revenue of $78.4B, a 3.8% increase over\u00a0prior\u00a0year\u00a0period.\u00a0\u00a0MWI Animal\u00a0Health\u00a0which is part of the other segment and is now accounted for as \u201cheld for sale\u201d\u00a0but contributed towards at1% increase in that segment. (company press release) Central Garden and Petrecorded its second quarter of fiscal 2026\u00a0with Net sales\u00a0greater than\u00a0$1.5B for the first 6 months.\u00a0At the close of the quarter, Central entered\u00a0a new pet distribution business with\u00a0Phillips Pet Food &amp; Supplies. (company press release) Colgate Palmolive\u00a0releasedits\u00a0first\u00a0quarter of\u00a02026 results reflecting\u00a0Net Sales\u00a0increase of 8.4% versus prior year\u00a0period.\u00a0It\u2019s Hill\u2019s\u00a0Pet Nutrition business\u00a0contributed\u00a0$280M in operating\u00a0profit\u00a0an 8% increase versus prior year\u00a0period. (company press release) Elancoshared its first quarter of 2026 results\u00a0with\u00a0revenue\u00a0of $1,371M\u00a0reflecting aView Full Post;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/brakkeconsulting.com\/pt\/this-week-in-animal-health-earnings-reports-dominate-the-news\/\" \/>\n<meta property=\"og:site_name\" content=\"Brakke Consulting Website\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-08T16:43:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/brakkeconsulting.com\/wp-content\/uploads\/2026\/05\/PMHD-Study-300x200.png\" \/>\n<meta name=\"author\" content=\"Amanda McDavid\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Amanda McDavid\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/zh\\\/this-week-in-animal-health-earnings-reports-dominate-the-news\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/zh\\\/this-week-in-animal-health-earnings-reports-dominate-the-news\\\/\"},\"author\":{\"name\":\"Amanda McDavid\",\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/#\\\/schema\\\/person\\\/cbd3330707aa1f20925a2f9d78722615\"},\"headline\":\"This Week in Animal Health: Earnings Reports Dominate the News\",\"datePublished\":\"2026-05-08T16:43:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/zh\\\/this-week-in-animal-health-earnings-reports-dominate-the-news\\\/\"},\"wordCount\":2197,\"image\":{\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/zh\\\/this-week-in-animal-health-earnings-reports-dominate-the-news\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/brakkeconsulting.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/PMHD-Study-300x200.png\",\"articleSection\":[\"Newsletter\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/zh\\\/this-week-in-animal-health-earnings-reports-dominate-the-news\\\/\",\"url\":\"https:\\\/\\\/brakkeconsulting.com\\\/zh\\\/this-week-in-animal-health-earnings-reports-dominate-the-news\\\/\",\"name\":\"News from Brakke Consulting\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/zh\\\/this-week-in-animal-health-earnings-reports-dominate-the-news\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/zh\\\/this-week-in-animal-health-earnings-reports-dominate-the-news\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/brakkeconsulting.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/PMHD-Study-300x200.png\",\"datePublished\":\"2026-05-08T16:43:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/#\\\/schema\\\/person\\\/cbd3330707aa1f20925a2f9d78722615\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/zh\\\/this-week-in-animal-health-earnings-reports-dominate-the-news\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/brakkeconsulting.com\\\/zh\\\/this-week-in-animal-health-earnings-reports-dominate-the-news\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/zh\\\/this-week-in-animal-health-earnings-reports-dominate-the-news\\\/#primaryimage\",\"url\":\"http:\\\/\\\/brakkeconsulting.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/PMHD-Study-300x200.png\",\"contentUrl\":\"http:\\\/\\\/brakkeconsulting.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/PMHD-Study-300x200.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/zh\\\/this-week-in-animal-health-earnings-reports-dominate-the-news\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/brakkeconsulting.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"This Week in Animal Health: Earnings Reports Dominate the News\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/#website\",\"url\":\"https:\\\/\\\/brakkeconsulting.com\\\/\",\"name\":\"Brakke Consulting Website\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/brakkeconsulting.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/#\\\/schema\\\/person\\\/cbd3330707aa1f20925a2f9d78722615\",\"name\":\"Amanda McDavid\",\"url\":\"https:\\\/\\\/brakkeconsulting.com\\\/pt\\\/author\\\/amanda\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Not\u00edcias da Brakke Consulting","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/brakkeconsulting.com\/pt\/this-week-in-animal-health-earnings-reports-dominate-the-news\/","og_locale":"pt_PT","og_type":"article","og_title":"News from Brakke Consulting","og_description":"*********************************** Brakke Consulting&#8217;s\u00a0 Animal Health News &amp; Notes for\u00a0May 8, 2026 Copyright \u00a9 Brakke Consulting Editor: Christine Merle DVM, MBA, CVPM\u202f ************************************ IN THE NEWS: Brakke Consulting 2026 Pet Medications Home Delivery Study Tails of Talent: Branding Lessons to Win the Talent Game Earning News Cencora\u00a0(MWI\u00a0Animal Health) Central Garden and Pet Colgate-Palmolive (Hill\u2019s Pet Nutrition) Elanco Freshpet IDEXX Laboratories Phibro Zoetis Zomedica Company News AniVC Aurica Search Fund (SP) Bimeda dsm-firmenich\u00a0(EMEA) Digitalis Ventures Farmland (NZ) Gallant General Mills Golden Child Hill\u2019s Pet Nutrition HomewardVet Jaguar Health Orion Corporation Pet Flavors PetMade Phibro Rigi Capital (SP) Super\u2019s Diana (SP) Techion\u00a0(NZ) Travv VAXA Technologies Animal Health\u00a0News Global United Kingdom United States ************************************ Company Earnings Releases Cencorareported\u00a0the\u00a0second quarter of fiscal 2026\u00a0revenue of $78.4B, a 3.8% increase over\u00a0prior\u00a0year\u00a0period.\u00a0\u00a0MWI Animal\u00a0Health\u00a0which is part of the other segment and is now accounted for as \u201cheld for sale\u201d\u00a0but contributed towards at1% increase in that segment. (company press release) Central Garden and Petrecorded its second quarter of fiscal 2026\u00a0with Net sales\u00a0greater than\u00a0$1.5B for the first 6 months.\u00a0At the close of the quarter, Central entered\u00a0a new pet distribution business with\u00a0Phillips Pet Food &amp; Supplies. (company press release) Colgate Palmolive\u00a0releasedits\u00a0first\u00a0quarter of\u00a02026 results reflecting\u00a0Net Sales\u00a0increase of 8.4% versus prior year\u00a0period.\u00a0It\u2019s Hill\u2019s\u00a0Pet Nutrition business\u00a0contributed\u00a0$280M in operating\u00a0profit\u00a0an 8% increase versus prior year\u00a0period. (company press release) Elancoshared its first quarter of 2026 results\u00a0with\u00a0revenue\u00a0of $1,371M\u00a0reflecting aView Full Post;","og_url":"https:\/\/brakkeconsulting.com\/pt\/this-week-in-animal-health-earnings-reports-dominate-the-news\/","og_site_name":"Brakke Consulting Website","article_published_time":"2026-05-08T16:43:55+00:00","og_image":[{"url":"https:\/\/brakkeconsulting.com\/wp-content\/uploads\/2026\/05\/PMHD-Study-300x200.png","type":"","width":"","height":""}],"author":"Amanda McDavid","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Amanda McDavid","Tempo estimado de leitura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/brakkeconsulting.com\/zh\/this-week-in-animal-health-earnings-reports-dominate-the-news\/#article","isPartOf":{"@id":"https:\/\/brakkeconsulting.com\/zh\/this-week-in-animal-health-earnings-reports-dominate-the-news\/"},"author":{"name":"Amanda McDavid","@id":"https:\/\/brakkeconsulting.com\/#\/schema\/person\/cbd3330707aa1f20925a2f9d78722615"},"headline":"This Week in Animal Health: Earnings Reports Dominate the News","datePublished":"2026-05-08T16:43:55+00:00","mainEntityOfPage":{"@id":"https:\/\/brakkeconsulting.com\/zh\/this-week-in-animal-health-earnings-reports-dominate-the-news\/"},"wordCount":2197,"image":{"@id":"https:\/\/brakkeconsulting.com\/zh\/this-week-in-animal-health-earnings-reports-dominate-the-news\/#primaryimage"},"thumbnailUrl":"https:\/\/brakkeconsulting.com\/wp-content\/uploads\/2026\/05\/PMHD-Study-300x200.png","articleSection":["Newsletter"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/brakkeconsulting.com\/zh\/this-week-in-animal-health-earnings-reports-dominate-the-news\/","url":"https:\/\/brakkeconsulting.com\/zh\/this-week-in-animal-health-earnings-reports-dominate-the-news\/","name":"Not\u00edcias da Brakke Consulting","isPartOf":{"@id":"https:\/\/brakkeconsulting.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/brakkeconsulting.com\/zh\/this-week-in-animal-health-earnings-reports-dominate-the-news\/#primaryimage"},"image":{"@id":"https:\/\/brakkeconsulting.com\/zh\/this-week-in-animal-health-earnings-reports-dominate-the-news\/#primaryimage"},"thumbnailUrl":"https:\/\/brakkeconsulting.com\/wp-content\/uploads\/2026\/05\/PMHD-Study-300x200.png","datePublished":"2026-05-08T16:43:55+00:00","author":{"@id":"https:\/\/brakkeconsulting.com\/#\/schema\/person\/cbd3330707aa1f20925a2f9d78722615"},"breadcrumb":{"@id":"https:\/\/brakkeconsulting.com\/zh\/this-week-in-animal-health-earnings-reports-dominate-the-news\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/brakkeconsulting.com\/zh\/this-week-in-animal-health-earnings-reports-dominate-the-news\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/brakkeconsulting.com\/zh\/this-week-in-animal-health-earnings-reports-dominate-the-news\/#primaryimage","url":"https:\/\/brakkeconsulting.com\/wp-content\/uploads\/2026\/05\/PMHD-Study-300x200.png","contentUrl":"https:\/\/brakkeconsulting.com\/wp-content\/uploads\/2026\/05\/PMHD-Study-300x200.png"},{"@type":"BreadcrumbList","@id":"https:\/\/brakkeconsulting.com\/zh\/this-week-in-animal-health-earnings-reports-dominate-the-news\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/brakkeconsulting.com\/"},{"@type":"ListItem","position":2,"name":"This Week in Animal Health: Earnings Reports Dominate the News"}]},{"@type":"WebSite","@id":"https:\/\/brakkeconsulting.com\/#website","url":"https:\/\/brakkeconsulting.com\/","name":"Site da Brakke Consulting","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/brakkeconsulting.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/brakkeconsulting.com\/#\/schema\/person\/cbd3330707aa1f20925a2f9d78722615","name":"Amanda McDavid","url":"https:\/\/brakkeconsulting.com\/pt\/author\/amanda\/"}]}},"_links":{"self":[{"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/posts\/36565","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/comments?post=36565"}],"version-history":[{"count":1,"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/posts\/36565\/revisions"}],"predecessor-version":[{"id":36568,"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/posts\/36565\/revisions\/36568"}],"wp:attachment":[{"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/media?parent=36565"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/categories?post=36565"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/tags?post=36565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}