{"id":29300,"date":"2021-05-13T16:03:59","date_gmt":"2021-05-13T22:03:59","guid":{"rendered":"https:\/\/brakkeconsulting.com\/?p=29300"},"modified":"2021-05-13T16:03:59","modified_gmt":"2021-05-13T22:03:59","slug":"animal-health-news-notes-for-may-14-2021","status":"publish","type":"post","link":"https:\/\/brakkeconsulting.com\/pt\/animal-health-news-notes-for-may-14-2021\/","title":{"rendered":"Not\u00edcias e notas de sa\u00fade animal para 14 de maio de 2021"},"content":{"rendered":"<p>***********************************<br \/>\n<strong>Brakke Consulting&#039;s <\/strong><br \/>\n<strong>Not\u00edcias e notas de sa\u00fade animal de 14 de maio de<\/strong><strong> 2021<\/strong><br \/>\n<em>Copyright \u00a9 Brakke Consulting<br \/>\n<\/em><em>Editor: Lynn Fondon DVM MBA<br \/>\n<\/em>************************************<\/p>\n<p>NAS NOTICIAS:<\/p>\n<p><u>Not\u00edcias de Ganhos<br \/>\n<\/u>Empresa Melhor Escolha<br \/>\nCryoport<br \/>\nDS Pharma Sa\u00fade Animal<br \/>\nElanco<br \/>\nBioci\u00eancias afins<br \/>\nOuro Fino<br \/>\nPropriedades de marcas de espectro<br \/>\nZomedica<\/p>\n<p><u>Outras not\u00edcias<br \/>\n<\/u>Diagn\u00f3stico Animal Avan\u00e7ado<br \/>\nAlltech<br \/>\nBio-Cide Internacional<br \/>\nBoehringer Ingelheim<br \/>\nCannaHorse<br \/>\nElanco<br \/>\nInd\u00fastrias Kemin<br \/>\nPet Releaf<br \/>\nParceiros veterin\u00e1rios de ra\u00e7as raras<br \/>\nTrouw Nutrition<br \/>\nZenex Sa\u00fade Animal \u00cdndia<br \/>\nSa\u00fade Animal Zydus<\/p>\n<p><strong>************************************<br \/>\nRELEASES DE RESULTADOS DA EMPRESA<\/strong><\/p>\n<ul>\n<li><strong>Elanco Sa\u00fade Animal<\/strong> reportou fortes resultados financeiros para o primeiro trimestre de 2021. A receita no primeiro trimestre foi de $1.242 milh\u00f5es, composta por $683 milh\u00f5es do portf\u00f3lio herdado da Elanco e $559 milh\u00f5es do portf\u00f3lio legado da Bayer Animal Health. A receita aumentou 89% impulsionada pela inclus\u00e3o do neg\u00f3cio Bayer Animal Health; A receita herdada da Elanco no primeiro trimestre foi de $683 milh\u00f5es, um aumento de 4% ano a ano. O preju\u00edzo l\u00edquido do trimestre foi de $(61) milh\u00f5es, em compara\u00e7\u00e3o com um preju\u00edzo l\u00edquido de $(49) milh\u00f5es no per\u00edodo do ano anterior. <em>(comunicado de imprensa da empresa)<\/em><\/li>\n<li><strong>Ouro Fino Sa\u00fade Animal<\/strong> resultados relatados para o primeiro trimestre de 2021. As receitas foram de R$168,8 milh\u00f5es ($32,3 milh\u00f5es), um aumento de 51% em rela\u00e7\u00e3o ao trimestre do ano anterior.<em> (IHS Markit Connect)<\/em><\/li>\n<li><strong>DS Pharma Sa\u00fade Animal<\/strong> reportou resultados para o ano fiscal encerrado em 31 de mar\u00e7o de 2021. As vendas foram de 12.860 milh\u00f5es de ienes ($118 milh\u00f5es), uma queda de 11% em rela\u00e7\u00e3o ao ano fiscal anterior. A empresa foi impactada pela descontinua\u00e7\u00e3o de seus neg\u00f3cios de alimentos para animais de estima\u00e7\u00e3o, incluindo a cessa\u00e7\u00e3o de um pacto para distribuir as dietas da Hill&#039;s Pet Nutrition no Jap\u00e3o, que terminou em dezembro de 2020. As vendas de produtos de sa\u00fade animal da empresa, excluindo o segmento de alimentos para animais de estima\u00e7\u00e3o, aumentaram 13% em 2020.<em> (IHS Markit Connect)<\/em><\/li>\n<li><strong>Bioci\u00eancias afins<\/strong>, Inc. anunciou os resultados financeiros para o primeiro trimestre de 2021. As receitas foram de $2,4 milh\u00f5es em compara\u00e7\u00e3o com as receitas de $603.000 no trimestre do ano anterior. Desse total, $227.000 foram receitas l\u00edquidas de produtos da Zimeta; $326.000 foram receitas de royalties para a Mirataz; e $1,8 milh\u00f5es foram receitas de fabrica\u00e7\u00e3o contratada. O preju\u00edzo l\u00edquido foi de $(9,7) milh\u00f5es em compara\u00e7\u00e3o com um preju\u00edzo de $(22,8) milh\u00f5es no per\u00edodo do ano anterior.<em> (site da companhia)<\/em><\/li>\n<li><strong>Zomedica<\/strong> os resultados financeiros consolidados relatados para o primeiro trimestre de Receita foram $14.124 e resultaram da venda de produtos Truforma e garantias associadas. A empresa iniciou a comercializa\u00e7\u00e3o do Truforma em 15 de mar\u00e7o de 2021. O preju\u00edzo l\u00edquido foi de aproximadamente $(4,0) milh\u00f5es, em compara\u00e7\u00e3o com um preju\u00edzo de aproximadamente $(2,5) milh\u00f5es nos tr\u00eas meses encerrados em 31 de mar\u00e7o de 2020. A Zomedica tinha caixa e equivalentes de caixa de aproximadamente $276,6 milh\u00f5es em 31 de mar\u00e7o de 2021, em compara\u00e7\u00e3o com aproximadamente $1,5 milh\u00e3o em 31 de mar\u00e7o de 2020. <em>(comunicado de imprensa da empresa)<\/em><\/li>\n<li><strong>Propriedades de marcas de espectro<\/strong> reportou resultados para seu segundo trimestre fiscal encerrado em 31 de mar\u00e7o de 2021. As vendas l\u00edquidas globais de Pet Care foram de $294 milh\u00f5es, um aumento de 24% ano a ano. <em>(site da companhia)<\/em><\/li>\n<li><strong>Empresa Melhor Escolha<\/strong> informou seus resultados financeiros para o primeiro trimestre encerrado em 31 de mar\u00e7o de 2021. As vendas l\u00edquidas foram de $10,8 milh\u00f5es, uma queda de 11% em compara\u00e7\u00e3o com o trimestre do ano anterior. O preju\u00edzo l\u00edquido foi de $(12,85) milh\u00f5es em compara\u00e7\u00e3o com um preju\u00edzo de $(9,45) milh\u00f5es no ano anterior. <em>(Globenewswire)<\/em><\/li>\n<li><strong>Cryoport <\/strong>reportou resultados financeiros para o primeiro trimestre de 2021. O volume de neg\u00f3cios de sa\u00fade animal melhorou para $9 milh\u00f5es de $0,2m no trimestre comparativo do ano passado, impulsionado principalmente pela aquisi\u00e7\u00e3o da MVE Biological Solutions.<em> (IHS Markit Connect)<\/em><\/li>\n<\/ul>\n<p><strong>************************************<br \/>\n<\/strong><strong>COMUNICADOS DE NOT\u00cdCIAS DA EMPRESA<\/strong><\/p>\n<ul>\n<li><strong>Elanco Sa\u00fade Animal<\/strong> anunciou o lan\u00e7amento do ZoaShield (zoaleno) para oferecer aos produtores de aves uma solu\u00e7\u00e3o comprovada e flex\u00edvel que mant\u00e9m a coccidiose sob controle de maneira f\u00e1cil e gerenci\u00e1vel.<em> (comunicado de imprensa da empresa)<\/em><\/li>\n<li>A FDA anunciou que, em resposta \u00e0 escassez de Vetmedin (pimobendan), a ag\u00eancia n\u00e3o pretende se opor \u00e0 importa\u00e7\u00e3o tempor\u00e1ria de c\u00e1psulas Vetmedin e mastig\u00e1veis Vetmedin por <strong>Boehringer Ingelheim Sa\u00fade Animal EUA<\/strong>, Inc., do Canad\u00e1, Reino Unido e Irlanda para aumentar imediatamente a disponibilidade do Vetmedin nos EUA. N\u00e3o h\u00e1 alternativa aprovada pela FDA ao Vetmedin. Embora os produtos Vetmedin importados n\u00e3o tenham sido avaliados ou aprovados pela FDA, eles s\u00e3o aprovados em seus pa\u00edses de origem e est\u00e3o sujeitos aos padr\u00f5es regulat\u00f3rios desses pa\u00edses, incluindo a ades\u00e3o \u00e0s boas pr\u00e1ticas de fabrica\u00e7\u00e3o. (FDA)<\/li>\n<li><strong>Ind\u00fastrias Kemin<\/strong> anunciou que adquiriu <strong>Bio-Cide Internacional,<\/strong>, uma fonte multiespecializada l\u00edder de tecnologia antimicrobiana baseada em di\u00f3xido de cloro. Os termos financeiros n\u00e3o foram divulgados. <em>(joplinglobe.com)<\/em><\/li>\n<li><strong>Alltech <\/strong>anunciou o lan\u00e7amento da marca Lifeforce de suplementos para equinos. A nova linha inclui suplementos para: sa\u00fade e manuten\u00e7\u00e3o das articula\u00e7\u00f5es; digest\u00e3o; sa\u00fade dos cascos; e manuten\u00e7\u00e3o do peso. A linha tamb\u00e9m inclui um suplemento de desempenho de elite para manter a cartilagem saud\u00e1vel e o l\u00edquido sinovial nas articula\u00e7\u00f5es, apoiando a resist\u00eancia muscular e otimizando a digest\u00e3o. <em>(IHS Markit Connect)<\/em><\/li>\n<li><strong>Trouw Nutrition <\/strong>anunciou uma expans\u00e3o de instala\u00e7\u00f5es de $12,1 milh\u00f5es, aumentando a Planta Piloto existente de 8.100 p\u00e9s quadrados para uma nova instala\u00e7\u00e3o moderna de 32.052 p\u00e9s quadrados. A nova instala\u00e7\u00e3o reflete o investimento cont\u00ednuo da Trouw em sua Divis\u00e3o de Animais de Companhia nos Estados Unidos e na ind\u00fastria mais ampla de alimentos para animais de estima\u00e7\u00e3o.<em> (GobalPets)<\/em><\/li>\n<li><strong>Diagn\u00f3stico Animal Avan\u00e7ado<\/strong> anunciou que obteve $7 milh\u00f5es em fundos de investimento para ajud\u00e1-la a expandir sua plataforma de ponto de atendimento (POC) nos setores de sa\u00fade animal e farmac\u00eautica humana. Na \u00e1rea pecu\u00e1ria, a AAD utilizar\u00e1 o investimento para a expans\u00e3o comercial de seus testes. A Mountain Group Partners (MGP) liderou a rodada de financiamento.<em> (IHS Markit Connect)<\/em><\/li>\n<li><strong>Pet Releaf<\/strong> anunciou o lan\u00e7amento de Sentesa, uma linha veterin\u00e1ria de suplementos \u00e0 base de c\u00e2nhamo formulados para controlar a resposta inflamat\u00f3ria, desconforto, calma, flexibilidade articular e mobilidade de um c\u00e3o. As c\u00e1psulas de Sentesa cont\u00eam canabidiol (CBD), beta-cariofileno e \u00e1cido capr\u00edlico, um triglicer\u00eddeo. <em>(Neg\u00f3cio Veterin\u00e1rio de Hoje)<\/em><\/li>\n<li><strong>CannaHorse<\/strong> anunciou que lan\u00e7ou comercialmente o Equilibrium Oral, seu primeiro canabin\u00f3ide equino terap\u00eautico nos EUA. Equilibrium Oral \u00e9 projetado para reduzir a ansiedade em cavalos e est\u00e1 dispon\u00edvel como uma formula\u00e7\u00e3o de gel para administra\u00e7\u00e3o via seringa ou na ra\u00e7\u00e3o. <em>(IHS Markit Connect)<\/em><\/li>\n<li><strong>Parceiros veterin\u00e1rios de ra\u00e7as raras <\/strong>anunciou que fechou uma nova rodada de financiamento, liderada pelos investidores existentes Halle Capital Management e Trilantic North America. O investimento ser\u00e1 usado para apoiar o crescimento cont\u00ednuo da Rarebreed por meio da aquisi\u00e7\u00e3o de hospitais veterin\u00e1rios adicionais e melhorias nos servi\u00e7os prestados \u00e0s equipes de sa\u00fade em sua rede de 33 cl\u00ednicas no Nordeste.<em> (BusinessWire)<\/em><\/li>\n<li>\u00cdNDIA A Cadila Healthcare anunciou um acordo definitivo para vender sua subsidi\u00e1ria integral<strong> Sa\u00fade Animal Zydus<\/strong> a um cons\u00f3rcio liderado pela Multiples Alternate Asset Management por Rs 2.921 crore ($398 milh\u00f5es). O cons\u00f3rcio est\u00e1 adquirindo o empreendimento por meio de uma sociedade de prop\u00f3sito espec\u00edfico (SPV) por eles controlada, em nome de <strong>Zenex Sa\u00fade Animal \u00cdndia<\/strong>. A Zydus Animal Health and Investments Ltd (ZAHL) tem outro empreendimento de sa\u00fade animal que dever\u00e1 iniciar neg\u00f3cios de sa\u00fade animal nos EUA e em alguns pa\u00edses europeus e este empreendimento comercial n\u00e3o faz parte da transa\u00e7\u00e3o. <em>(Outlookindia.com)<\/em><\/li>\n<\/ul>\n<p>***********************************<br \/>\n<strong>RASTREADOR DE PRE\u00c7O DE A\u00c7\u00d5ES DE SA\u00daDE ANIMAL<\/strong><\/p>\n<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-29301\" src=\"https:\/\/brakkeconsulting.com\/wp-content\/uploads\/2021\/05\/Stock-Table-5.14.png\" alt=\"\" width=\"543\" height=\"396\" srcset=\"https:\/\/brakkeconsulting.com\/wp-content\/uploads\/2021\/05\/Stock-Table-5.14.png 543w, https:\/\/brakkeconsulting.com\/wp-content\/uploads\/2021\/05\/Stock-Table-5.14-480x350.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 543px, 100vw\" \/><\/strong><\/p>\n<p>***********************************<br \/>\n<strong>NOT\u00cdCIAS DE SA\u00daDE ANIMAL<\/strong><\/p>\n<ul>\n<li>EUA \u2013 SESS\u00c3O DE BIOTECNOLOGIA DA FDA O Centro de Medicina Veterin\u00e1ria (CVM) da FDA est\u00e1 anunciando uma Sess\u00e3o de Divulga\u00e7\u00e3o das Partes Interessadas em Biotecnologia Animal que ser\u00e1 aberta ao p\u00fablico e ocorrer\u00e1 virtualmente na quarta-feira, 28 de julho, das 15h40 \u00e0s 16h45 ET via Amplia\u00e7\u00e3o. A sess\u00e3o est\u00e1 aberta a todas as partes interessadas, sem nenhum custo, e ocorrer\u00e1 em conjunto com a confer\u00eancia Genome Writer&#039;s Guild 2021. <a href=\"https:\/\/www.fda.gov\/animal-veterinary\/cvm-updates\/fda-announces-animal-biotechnology-stakeholder-virtual-outreach-session?utm_medium=email&amp;utm_source=govdelivery\">Clique aqui<\/a> Para maiores informa\u00e7\u00f5es<em> (FDA)<\/em><\/li>\n<\/ul>\n<p>************************************<br \/>\n<strong>PONTO DE VISTA DA BRAKKE CONSULTORIA<\/strong><br \/>\n<strong>Devemos voltar ao escrit\u00f3rio?<\/strong><\/p>\n<p>Acabamos de participar de uma grande experi\u00eancia de passar rapidamente do escrit\u00f3rio para o trabalho remoto. Sem uma pandemia, \u00e9 duvidoso que jamais ter\u00edamos visto uma mudan\u00e7a t\u00e3o dram\u00e1tica no ambiente de trabalho. Muitos c\u00e9ticos que pensavam que trabalhar remotamente em seus neg\u00f3cios nunca seria funcional se tornaram crentes.<\/p>\n<p>A pergunta para muitas empresas agora \u00e9 qual \u00e9 o pr\u00f3ximo passo? Encontrar a resposta certa envolve considera\u00e7\u00e3o pelo moral, rotatividade e produtividade. Economia de espa\u00e7o no escrit\u00f3rio, preocupa\u00e7\u00f5es com cuidados infantis e capacidade de manter um ambiente de neg\u00f3cios colaborativo tamb\u00e9m s\u00e3o fatores nessa decis\u00e3o.<\/p>\n<p>Uma pesquisa recente com 1.800 profissionais e executivos de alto escal\u00e3o conduzida pela Littler, um escrit\u00f3rio de advocacia da Calif\u00f3rnia, revelou duas quest\u00f5es interessantes sobre o retorno dos trabalhadores ao escrit\u00f3rio:<\/p>\n<ul>\n<li>Apenas 4% dos empregadores acreditam que seus funcion\u00e1rios preferem o retorno em tempo integral ao trabalho pessoal, mas 28% dos empregadores planejam que a maioria de seus funcion\u00e1rios volte em tempo integral.<\/li>\n<li>71% dos empregadores acreditam que seus funcion\u00e1rios prefeririam um modelo h\u00edbrido com op\u00e7\u00f5es remotas, mas apenas 55% por cento dos empregadores planejam oferecer essa configura\u00e7\u00e3o.<\/li>\n<\/ul>\n<p>Ajude-nos a entender onde voc\u00ea est\u00e1 com problemas de retorno ao escrit\u00f3rio respondendo \u00e0 pergunta da pesquisa da semana.<\/p>\n<p><em>Cary Christensen<\/em><\/p>\n<p>***********************************<br \/>\n<strong>SUA VIS\u00c3O <\/strong><\/p>\n<p>Os leitores da newsletter est\u00e3o otimistas em 2021! Na semana passada, perguntamos: \u201cO que voc\u00ea espera que seja o crescimento global em sa\u00fade animal em 2021?\u201d O maior n\u00famero de entrevistados, 54%, disse 6-8%. Apenas a 8% disse que o setor cresceria menos, enquanto a 38% disse ainda mais. A m\u00e9dia para todos os entrevistados foi de 8,2%. Isso se compara ao crescimento anual de 4,5-5% que tem sido t\u00edpico nos \u00faltimos anos.<\/p>\n<p><strong>Essa semana:<\/strong><\/p>\n<p><a href=\"https:\/\/www.surveymonkey.com\/r\/99CMZBQ\"><u>Qual resposta melhor descreve a posi\u00e7\u00e3o atual da sua empresa em rela\u00e7\u00e3o ao local de trabalho para funcion\u00e1rios que come\u00e7aram a trabalhar em casa devido \u00e0 pandemia?<\/u><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>*********************************** Not\u00edcias e notas sobre sa\u00fade animal da Brakke Consulting para 14 de maio de 2021 Copyright \u00a9 Brakke Editor de consultoria: Lynn Fondon DVM MBA ************************************ NAS NOT\u00cdCIAS: Not\u00edcias sobre ganhos melhores Choice Company Cryoport DS Pharma Sa\u00fade Animal Elanco Kindred Biosciences Ouro Fino Spectrum Brands Holdings Zomedica Outras Not\u00edcias Advanced Animal Diagnostics Alltech Bio-Cide International Boehringer Ingelheim CannaHorse Elanco Kemin Industries Pet Releaf Rarebreed Veterinary Partners Trouw Nutrition Zenex Animal Health India Zydus Animal Health **** ******************************** DIVULGA\u00c7\u00d5ES DE GANHOS DA EMPRESA A Elanco Animal Health relatou fortes resultados financeiros no primeiro trimestre de 2021. Receita no primeiro trimestre foi de $1.242 milh\u00f5es, composto por $683 milh\u00f5es do portf\u00f3lio legado da Elanco e $559 milh\u00f5es do portf\u00f3lio legado da Bayer Animal Health. A receita aumentou 89% impulsionada pela inclus\u00e3o do neg\u00f3cio Bayer Animal Health; a receita herdada da Elanco no primeiro trimestre foi de $683 milh\u00f5es, um aumento de 4% ano ap\u00f3s ano. O preju\u00edzo l\u00edquido no trimestre foi de $(61) milh\u00f5es em compara\u00e7\u00e3o com um preju\u00edzo l\u00edquido de $(49) milh\u00f5es no mesmo per\u00edodo do ano anterior. (comunicado \u00e0 imprensa da empresa) A Ouro Fino Sa\u00fade Animal divulgou os resultados do primeiro trimestre de 2021. As receitas foram de R$168,8 milh\u00f5es ($32,3 milh\u00f5es), um aumento de 51% em rela\u00e7\u00e3o ao trimestre do ano anterior. (IHS Markit Connect) A DS Pharma Animal Health relatou resultados para o ano fiscal encerrado em 31 de mar\u00e7o de 2021. As vendas foram de 12.860 milh\u00f5es de ienes ($118 milh\u00f5es), um<\/p>\n<div class=\"view-full-post\"><a href=\"https:\/\/brakkeconsulting.com\/pt\/animal-health-news-notes-for-may-14-2021\/\" class=\"view-full-post-btn\">Ver postagem completa<\/a><\/div>\n<p>;<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"class_list":["post-29300","post","type-post","status-publish","format-standard","hentry","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>News from Brakke Consulting<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/brakkeconsulting.com\/pt\/animal-health-news-notes-for-may-14-2021\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"News from Brakke Consulting\" \/>\n<meta property=\"og:description\" content=\"*********************************** Brakke Consulting&#8217;s Animal Health News &amp; Notes for May 14, 2021 Copyright \u00a9 Brakke Consulting Editor: Lynn Fondon DVM MBA ************************************ IN THE NEWS: Earnings News Better Choice Company Cryoport DS Pharma Animal Health Elanco Kindred Biosciences Ouro Fino Spectrum Brands Holdings Zomedica Other News Advanced Animal Diagnostics Alltech Bio-Cide International Boehringer Ingelheim CannaHorse Elanco Kemin Industries Pet Releaf Rarebreed Veterinary Partners Trouw Nutrition Zenex Animal Health India Zydus Animal Health ************************************ COMPANY EARNINGS RELEASES Elanco Animal Health reported strong financial results for the first quarter of 2021. Revenue in the first quarter was $1,242 million, comprised of $683 million from the legacy Elanco portfolio and $559 million from the legacy Bayer Animal Health portfolio. Revenue increased 89% driven by the inclusion of the Bayer Animal Health business; legacy Elanco revenue in the first quarter was $683 million, an increase of 4% year over year. Net loss for the quarter was $(61) million compared to a net loss of $(49) million in the year-ago period. (company press release) Ouro Fino Sa\u00fade Animal reported results for the first quarter of 2021. Revenues were R$168.8 million ($32.3 million), an increase of 51% over the\u00a0 prior-year quarter. (IHS Markit Connect) DS Pharma Animal Health reported results for the fiscal year ended March 31, 2021. Sales were JPY 12,860 million ($118 million), anView Full Post;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/brakkeconsulting.com\/pt\/animal-health-news-notes-for-may-14-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Brakke Consulting Website\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-13T22:03:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/brakkeconsulting.com\/wp-content\/uploads\/2021\/05\/Stock-Table-5.14.png\" \/>\n<meta name=\"author\" content=\"Brakke Consulting\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Brakke Consulting\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/animal-health-news-notes-for-may-14-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/animal-health-news-notes-for-may-14-2021\\\/\"},\"author\":{\"name\":\"Brakke Consulting\",\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/#\\\/schema\\\/person\\\/a5d2c4b59040e54bfe8f4f41f77e04d6\"},\"headline\":\"Animal Health News &#038; Notes for May 14, 2021\",\"datePublished\":\"2021-05-13T22:03:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/animal-health-news-notes-for-may-14-2021\\\/\"},\"wordCount\":1386,\"image\":{\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/animal-health-news-notes-for-may-14-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/brakkeconsulting.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Stock-Table-5.14.png\",\"articleSection\":[\"Newsletter\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/animal-health-news-notes-for-may-14-2021\\\/\",\"url\":\"https:\\\/\\\/brakkeconsulting.com\\\/animal-health-news-notes-for-may-14-2021\\\/\",\"name\":\"News from Brakke Consulting\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/animal-health-news-notes-for-may-14-2021\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/animal-health-news-notes-for-may-14-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/brakkeconsulting.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Stock-Table-5.14.png\",\"datePublished\":\"2021-05-13T22:03:59+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/#\\\/schema\\\/person\\\/a5d2c4b59040e54bfe8f4f41f77e04d6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/animal-health-news-notes-for-may-14-2021\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/brakkeconsulting.com\\\/animal-health-news-notes-for-may-14-2021\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/animal-health-news-notes-for-may-14-2021\\\/#primaryimage\",\"url\":\"http:\\\/\\\/brakkeconsulting.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Stock-Table-5.14.png\",\"contentUrl\":\"http:\\\/\\\/brakkeconsulting.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Stock-Table-5.14.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/animal-health-news-notes-for-may-14-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/brakkeconsulting.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Animal Health News &#038; Notes for May 14, 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/#website\",\"url\":\"https:\\\/\\\/brakkeconsulting.com\\\/\",\"name\":\"Brakke Consulting Website\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/brakkeconsulting.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/#\\\/schema\\\/person\\\/a5d2c4b59040e54bfe8f4f41f77e04d6\",\"name\":\"Brakke Consulting\",\"url\":\"https:\\\/\\\/brakkeconsulting.com\\\/pt\\\/author\\\/i5ww2018\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Not\u00edcias da Brakke Consulting","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/brakkeconsulting.com\/pt\/animal-health-news-notes-for-may-14-2021\/","og_locale":"pt_PT","og_type":"article","og_title":"News from Brakke Consulting","og_description":"*********************************** Brakke Consulting&#8217;s Animal Health News &amp; Notes for May 14, 2021 Copyright \u00a9 Brakke Consulting Editor: Lynn Fondon DVM MBA ************************************ IN THE NEWS: Earnings News Better Choice Company Cryoport DS Pharma Animal Health Elanco Kindred Biosciences Ouro Fino Spectrum Brands Holdings Zomedica Other News Advanced Animal Diagnostics Alltech Bio-Cide International Boehringer Ingelheim CannaHorse Elanco Kemin Industries Pet Releaf Rarebreed Veterinary Partners Trouw Nutrition Zenex Animal Health India Zydus Animal Health ************************************ COMPANY EARNINGS RELEASES Elanco Animal Health reported strong financial results for the first quarter of 2021. Revenue in the first quarter was $1,242 million, comprised of $683 million from the legacy Elanco portfolio and $559 million from the legacy Bayer Animal Health portfolio. Revenue increased 89% driven by the inclusion of the Bayer Animal Health business; legacy Elanco revenue in the first quarter was $683 million, an increase of 4% year over year. Net loss for the quarter was $(61) million compared to a net loss of $(49) million in the year-ago period. (company press release) Ouro Fino Sa\u00fade Animal reported results for the first quarter of 2021. Revenues were R$168.8 million ($32.3 million), an increase of 51% over the\u00a0 prior-year quarter. (IHS Markit Connect) DS Pharma Animal Health reported results for the fiscal year ended March 31, 2021. Sales were JPY 12,860 million ($118 million), anView Full Post;","og_url":"https:\/\/brakkeconsulting.com\/pt\/animal-health-news-notes-for-may-14-2021\/","og_site_name":"Brakke Consulting Website","article_published_time":"2021-05-13T22:03:59+00:00","og_image":[{"url":"https:\/\/brakkeconsulting.com\/wp-content\/uploads\/2021\/05\/Stock-Table-5.14.png","type":"","width":"","height":""}],"author":"Brakke Consulting","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Brakke Consulting","Tempo estimado de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/brakkeconsulting.com\/animal-health-news-notes-for-may-14-2021\/#article","isPartOf":{"@id":"https:\/\/brakkeconsulting.com\/animal-health-news-notes-for-may-14-2021\/"},"author":{"name":"Brakke Consulting","@id":"https:\/\/brakkeconsulting.com\/#\/schema\/person\/a5d2c4b59040e54bfe8f4f41f77e04d6"},"headline":"Animal Health News &#038; Notes for May 14, 2021","datePublished":"2021-05-13T22:03:59+00:00","mainEntityOfPage":{"@id":"https:\/\/brakkeconsulting.com\/animal-health-news-notes-for-may-14-2021\/"},"wordCount":1386,"image":{"@id":"https:\/\/brakkeconsulting.com\/animal-health-news-notes-for-may-14-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/brakkeconsulting.com\/wp-content\/uploads\/2021\/05\/Stock-Table-5.14.png","articleSection":["Newsletter"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/brakkeconsulting.com\/animal-health-news-notes-for-may-14-2021\/","url":"https:\/\/brakkeconsulting.com\/animal-health-news-notes-for-may-14-2021\/","name":"Not\u00edcias da Brakke Consulting","isPartOf":{"@id":"https:\/\/brakkeconsulting.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/brakkeconsulting.com\/animal-health-news-notes-for-may-14-2021\/#primaryimage"},"image":{"@id":"https:\/\/brakkeconsulting.com\/animal-health-news-notes-for-may-14-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/brakkeconsulting.com\/wp-content\/uploads\/2021\/05\/Stock-Table-5.14.png","datePublished":"2021-05-13T22:03:59+00:00","author":{"@id":"https:\/\/brakkeconsulting.com\/#\/schema\/person\/a5d2c4b59040e54bfe8f4f41f77e04d6"},"breadcrumb":{"@id":"https:\/\/brakkeconsulting.com\/animal-health-news-notes-for-may-14-2021\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/brakkeconsulting.com\/animal-health-news-notes-for-may-14-2021\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/brakkeconsulting.com\/animal-health-news-notes-for-may-14-2021\/#primaryimage","url":"https:\/\/brakkeconsulting.com\/wp-content\/uploads\/2021\/05\/Stock-Table-5.14.png","contentUrl":"https:\/\/brakkeconsulting.com\/wp-content\/uploads\/2021\/05\/Stock-Table-5.14.png"},{"@type":"BreadcrumbList","@id":"https:\/\/brakkeconsulting.com\/animal-health-news-notes-for-may-14-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/brakkeconsulting.com\/"},{"@type":"ListItem","position":2,"name":"Animal Health News &#038; Notes for May 14, 2021"}]},{"@type":"WebSite","@id":"https:\/\/brakkeconsulting.com\/#website","url":"https:\/\/brakkeconsulting.com\/","name":"Site da Brakke Consulting","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/brakkeconsulting.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/brakkeconsulting.com\/#\/schema\/person\/a5d2c4b59040e54bfe8f4f41f77e04d6","name":"Brakke Consultoria","url":"https:\/\/brakkeconsulting.com\/pt\/author\/i5ww2018\/"}]}},"_links":{"self":[{"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/posts\/29300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/comments?post=29300"}],"version-history":[{"count":1,"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/posts\/29300\/revisions"}],"predecessor-version":[{"id":29302,"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/posts\/29300\/revisions\/29302"}],"wp:attachment":[{"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/media?parent=29300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/categories?post=29300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/tags?post=29300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}