{"id":27963,"date":"2020-03-26T18:47:24","date_gmt":"2020-03-27T00:47:24","guid":{"rendered":"https:\/\/brakkeconsulting.com\/?p=27963"},"modified":"2020-03-26T18:47:24","modified_gmt":"2020-03-27T00:47:24","slug":"animal-health-news-notes-for-march-27-2020","status":"publish","type":"post","link":"https:\/\/brakkeconsulting.com\/pt\/animal-health-news-notes-for-march-27-2020\/","title":{"rendered":"Not\u00edcias e notas de sa\u00fade animal de 27 de mar\u00e7o de 2020"},"content":{"rendered":"<p>***********************************<br \/>\n<strong>Brakke Consulting&#039;s <\/strong><br \/>\n<strong>Not\u00edcias e notas de sa\u00fade animal de 27 de mar\u00e7o<\/strong><strong>, 2020<\/strong><br \/>\n<em>Copyright \u00a9 Brakke Consulting<br \/>\n<\/em><em>Editor: Lynn Fondon DVM MBA<br \/>\n<\/em>************************************<\/p>\n<p>NAS NOTICIAS:<\/p>\n<p><u>Novidades da Brakke Consulting<\/u><br \/>\n<strong>Relat\u00f3rio: Produtos de Sa\u00fade para Animais de Estima\u00e7\u00e3o \u2013 Mudan\u00e7a de Canais<\/strong><\/p>\n<p><u>Not\u00edcias de Ganhos<br \/>\n<\/u>Anpario<br \/>\nGeneral Mills<br \/>\nKrka<br \/>\nNeogen<\/p>\n<p><u>Outras not\u00edcias<br \/>\n<\/u>Avivagen<br \/>\nDistribui\u00e7\u00e3o Clipper<br \/>\nCovetrus<br \/>\nDechra<br \/>\nHester Bioci\u00eancias<br \/>\nInaba Alimentos EUA<br \/>\nInd\u00fastrias Melder<br \/>\nInd\u00fastrias Kemin<br \/>\nMiller Suprimentos Veterin\u00e1rios<br \/>\nNeogen<br \/>\nPetIQ<br \/>\npetriagem<br \/>\nAnimais de estima\u00e7\u00e3o livres de estresse<br \/>\nwebinar veterin\u00e1rio<strong><br \/>\n<\/strong><\/p>\n<p><strong>************************************<\/strong><\/p>\n<p><strong>Alian\u00e7a de Agricultura Animal<\/strong><\/p>\n<p><strong>Encontro de Partes Interessadas 2020<\/strong><\/p>\n<p><strong>7 a 8 de maio | Cimeira virtual<\/strong><\/p>\n<p>O 2020 Stakeholders Summit acontecer\u00e1 virtualmente de 7 a 8 de maio e em uma s\u00e9rie de webinars pr\u00e9-confer\u00eancia. As sess\u00f5es abordar\u00e3o sustentabilidade, bem-estar animal, engajamento de influenciadores, prepara\u00e7\u00e3o para campanhas de ativistas pelos direitos dos animais e outros t\u00f3picos importantes.<\/p>\n<p>Participe do Virtual Summit e voc\u00ea estar\u00e1 preparado para construir pontes da fazenda \u00e0 mesa. A C\u00fapula anual, agora em seu 19\u00ba ano, re\u00fane l\u00edderes de pensamento nas ind\u00fastrias de agricultura e alimentos para discutir quest\u00f5es importantes e ideias prontas para conectar todos ao longo da cadeia alimentar, envolver influenciadores e proteger o futuro da agricultura animal. Os participantes sair\u00e3o do Virtual Summit 2020 com as ferramentas necess\u00e1rias para agir e fazer parte de toda e qualquer conversa que possa impactar o futuro da pecu\u00e1ria e seus neg\u00f3cios.<\/p>\n<p>Para mais detalhes e para se inscrever, clique<a href=\"http:\/\/summit.animalagalliance.org\/\"> aqui.<\/a><\/p>\n<p><strong>************************************<\/strong><\/p>\n<p><strong>RELEASES DE RESULTADOS DA EMPRESA<\/strong><\/p>\n<ul>\n<li><strong>Corpora\u00e7\u00e3o Neogen<\/strong> anunciou os resultados para o terceiro trimestre de seu ano fiscal de 2020, encerrado em 29 de fevereiro. As receitas foram de $99,9 milh\u00f5es, 2% acima do terceiro trimestre do ano anterior. O lucro l\u00edquido do terceiro trimestre foi de $12,2 milh\u00f5es, em compara\u00e7\u00e3o com $13,1 milh\u00f5es do ano anterior. O segmento de Seguran\u00e7a Animal da Neogen relatou um aumento de receita de 6% para $49,4 milh\u00f5es.<em> (comunicado de imprensa da empresa)<\/em><\/li>\n<li><strong>Krka <\/strong>reportou resultados para o ano inteiro de 2019. O volume de neg\u00f3cios chegou a 69 milh\u00f5es de euros ($76 milh\u00f5es), um aumento de 9% em compara\u00e7\u00e3o com 2018. <em>(Farm\u00e1cia Animal)<\/em><\/li>\n<li><strong>General Mills <\/strong>resultados relatados para o terceiro trimestre fiscal encerrado em 23 de fevereiro. As vendas l\u00edquidas para o segmento de animais de estima\u00e7\u00e3o da empresa (Blue Buffalo) foram de $384 milh\u00f5es, um aumento de 11% em rela\u00e7\u00e3o ao trimestre do ano anterior.<em> (Not\u00edcias de produtos para animais de estima\u00e7\u00e3o)<\/em><\/li>\n<li><strong>Anpario<\/strong> resultados relatados para o ano fiscal de 2019. As receitas totais para o ano inteiro foram de GBP 29 milh\u00f5es ($33,4 milh\u00f5es), um aumento de 3% para o ano fiscal de 2019.<em> (Farm\u00e1cia Animal)<\/em><\/li>\n<\/ul>\n<p><strong>***********************************<\/strong><br \/>\n<strong>CONSULTORIA DE FREIO<\/strong><\/p>\n<p><strong>PRODUTOS DE SA\u00daDE PARA ANIMAIS DE ESTIMA\u00c7\u00c3O: MUDANDO DE CANAIS<\/strong><\/p>\n<p>As vendas de produtos para animais de estima\u00e7\u00e3o est\u00e3o em um ponto de inflex\u00e3o?<\/p>\n<p>Um novo relat\u00f3rio da Brakke Consulting mede e caracteriza as mudan\u00e7as mais din\u00e2micas que ocorrem na comercializa\u00e7\u00e3o de produtos para animais de estima\u00e7\u00e3o \u2013 o surgimento de novos canais e a mudan\u00e7a de comportamento de compra dos donos de animais, especialmente no que se refere a produtos tradicionalmente adquiridos na cl\u00ednica veterin\u00e1ria.<\/p>\n<p>Pet Health Products: Changing Channels \u00e9 baseado em dois estudos nacionais representativos: um de mais de 1.000 donos de animais de estima\u00e7\u00e3o, o outro de mais de 550 veterin\u00e1rios de animais de companhia. Os dados dessas pesquisas s\u00e3o comparados aos dados de estudos anteriores da Brakke nessas \u00e1reas para destacar as tend\u00eancias.<\/p>\n<p>Este novo relat\u00f3rio oportuno fornece aos profissionais de marketing e investidores informa\u00e7\u00f5es importantes para ajudar:<\/p>\n<ul>\n<li>Concentre recursos nas \u00e1reas mais produtivas<\/li>\n<li>Construir estrat\u00e9gias de defesa mais eficazes nos principais canais<\/li>\n<li>Recalibrar as estrat\u00e9gias de canal para os principais produtos<\/li>\n<li>Crie estrat\u00e9gias de canal inovadoras para novos produtos e categorias<\/li>\n<li>Desenhar estrat\u00e9gias de investimento baseadas em \u201cpescar onde est\u00e1 o peixe\u201d<\/li>\n<\/ul>\n<p>Pet Health Products, Changing Channels j\u00e1 est\u00e1 dispon\u00edvel para compra. O custo por relat\u00f3rio \u00e9 de $10.000. Para obter mais informa\u00e7\u00f5es sobre este importante estudo, entre em contato com John Volk em <a href=\"mailto:john@volkonline.com\">john@volkonline.com<\/a> \u00a0ou Bob Jones em <a href=\"mailto:rwjones@brakkeconsulting.com\">rwjones@brakkeconsulting.com<\/a> .<\/p>\n<p><a href=\"http:\/\/www.BrakkeConsulting.com\">www.BrakkeConsulting.com<\/a><\/p>\n<p><strong>************************************<\/strong><\/p>\n<p><strong>COMUNICADOS DE NOT\u00cdCIAS DA EMPRESA<\/strong><\/p>\n<ul>\n<li>A FDA anunciou a aprova\u00e7\u00e3o do <strong>Produtos Veterin\u00e1rios Dechra<\/strong>&#039; Marboquin comprimidos, a primeira aprova\u00e7\u00e3o gen\u00e9rica para marbofloxacina, para o tratamento de infec\u00e7\u00f5es suscept\u00edveis em c\u00e3es e gatos.<em> (FDA)<\/em><\/li>\n<li><strong>Covetrus<\/strong> informou que est\u00e1 vendo uma forte demanda em seus servi\u00e7os de gerenciamento de prescri\u00e7\u00f5es e farm\u00e1cia on-line, vinculados ao aumento do envolvimento da pr\u00e1tica e da demanda de donos de animais de estima\u00e7\u00e3o \u00e0 medida que o novo coronav\u00edrus (COVID-19) se espalha pelos Estados Unidos. Nas \u00faltimas tr\u00eas semanas, a rede de farm\u00e1cias Covetrus registrou um aumento significativo no n\u00famero de prescri\u00e7\u00f5es de medicamentos e alimentos diet\u00e9ticos a serem envasados e enviados para donos de animais de estima\u00e7\u00e3o, com o n\u00famero de produtos enviados no m\u00eas crescendo aproximadamente 45% em rela\u00e7\u00e3o a 2019. <em>(Seekingalpha. com)<\/em><\/li>\n<li><strong>Neogen<\/strong> anunciou o lan\u00e7amento do teste GGP Shrimp 50k, uma ferramenta gen\u00f4mica que incorpora os \u00faltimos avan\u00e7os em informa\u00e7\u00f5es de marcadores gen\u00e9ticos para o camar\u00e3o whiteleg (tamb\u00e9m conhecido como camar\u00e3o branco do Pac\u00edfico ou camar\u00e3o rei). O teste est\u00e1 dispon\u00edvel atrav\u00e9s do Centre for Aquaculture Technologies Canada (CATC).<em> (Farm\u00e1cia Animal)<\/em><\/li>\n<li><strong>Ind\u00fastrias Kemin<\/strong> anunciou que recebeu a aprova\u00e7\u00e3o do FDA para o uso do KemTRACE Chromium como fonte de propionato de cromo em dietas para cavalos. KemTRACE \u00e9 a primeira fonte de propionato de cromo aprovada pela FDA e tamb\u00e9m est\u00e1 dispon\u00edvel para uso em su\u00ednos, frangos de corte e bovinos. <em>(Farm\u00e1cia Animal)<\/em><\/li>\n<li><strong>Inaba Alimentos EUA <\/strong>e <strong>Clipper distribuindo um<\/strong>anunciou o lan\u00e7amento do Churu Veterinarian Formula, um pur\u00ea totalmente natural, estimulante do apetite, altamente saboroso e que auxilia na recupera\u00e7\u00e3o do paciente. Churu Veterinarian Formula est\u00e1 dispon\u00edvel nos sabores frango e atum. <em>(comunicado de imprensa da empresa)<\/em><\/li>\n<li><strong>PetIQ<\/strong>anunciou que, com muita cautela para seus funcion\u00e1rios e clientes em resposta ao COVID-19, todas as cl\u00ednicas comunit\u00e1rias veterin\u00e1rias e centros de bem-estar fechar\u00e3o temporariamente a partir de sexta-feira, 20 de mar\u00e7o de 2020. A divis\u00e3o VIP Petcare da empresa opera em mais de 3.400 localiza\u00e7\u00f5es de parceiros de varejo em 41 estados. A Empresa est\u00e1 monitorando continuamente esta situa\u00e7\u00e3o e reabrir\u00e1 seus locais de atendimento veterin\u00e1rio assim que poss\u00edvel. <em>(comunicado de imprensa da empresa)<\/em><\/li>\n<li><strong>petriagem<\/strong>, um provedor de telessa\u00fade B2B para pr\u00e1ticas veterin\u00e1rias, anunciou uma parceria com <strong>Miller Suprimentos Veterin\u00e1rios<\/strong>. Miller comercializar\u00e1 Petriage para seus milhares de clientes veterin\u00e1rios<em>. (PRnewswire)<\/em><\/li>\n<li><strong>webinar veterin\u00e1rio<\/strong> anunciaram que fizeram parceria com <strong>Animais de estima\u00e7\u00e3o livres de estresse<\/strong>, um curso online profissional de manejo e comportamento de animais, credenciamento de cl\u00ednicas e comunidade. O curso Stress Free Pets for Veterinary Professionals \u00e9 aprovado pelo RACE e consiste em 10 m\u00f3dulos para Enfermeiros Veterin\u00e1rios e 11 m\u00f3dulos para Veterin\u00e1rios. <em>(comunicado de imprensa da empresa)<\/em><\/li>\n<li>\u00cdNDIA <strong>Hester Bioci\u00eancias<\/strong> anunciou que criou uma divis\u00e3o de Ci\u00eancia e Tecnologia de Manufatura (MSAT) para estimular seu neg\u00f3cio de vacinas.<em> (Farm\u00e1cia Animal)<\/em><\/li>\n<li>M\u00c9XICO <strong>Avivagen<\/strong> anunciou seus primeiros pedidos de compra de gado OxC-beta na Am\u00e9rica do Norte e est\u00e1 finalizando acordos de vendas no M\u00e9xico com <strong>Ind\u00fastrias Melder, SA De CV <\/strong><em>(comunicado de imprensa da empresa)<\/em><\/li>\n<\/ul>\n<p>***********************************<\/p>\n<p><strong>RASTREADOR DE PRE\u00c7O DE A\u00c7\u00d5ES DE SA\u00daDE ANIMAL<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-27964\" src=\"https:\/\/brakkeconsulting.com\/wp-content\/uploads\/2020\/03\/Stock-Table-3.27.jpg\" alt=\"\" width=\"839\" height=\"639\" srcset=\"https:\/\/brakkeconsulting.com\/wp-content\/uploads\/2020\/03\/Stock-Table-3.27.jpg 839w, https:\/\/brakkeconsulting.com\/wp-content\/uploads\/2020\/03\/Stock-Table-3.27-480x366.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 839px, 100vw\" \/><\/p>\n<p>***********************************<\/p>\n<p><strong>NOT\u00cdCIAS DE SA\u00daDE ANIMAL<br \/>\n<\/strong><\/p>\n<ul>\n<li>FDA \u2013 TELEMEDICINA Como parte do compromisso cont\u00ednuo da FDA de combater a pandemia de coronav\u00edrus (COVID-19) e fornecer flexibilidade nos setores regulamentados pela FDA, a ag\u00eancia anunciou hoje que pretende n\u00e3o impor temporariamente certos requisitos para permitir que os veterin\u00e1rios utilizem melhor telemedicina para atender \u00e0s necessidades de sa\u00fade animal durante a pandemia. A ag\u00eancia pretende suspender temporariamente a aplica\u00e7\u00e3o de partes dos requisitos federais de rela\u00e7\u00e3o veterin\u00e1rio-cliente-paciente (VCPR) relevantes para certos regulamentos da FDA. (Os conselhos veterin\u00e1rios estaduais individuais podem ter outros regulamentos de telemedicina que ainda devem ser seguidos.) Para obter mais informa\u00e7\u00f5es, clique em <a href=\"https:\/\/www.fda.gov\/news-events\/press-announcements\/coronavirus-covid-19-update-fda-helps-facilitate-veterinary-telemedicine-during-pandemic?utm_campaign=3-24-2020-GFI269&amp;utm_medium=email&amp;utm_source=Eloqua\">aqui<\/a>. <em>(FDA)<br \/>\n<\/em><\/li>\n<li>EUA \u2013 TESTE DE PSA O Departamento de Seguran\u00e7a Interna (DHS) dos EUA anunciou que os cientistas do Plum Island Animal Disease Center conclu\u00edram uma avalia\u00e7\u00e3o bem-sucedida de <strong>MatMaCorp<\/strong>O sistema port\u00e1til de an\u00e1lise de \u00e1cido nucleico da para detectar o v\u00edrus da peste su\u00edna africana (PSA) em porcos e produtos su\u00ednos infectados.<em> (alimentos)<\/em><\/li>\n<\/ul>\n<p>************************************<br \/>\n<strong>PONTO DE VISTA DA BRAKKE CONSULTORIA<\/strong><\/p>\n<p>\u00c0 medida que a pandemia de coronav\u00edrus se espalha por todos os cantos do globo, j\u00e1 estamos vendo seu impacto na sa\u00fade animal. A Covetrus relatou um aumento de 45% nos produtos enviados aos donos de animais de estima\u00e7\u00e3o nas tr\u00eas primeiras semanas de mar\u00e7o. A FDA anunciou que est\u00e1 relaxando a supervis\u00e3o da telemedicina veterin\u00e1ria, permitindo que os veterin\u00e1rios prestem atendimento em alguns casos sem consultas pessoais. Na semana passada, os provedores de telessa\u00fade Babelbark e whiskerDocs anunciaram que est\u00e3o oferecendo seus servi\u00e7os gratuitamente pelos pr\u00f3ximos 60 dias, e tenho certeza de que outros provedores de telessa\u00fade tamb\u00e9m est\u00e3o intensificando. A Neogen, que fabrica desinfetantes, luvas e desinfetantes para as m\u00e3os, anunciou que estava aumentando a produ\u00e7\u00e3o. Confer\u00eancias e reuni\u00f5es foram adiadas ou convertidas em reuni\u00f5es virtuais.<\/p>\n<p>A ind\u00fastria e, de fato, o mundo, est\u00e3o navegando em \u00e1guas desconhecidas agora, sem muitos dados concretos para nos guiar. No entanto, j\u00e1 estamos vendo um pouco da resili\u00eancia e adaptabilidade que nos ajudar\u00e1 a atravessar a tempestade. Fique em casa se puder, e fique seguro.<br \/>\n<em>Lynn Fondon<br \/>\n<\/em><\/p>\n<p>***********************************<br \/>\n<strong>SUA VIS\u00c3O<\/strong><\/p>\n<p>Na semana passada, pedimos que voc\u00ea previsse o impacto do COVID-19 no crescimento do segundo trimestre de sua empresa. A maioria de voc\u00eas disse que espera um decl\u00ednio no crescimento em compara\u00e7\u00e3o com o 2T 2019: 44% previu um decl\u00ednio de 1-5% e 36% espera uma queda de mais de 5%. Estaremos de olho nas tend\u00eancias do setor para ver como tudo se desenrola.<\/p>\n<p><strong>Pergunta da enquete desta semana:<\/strong><br \/>\nUma das tend\u00eancias emergentes ap\u00f3s os bloqueios e distanciamento social em toda a cidade \u00e9 o uso de chats de v\u00eddeo para realizar reuni\u00f5es sociais.<\/p>\n<p><a href=\"https:\/\/www.surveymonkey.com\/r\/BFDY9PY\"><strong>Voc\u00ea participou de um happy hour virtual ou chat de v\u00eddeo em grupo no \u00faltimo m\u00eas?<\/strong><\/a><\/p>\n<p>**********************************<\/p>\n<p>Problemas para visualizar esta newsletter? Voc\u00ea pode visualiz\u00e1-lo online em <a href=\"http:\/\/www.BrakkeConsulting.com\">www.BrakkeConsulting.com<\/a><\/p>\n<p><em>Este boletim eletr\u00f4nico \u00e9 propriedade exclusiva da Brakke Consulting.<br \/>\nQualquer uso do conte\u00fado deste documento deve ser aprovado e devidamente atribu\u00eddo \u00e0 Brakke Consulting.<\/em><\/p>\n<p>Para obter mais informa\u00e7\u00f5es sobre os servi\u00e7os e estudos sindicados da Brakke Consulting, visite nosso website em <a href=\"https:\/\/brakkeconsulting.com\/pt\/\">www.brakkeconsulting.com<\/a>.<\/p>\n<p>Brakke Consultoria<br \/>\nRua Green Valley, 806<br \/>\nSu\u00edte 200<br \/>\nGreensboro, NC 27408<\/p>","protected":false},"excerpt":{"rendered":"<p>*********************************** Not\u00edcias e notas sobre sa\u00fade animal da Brakke Consulting para 27 de mar\u00e7o de 2020 Copyright \u00a9 Brakke Editora de Consultoria: Lynn Fondon DVM MBA ************************************ NAS NOT\u00cdCIAS: Not\u00edcias da Brakke Consulting Relat\u00f3rio: Produtos de sa\u00fade para animais de estima\u00e7\u00e3o - Mudan\u00e7a de canal Not\u00edcias sobre ganhos Anpario General Mills Krka Neogen Outras not\u00edcias Avivagen Clipper Distribuindo Covetrus Dechra Hester Biosciences Inaba Foods EUA Industrias Melder Kemin Industries Miller Veterinary Supply Neogen PetIQ Petriage Stress Free Pets vet-webinar ******* ***************************** C\u00fapula das partes interessadas da Animal Agriculture Alliance 2020, 7 a 8 de maio | C\u00fapula Virtual A C\u00fapula de Stakeholders de 2020 acontecer\u00e1 virtualmente de 7 a 8 de maio e em uma s\u00e9rie de webinars pr\u00e9-confer\u00eancia. As sess\u00f5es abordar\u00e3o sustentabilidade, bem-estar animal, envolvimento de influenciadores, prepara\u00e7\u00e3o para campanhas de ativistas pelos direitos dos animais e outros t\u00f3picos importantes. Participe do Virtual Summit e voc\u00ea estar\u00e1 preparado para construir pontes da fazenda \u00e0 mesa. A Cimeira anual, agora no seu 19\u00ba ano, re\u00fane l\u00edderes de pensamento nas ind\u00fastrias agr\u00edcola e alimentar para discutir quest\u00f5es urgentes e ideias inovadoras para ligar todos ao longo da cadeia alimentar, envolver influenciadores e proteger o futuro da agricultura animal. Os participantes sair\u00e3o do Virtual Summit 2020 com as ferramentas necess\u00e1rias para agir e fazer parte de toda e qualquer conversa que possa impactar o futuro da pecu\u00e1ria e de seus neg\u00f3cios. Para mais detalhes e inscri\u00e7\u00e3o, clique aqui.<\/p>\n<div class=\"view-full-post\"><a href=\"https:\/\/brakkeconsulting.com\/pt\/animal-health-news-notes-for-march-27-2020\/\" class=\"view-full-post-btn\">Ver postagem completa<\/a><\/div>\n<p>;<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"class_list":["post-27963","post","type-post","status-publish","format-standard","hentry","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>News from Brakke Consulting<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/brakkeconsulting.com\/pt\/animal-health-news-notes-for-march-27-2020\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"News from Brakke Consulting\" \/>\n<meta property=\"og:description\" content=\"*********************************** Brakke Consulting&#8217;s Animal Health News &amp; Notes for March 27, 2020 Copyright \u00a9 Brakke Consulting Editor: Lynn Fondon DVM MBA ************************************ IN THE NEWS: Brakke Consulting news Report: Pet Health Products &#8211; Changing Channels Earnings News Anpario General Mills Krka Neogen Other News Avivagen Clipper Distributing Covetrus Dechra Hester Biosciences Inaba Foods USA Industrias Melder Kemin Industries Miller Veterinary Supply Neogen PetIQ Petriage Stress Free Pets vet-webinar ************************************ Animal Agriculture Alliance 2020 Stakeholders Summit May 7 \u2013 8 | Virtual Summit The 2020 Stakeholders Summit will take place virtually on May 7 \u2013 8 and in a series of pre-conference webinars. Sessions will cover sustainability, animal welfare, influencer engagement, preparing for animal rights activist campaigns and other hot topics. Attend the Virtual Summit and you\u2019ll be primed and prepared to build bridges from farm to fork. The annual Summit, now in its 19th year, brings together thought leaders in the agriculture and food industries to discuss hot-button issues and out-of-the-box ideas to connect everyone along the food chain, engage influencers and protect the future of animal agriculture. Attendees will leave the 2020 Virtual Summit with the tools they need to take action and be part of any and all conversations that could impact the future of animal agriculture and their business. For more details and to register, click here.View Full Post;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/brakkeconsulting.com\/pt\/animal-health-news-notes-for-march-27-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"Brakke Consulting Website\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-27T00:47:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/brakkeconsulting.com\/wp-content\/uploads\/2020\/03\/Stock-Table-3.27.jpg\" \/>\n<meta name=\"author\" content=\"Brakke Consulting\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Brakke Consulting\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/animal-health-news-notes-for-march-27-2020\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/animal-health-news-notes-for-march-27-2020\\\/\"},\"author\":{\"name\":\"Brakke Consulting\",\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/#\\\/schema\\\/person\\\/a5d2c4b59040e54bfe8f4f41f77e04d6\"},\"headline\":\"Animal Health News &#038; Notes for March 27, 2020\",\"datePublished\":\"2020-03-27T00:47:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/animal-health-news-notes-for-march-27-2020\\\/\"},\"wordCount\":1470,\"image\":{\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/animal-health-news-notes-for-march-27-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/brakkeconsulting.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Stock-Table-3.27.jpg\",\"articleSection\":[\"Newsletter\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/animal-health-news-notes-for-march-27-2020\\\/\",\"url\":\"https:\\\/\\\/brakkeconsulting.com\\\/animal-health-news-notes-for-march-27-2020\\\/\",\"name\":\"News from Brakke Consulting\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/animal-health-news-notes-for-march-27-2020\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/animal-health-news-notes-for-march-27-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/brakkeconsulting.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Stock-Table-3.27.jpg\",\"datePublished\":\"2020-03-27T00:47:24+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/#\\\/schema\\\/person\\\/a5d2c4b59040e54bfe8f4f41f77e04d6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/animal-health-news-notes-for-march-27-2020\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/brakkeconsulting.com\\\/animal-health-news-notes-for-march-27-2020\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/animal-health-news-notes-for-march-27-2020\\\/#primaryimage\",\"url\":\"https:\\\/\\\/brakkeconsulting.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Stock-Table-3.27.jpg\",\"contentUrl\":\"https:\\\/\\\/brakkeconsulting.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Stock-Table-3.27.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/animal-health-news-notes-for-march-27-2020\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/brakkeconsulting.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Animal Health News &#038; Notes for March 27, 2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/#website\",\"url\":\"https:\\\/\\\/brakkeconsulting.com\\\/\",\"name\":\"Brakke Consulting Website\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/brakkeconsulting.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/#\\\/schema\\\/person\\\/a5d2c4b59040e54bfe8f4f41f77e04d6\",\"name\":\"Brakke Consulting\",\"url\":\"https:\\\/\\\/brakkeconsulting.com\\\/pt\\\/author\\\/i5ww2018\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Not\u00edcias da Brakke Consulting","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/brakkeconsulting.com\/pt\/animal-health-news-notes-for-march-27-2020\/","og_locale":"pt_PT","og_type":"article","og_title":"News from Brakke Consulting","og_description":"*********************************** Brakke Consulting&#8217;s Animal Health News &amp; Notes for March 27, 2020 Copyright \u00a9 Brakke Consulting Editor: Lynn Fondon DVM MBA ************************************ IN THE NEWS: Brakke Consulting news Report: Pet Health Products &#8211; Changing Channels Earnings News Anpario General Mills Krka Neogen Other News Avivagen Clipper Distributing Covetrus Dechra Hester Biosciences Inaba Foods USA Industrias Melder Kemin Industries Miller Veterinary Supply Neogen PetIQ Petriage Stress Free Pets vet-webinar ************************************ Animal Agriculture Alliance 2020 Stakeholders Summit May 7 \u2013 8 | Virtual Summit The 2020 Stakeholders Summit will take place virtually on May 7 \u2013 8 and in a series of pre-conference webinars. Sessions will cover sustainability, animal welfare, influencer engagement, preparing for animal rights activist campaigns and other hot topics. Attend the Virtual Summit and you\u2019ll be primed and prepared to build bridges from farm to fork. The annual Summit, now in its 19th year, brings together thought leaders in the agriculture and food industries to discuss hot-button issues and out-of-the-box ideas to connect everyone along the food chain, engage influencers and protect the future of animal agriculture. Attendees will leave the 2020 Virtual Summit with the tools they need to take action and be part of any and all conversations that could impact the future of animal agriculture and their business. For more details and to register, click here.View Full Post;","og_url":"https:\/\/brakkeconsulting.com\/pt\/animal-health-news-notes-for-march-27-2020\/","og_site_name":"Brakke Consulting Website","article_published_time":"2020-03-27T00:47:24+00:00","og_image":[{"url":"https:\/\/brakkeconsulting.com\/wp-content\/uploads\/2020\/03\/Stock-Table-3.27.jpg","type":"","width":"","height":""}],"author":"Brakke Consulting","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Brakke Consulting","Tempo estimado de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/brakkeconsulting.com\/animal-health-news-notes-for-march-27-2020\/#article","isPartOf":{"@id":"https:\/\/brakkeconsulting.com\/animal-health-news-notes-for-march-27-2020\/"},"author":{"name":"Brakke Consulting","@id":"https:\/\/brakkeconsulting.com\/#\/schema\/person\/a5d2c4b59040e54bfe8f4f41f77e04d6"},"headline":"Animal Health News &#038; Notes for March 27, 2020","datePublished":"2020-03-27T00:47:24+00:00","mainEntityOfPage":{"@id":"https:\/\/brakkeconsulting.com\/animal-health-news-notes-for-march-27-2020\/"},"wordCount":1470,"image":{"@id":"https:\/\/brakkeconsulting.com\/animal-health-news-notes-for-march-27-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/brakkeconsulting.com\/wp-content\/uploads\/2020\/03\/Stock-Table-3.27.jpg","articleSection":["Newsletter"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/brakkeconsulting.com\/animal-health-news-notes-for-march-27-2020\/","url":"https:\/\/brakkeconsulting.com\/animal-health-news-notes-for-march-27-2020\/","name":"Not\u00edcias da Brakke Consulting","isPartOf":{"@id":"https:\/\/brakkeconsulting.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/brakkeconsulting.com\/animal-health-news-notes-for-march-27-2020\/#primaryimage"},"image":{"@id":"https:\/\/brakkeconsulting.com\/animal-health-news-notes-for-march-27-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/brakkeconsulting.com\/wp-content\/uploads\/2020\/03\/Stock-Table-3.27.jpg","datePublished":"2020-03-27T00:47:24+00:00","author":{"@id":"https:\/\/brakkeconsulting.com\/#\/schema\/person\/a5d2c4b59040e54bfe8f4f41f77e04d6"},"breadcrumb":{"@id":"https:\/\/brakkeconsulting.com\/animal-health-news-notes-for-march-27-2020\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/brakkeconsulting.com\/animal-health-news-notes-for-march-27-2020\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/brakkeconsulting.com\/animal-health-news-notes-for-march-27-2020\/#primaryimage","url":"https:\/\/brakkeconsulting.com\/wp-content\/uploads\/2020\/03\/Stock-Table-3.27.jpg","contentUrl":"https:\/\/brakkeconsulting.com\/wp-content\/uploads\/2020\/03\/Stock-Table-3.27.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/brakkeconsulting.com\/animal-health-news-notes-for-march-27-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/brakkeconsulting.com\/"},{"@type":"ListItem","position":2,"name":"Animal Health News &#038; Notes for March 27, 2020"}]},{"@type":"WebSite","@id":"https:\/\/brakkeconsulting.com\/#website","url":"https:\/\/brakkeconsulting.com\/","name":"Site da Brakke Consulting","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/brakkeconsulting.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/brakkeconsulting.com\/#\/schema\/person\/a5d2c4b59040e54bfe8f4f41f77e04d6","name":"Brakke Consultoria","url":"https:\/\/brakkeconsulting.com\/pt\/author\/i5ww2018\/"}]}},"_links":{"self":[{"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/posts\/27963","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/comments?post=27963"}],"version-history":[{"count":1,"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/posts\/27963\/revisions"}],"predecessor-version":[{"id":27965,"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/posts\/27963\/revisions\/27965"}],"wp:attachment":[{"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/media?parent=27963"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/categories?post=27963"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/tags?post=27963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}