{"id":25934,"date":"2019-01-09T08:57:58","date_gmt":"2019-01-09T14:57:58","guid":{"rendered":"\/?p=25934"},"modified":"2019-01-09T08:57:58","modified_gmt":"2019-01-09T14:57:58","slug":"animal-health-news-notes-for-january-4-2019","status":"publish","type":"post","link":"https:\/\/brakkeconsulting.com\/pt\/animal-health-news-notes-for-january-4-2019\/","title":{"rendered":"Not\u00edcias e notas sobre sa\u00fade animal de 4 de janeiro de 2019"},"content":{"rendered":"<p>***********************************<br \/>\n<strong>Brakke Consulting&#039;s <\/strong><br \/>\n<strong>Not\u00edcias e notas sobre sa\u00fade animal de 4 de janeiro de 2019<\/strong><br \/>\nCopyright \u00a9 Brakke Consulting, Inc.<\/p>\n<p>Editor: Lynn Fondon DVM MBA<br \/>\n************************************<br \/>\nNAS NOTICIAS:<\/p>\n<p><span style=\"text-decoration: underline;\">Novidades da Brakke Consulting<\/span><br \/>\nVis\u00e3o geral da ind\u00fastria de sa\u00fade animal \u2013 registre-se agora<br \/>\nRecrutamento<\/p>\n<p><span style=\"text-decoration: underline;\">not\u00edcias de ganhos<\/span><br \/>\nNeogen<br \/>\nFazendas Sanderson<\/p>\n<p><span style=\"text-decoration: underline;\">outras not\u00edcias<\/span><br \/>\nAmerican Regent Animal Health<br \/>\nBoehringer Ingelheim<br \/>\nCareCredit<br \/>\nCovetrus<br \/>\nCentro de Gen\u00f4mica Delta<br \/>\nElanco<br \/>\nHenry Schein (Covetrus)<br \/>\nHenry Schein (CareCredit)<br \/>\nLifeLearn<br \/>\nLuitpold Sa\u00fade Animal<br \/>\nMerck<br \/>\nMerrick&#039;s<br \/>\nNeogen<br \/>\nOxyfresh<br \/>\nGrupo Pestell<br \/>\nArtigos para animais de estima\u00e7\u00e3o Plus<br \/>\nFarmaForce<br \/>\nPortaCheck<br \/>\nSentinel Capital Partners<br \/>\nesporte de resist\u00eancia<br \/>\nGuloseimas direcionadas para animais de estima\u00e7\u00e3o<br \/>\nTruPet<br \/>\nVetBiotek<br \/>\nVeterin\u00e1rios de primeira escolha<br \/>\nVetsource<br \/>\nveterin\u00e1rios plus<br \/>\nParceiros Wind Point<br \/>\nZhejiang ZhengliAntoo Biotecnologia<\/p>\n<p>***********************************<br \/>\n<strong>BRAKKE CONSULTING, INC.<\/strong><br \/>\n<strong>VIS\u00c3O GERAL DA IND\u00daSTRIA EM VMX E WVC <\/strong><br \/>\n<strong>AS INSCRI\u00c7\u00d5ES J\u00c1 EST\u00c3O ABERTAS<\/strong><\/p>\n<p>A Brakke Consulting tem o prazer de anunciar a Vis\u00e3o Geral da Ind\u00fastria de 2019. A Vis\u00e3o Geral da Ind\u00fastria de Sa\u00fade Animal de 2019 ser\u00e1 apresentada duas vezes neste inverno \u2013 uma vez na VMX em Orlando, Fl\u00f3rida, e outra na Western Veterinary Conference em Las Vegas, Nevada. Essas datas s\u00e3o:<\/p>\n<p>\u2022 VMX: ter\u00e7a-feira, 22 de janeiro de 2019, das 14h \u00e0s 16h, Rosen Plaza Hotel<br \/>\n\u2022 WVC: ter\u00e7a-feira, 19 de fevereiro de 2019, das 14h \u00e0s 16h, Four Seasons.<\/p>\n<p>As inscri\u00e7\u00f5es para as Vis\u00e3o Geral da Ind\u00fastria VMX e WVC j\u00e1 est\u00e3o abertas. As vagas s\u00e3o limitadas este ano, ent\u00e3o inscreva-se cedo!<\/p>\n<p>Para se registrar, acesse www.brakkeconsulting.com e role at\u00e9 a caixa \u201cNovidades\u201d. O pre\u00e7o \u00e9 de $400 por pessoa para inscri\u00e7\u00e3o online; o registro tardio \u00e9 $450. Os descontos est\u00e3o dispon\u00edveis para v\u00e1rios participantes da mesma empresa; visite nosso site ou ligue para 972-243-4033 para obter mais informa\u00e7\u00f5es.<\/p>\n<p>www.BrakkeConsulting.com<\/p>\n<p>***********************************<br \/>\nRELEASES DE RESULTADOS DA EMPRESA<\/p>\n<p>\u2022 A Neogen Corporation anunciou os resultados do segundo trimestre do ano fiscal de 2019 encerrado em 30 de novembro. O segmento de Seguran\u00e7a Animal da Neogen relatou receitas de $53,3 milh\u00f5es, um aumento de 4%. (comunicado de imprensa da empresa)<\/p>\n<p>\u2022 Sanderson Farms Inc. relatou resultados para o ano fiscal encerrado em 31 de outubro de 2018. As vendas l\u00edquidas foram de $3,236 bilh\u00f5es, em compara\u00e7\u00e3o com $3,342 bilh\u00f5es para o ano fiscal de 2017. O lucro l\u00edquido do ano totalizou $61,4 milh\u00f5es em compara\u00e7\u00e3o com o lucro l\u00edquido de $279,7 milh\u00f5es no \u00faltimo ano fiscal. (Alimentos)<\/p>\n<p>**********************************<br \/>\nCOMUNICADOS DE NOT\u00cdCIAS DA EMPRESA<\/p>\n<p>\u2022 A Boehringer Ingelheim anunciou que desenvolveu o ASF COMBAT (ASF Comprehensive Online Management and Biosecurity Assessment Tool). Esta ferramenta permite aos produtores de su\u00ednos avaliar \u00e1reas para melhoria da biosseguran\u00e7a nas suas explora\u00e7\u00f5es, preenchendo um pequeno question\u00e1rio baseado na literatura cient\u00edfica e na experi\u00eancia pr\u00e1tica do v\u00edrus da PSA, destinado a ajudar a reduzir o n\u00edvel de risco de introdu\u00e7\u00e3o da PSA. (Vantagem veterin\u00e1ria)<\/p>\n<p>\u2022 Em uma carta \u201cCaro Veterin\u00e1rio\u201d de 19 de dezembro, a FDA esclareceu a posi\u00e7\u00e3o do Centro de Medicina Veterin\u00e1ria (CVM) sobre o cumprimento das condi\u00e7\u00f5es de uso do produto alimentar medicamentoso Tylan 40 ou Tylan 100 Tipo A da Elanco (fosfato de tilosina) em bovinos de corte . Devido \u00e0s mudan\u00e7as no tamanho do gado desde que foi aprovado, os veterin\u00e1rios dizem que \u00e9 praticamente dif\u00edcil cumprir tanto o n\u00edvel de concentra\u00e7\u00e3o de ra\u00e7\u00e3o aprovado quanto a taxa de ingest\u00e3o do medicamento. A CVM est\u00e1 atualmente trabalhando com a Elanco para revisar a rotulagem dos produtos para resolver o problema. (Alimentos)<\/p>\n<p>\u2022 A Henry Schein, Inc. e a Vets First Choice anunciaram que a nova empresa p\u00fablica independente que resultar\u00e1 da cis\u00e3o planejada do neg\u00f3cio Henry Schein Animal Health e da subsequente fus\u00e3o com a Vets First Choice ser\u00e1 denominada Covetrus. A Henry Schein apresentou uma declara\u00e7\u00e3o de registro no Formul\u00e1rio S-4\/S-1 junto \u00e0 Comiss\u00e3o de Valores Mobili\u00e1rios dos EUA (\u201cSEC\u201d) relativa \u00e0 cis\u00e3o planejada; os investidores podem encontrar uma c\u00f3pia eletr\u00f4nica da declara\u00e7\u00e3o de registro (em HS Spinco, Inc.) em www.sec.gov. A transa\u00e7\u00e3o dever\u00e1 ser conclu\u00edda no primeiro trimestre de 2019. (comunicado \u00e0 imprensa da empresa)<\/p>\n<p>\u2022 A Luitpold Animal Health, uma divis\u00e3o da Luitpold Pharmaceuticals, Inc., anunciou que se tornou American Regent Animal Health, a partir de 1\u00ba de janeiro de 2019. A Luitpold Pharmaceuticals, Inc. simplificar\u00e1 suas opera\u00e7\u00f5es absorvendo suas subsidi\u00e1rias integrais, American Regent, e PharmaForce, Inc., em uma entidade corporativa a partir de 31 de dezembro de 2018. Embora Luitpold seja a entidade sobrevivente, seu nome ser\u00e1 alterado para \u201cAmerican Regent, Inc.\u201d ap\u00f3s a fus\u00e3o. (comunicado de imprensa da empresa)<\/p>\n<p>\u2022 A Vets Plus, Inc. anunciou que adquiriu a Merrick&#039;s Inc., fabricante de bolus, comprimidos, p\u00f3s e eletr\u00f3litos que atendem \u00e0 ind\u00fastria animal de produ\u00e7\u00e3o. A nova entidade, conhecida como Merrick&#039;s Animal Health, LLC, ser\u00e1 uma subsidi\u00e1ria integral da Vets Plus, Inc. Os termos financeiros n\u00e3o foram divulgados. (comunicado de imprensa da empresa)<\/p>\n<p>\u2022 A Oxyfresh anunciou o lan\u00e7amento do seu novo Pet Dental Spray. Segura para c\u00e3es e gatos, esta f\u00f3rmula exclusiva, sem sabor e sem \u00e1lcool, apresenta uma mistura patenteada de oxig\u00eanio e zinco que trabalham juntos para neutralizar compostos org\u00e2nicos que causam mau h\u00e1lito em animais de estima\u00e7\u00e3o. (Vantagem veterin\u00e1ria)<\/p>\n<p>\u2022 A PortaCheck anunciou que agora est\u00e1 distribuindo um teste de glicose na fazenda para gado leiteiro que foi incorporado ao seu sistema de monitoramento de cetonas BHBCheck Plus. (comunicado de imprensa da empresa)<\/p>\n<p>\u2022 A VetBiotek, Inc. anunciou que o UltraOtic Concentrate, para o tratamento de condi\u00e7\u00f5es \u00f3ticas em c\u00e3es e gatos, est\u00e1 agora dispon\u00edvel em frascos conta-gotas de 6 ml, f\u00e1ceis de usar. (comunicado de imprensa da empresa)<\/p>\n<p>\u2022 A empresa de private equity Sentinel Capital Partners comprou a rede de varejo especializada em animais de estima\u00e7\u00e3o Pet Supplies Plus, sediada nos EUA. Pet Supplies Plus opera atualmente 448 lojas franqueadas e corporativas em 33 estados dos EUA. Os termos financeiros n\u00e3o foram divulgados. (Animais de estima\u00e7\u00e3o globais)<\/p>\n<p>\u2022 A Wind Point Partners e a empresa do portf\u00f3lio Pestell Group anunciaram que adquiriram a Targeted Pet Treats (TPT) por meio de sua Pestell Pet Products. A TPT \u00e9 co-fabricante de tratamentos dent\u00e1rios e mastiga\u00e7\u00f5es de longa dura\u00e7\u00e3o para animais de estima\u00e7\u00e3o. Os termos financeiros n\u00e3o foram divulgados. (Neg\u00f3cio de animais de estima\u00e7\u00e3o)<\/p>\n<p>\u2022 A Sport Endurance, Inc fez um investimento de $2,2 milh\u00f5es na TruPet, empresa controladora da TruDog, uma empresa familiar de alimentos para animais de estima\u00e7\u00e3o. O investimento de $2,2 milh\u00f5es da Sport Endurance \u00e9 feito em conjunto com um grande investimento da Cambridge Companies SPG como parte da rodada da S\u00e9rie A com excesso de assinaturas de $5,2 milh\u00f5es da TruPet. (Not\u00edcias sobre produtos para animais de estima\u00e7\u00e3o)<\/p>\n<p>\u2022 A Henry Schein, Inc. e a CareCredit anunciaram a integra\u00e7\u00e3o da ferramenta de financiamento da CareCredit nas solu\u00e7\u00f5es de software de gest\u00e3o de consult\u00f3rios odontol\u00f3gicos e veterin\u00e1rios da Henry Schein. (Vantagem veterin\u00e1ria)<\/p>\n<p>\u2022 A Vetsource anunciou que fez parceria com a LifeLearn Animal Health para oferecer uma integra\u00e7\u00e3o perfeita entre a plataforma de com\u00e9rcio eletr\u00f4nico de entrega em domic\u00edlio da Vetsource e os sites veterin\u00e1rios personalizados WebDVM da LifeLearn. (PRweb)<\/p>\n<p>\u2022 CHINA A Merck anunciou que adquiriu a Zhejiang ZhengliAntoo Biotech, uma empresa privada especialista em vacinas veterin\u00e1rias com sede na China. Esta unidade \u00e9 a primeira unidade de fabrica\u00e7\u00e3o de sa\u00fade animal de propriedade integral da MSD na China. Os termos financeiros n\u00e3o foram divulgados. (Farm\u00e1cia Animal)<\/p>\n<p>\u2022 CANAD\u00c1 A Neogen Corporation anunciou que adquiriu os ativos do Delta Genomics Centre, um laborat\u00f3rio de gen\u00f4mica animal no Canad\u00e1. A Delta \u00e9 uma importante fornecedora de testes gen\u00e9ticos para associa\u00e7\u00f5es de carne bovina de ra\u00e7a pura do Canad\u00e1, produtores comerciais de gado de corte e comunidade nacional de pesquisa gen\u00f4mica. Com a aquisi\u00e7\u00e3o, as opera\u00e7\u00f5es laboratoriais da Delta ser\u00e3o renomeadas como Neogen Canada. Os termos financeiros n\u00e3o foram divulgados. (comunicado de imprensa da empresa)<\/p>\n<p>***********************************<br \/>\nNOT\u00cdCIAS DE SA\u00daDE ANIMAL<\/p>\n<p>\u2022 EUA \u2013 DOEN\u00c7A DE NEWCASTLE O Servi\u00e7o de Inspe\u00e7\u00e3o Sanit\u00e1ria Animal e Vegetal (APHIS) do USDA confirmou a presen\u00e7a da virulenta doen\u00e7a de Newcastle em um rebanho comercial de galinhas no Condado de Riverside, Calif\u00f3rnia. O APHIS disse que esta descoberta faz parte de um surto no sul da Calif\u00f3rnia que come\u00e7ou em maio de 2018 em aves dom\u00e9sticas, mas este \u00e9 o primeiro caso em aves comerciais desde 2003. (Alimentos)<\/p>\n<p>\u2022 CHINA \u2013 PSA A China detectou o v\u00edrus da peste su\u00edna africana em algumas prote\u00ednas em p\u00f3 feitas com sangue de porco e fabricadas por uma empresa sediada em Tianjin. A mat\u00e9ria-prima para as 73,93 toneladas de produtos proteicos contaminados, utilizados principalmente na alimenta\u00e7\u00e3o animal, veio de 12 matadouros de Tianjin. (Vantagem veterin\u00e1ria \u2013 Reuters)<\/p>\n<p>\u2022 EUA \u2013 USO DE ANTIMICROBIAIS A FDA anunciou que as vendas e distribui\u00e7\u00e3o dom\u00e9stica de todos os antimicrobianos de import\u00e2ncia m\u00e9dica destinados ao uso em animais produtores de alimentos diminu\u00edram em 33% entre os anos de 2016 e 2017. O relat\u00f3rio completo pode ser lido em https:\/\/www.fda. gov\/downloads\/ForIndustry\/UserFees\/AnimalDrugUserFeeActADUFA\/UCM628538.pdf. (FDA)<\/p>\n<p>\u2022 REINO UNIDO \u2013 VENDAS DE ANIMAIS DE ESTIMA\u00c7\u00c3O A Gr\u00e3-Bretanha proibiu a venda de cachorros e gatinhos a terceiros. A decis\u00e3o segue uma consulta p\u00fablica que encontrou apoio esmagador para proibir vendas a terceiros. De acordo com a nova medida, as pessoas que desejam adotar um cachorrinho ou gatinho teriam de lidar diretamente com um criador ou um centro de realojamento, em vez de lojas de animais ou outros revendedores comerciais. (AVMA SmartBrief-PBS)<\/p>\n<p>\u2022 EUA \u2013 VENDAS DE ANIMAIS DE ESTIMA\u00c7\u00c3O Um projeto de lei da Calif\u00f3rnia que pro\u00edbe a venda de c\u00e3es, gatos e coelhos criados em f\u00e1bricas em lojas de animais entrou oficialmente em vigor em 1\u00ba de janeiro. Al\u00e9m da proibi\u00e7\u00e3o, a AB 485 (Lei de Ado\u00e7\u00e3o e Resgate de Animais de Estima\u00e7\u00e3o) exigem que as lojas ofere\u00e7am c\u00e3es, gatos e coelhos de abrigos e grupos de resgate. A Calif\u00f3rnia \u00e9 o primeiro estado do pa\u00eds a promulgar uma pol\u00edtica deste tipo. (Not\u00edcias sobre produtos para animais de estima\u00e7\u00e3o)<\/p>\n<p>\u2022 CHINA \u2013 CSF Investigadores da Universidade de Jilin, na China, modificaram geneticamente porcos para serem resistentes ao v\u00edrus da peste su\u00edna cl\u00e1ssica, e estas caracter\u00edsticas de resist\u00eancia \u00e0 doen\u00e7a foram transmitidas pelo menos \u00e0 primeira gera\u00e7\u00e3o da descend\u00eancia dos porcos editados. Os pesquisadores combinaram a ferramenta de edi\u00e7\u00e3o gen\u00e9tica CRISPR-Cas9 com uma t\u00e9cnica conhecida como interfer\u00eancia de RNA (RNAi). A nova pesquisa foi publicada na revista PLOS Pathogens. (NewAtlas. com)<\/p>\n<p>************************************<br \/>\nBRAKKE CONSULTING, INC.<br \/>\nRECRUTAMENTO ATRAV\u00c9S DA SERENDIPIDADE GERENCIADA<\/p>\n<p>Op\u00e7\u00e3o 1: Publique um trabalho. Ore por uma resposta. Avalie os curr\u00edculos.<\/p>\n<p>Op\u00e7\u00e3o 2: Fa\u00e7a uma parceria com a Brakke Consulting, algu\u00e9m que est\u00e1 cuidando de voc\u00ea, trabalhando para voc\u00ea 24\/7\/52 para avaliar talentos, encontrar potencial. Trabalharemos com voc\u00ea para planejar suas necessidades, verificar continuamente quem est\u00e1 dispon\u00edvel, quem est\u00e1 pronto para uma mudan\u00e7a (n\u00e3o apenas algu\u00e9m que j\u00e1 fez o trabalho antes) e recrutar os candidatos mais promissores para sua empresa.<\/p>\n<p>Para saber mais sobre como podemos ajud\u00e1-lo a encontrar a pessoa certa para o seu cargo, entre em contato com John Mannhaupt em jackintx@aol.com ou 972-243-4033.<\/p>\n<p>www.BrakkeConsulting.com<\/p>\n<p>************************************<br \/>\nPONTO DE VISTA DA BRAKKE CONSULTORIA<\/p>\n<p>Feliz Ano Novo a todos os nossos assinantes! Esperamos que cada um de voc\u00eas tenha um 2019 de muito sucesso.<\/p>\n<p>No que se refere \u00e0s not\u00edcias da ind\u00fastria nesta primeira semana do Ano Novo, parece que as empresas financeiras continuam a interessar-se pelos mercados de sa\u00fade animal. Existem v\u00e1rias hist\u00f3rias de empresas de private equity que investem em empresas e de outra empresa que faz uma oferta p\u00fablica. O n\u00edvel de interesse parece estar um pouco voltado para o segmento de animais de companhia, mas existem algumas transa\u00e7\u00f5es na \u00e1rea de alimentos para animais.<\/p>\n<p>Uma \u00e1rea que nos chamou a aten\u00e7\u00e3o durante as f\u00e9rias e aqui referida em algumas hist\u00f3rias \u00e9 a tecnologia que se est\u00e1 a desenvolver na \u00e1rea da gen\u00e9tica como uma nova abordagem \u00e0 preven\u00e7\u00e3o de doen\u00e7as em algumas esp\u00e9cies. As modifica\u00e7\u00f5es gen\u00e9ticas de animais para a preven\u00e7\u00e3o de doen\u00e7as est\u00e3o em laborat\u00f3rio h\u00e1 muitos anos, mas agora parecem estar a passar para a fase comercial. Como os animais geneticamente resistentes poderiam impactar o neg\u00f3cio de produtos de sa\u00fade animal?<\/p>\n<p>Tenha um \u00f3timo fim de semana!<\/p>\n<p>Ron Brakke<\/p>\n<p>**********************************<br \/>\nEste boletim eletr\u00f4nico \u00e9 propriedade exclusiva da Brakke Consulting, Inc.<br \/>\nQualquer uso do conte\u00fado deste documento deve ser aprovado e devidamente atribu\u00eddo \u00e0 Brakke Consulting, Inc.<\/p>\n<p>Para obter mais informa\u00e7\u00f5es sobre os servi\u00e7os e estudos sindicados da Brakke Consulting, visite nosso website em www.brakkeconsulting.com.<\/p>","protected":false},"excerpt":{"rendered":"<p>*********************************** Not\u00edcias e notas sobre sa\u00fade animal da Brakke Consulting de 4 de janeiro de 2019 Copyright \u00a9 Brakke Consulting, Inc. Editor: Lynn Fondon DVM MBA ************************************ NAS NOT\u00cdCIAS: Not\u00edcias da Brakke Consulting Vis\u00e3o geral da ind\u00fastria de sa\u00fade animal - registre-se agora Not\u00edcias sobre ganhos de recrutamento Neogen Sanderson Farms outras not\u00edcias American Regent Animal Health Boehringer Ingelheim CareCredit Covetrus Delta Genomics Center Elanco Henry Schein (Covetrus) Henry Schein (CareCredit) LifeLearn Luitpold Sa\u00fade Animal Merck Merrick&#039;s Neogen Oxyfresh Pestell Group Pet Supplies Plus PharmaForce PortaCheck Sentinel Capital Partners Sport Endurance Targeted Pet Treats TruPet VetBiotek Vets First Choice Vetsource Vets Plus Wind Point Partners Zhejiang ZhengliAntoo Biotech *********************** ************ BRAKKE CONSULTING, INC. VIS\u00c3O GERAL DA IND\u00daSTRIA EM VMX E WVC O REGISTRO EST\u00c1 ABERTO A Brakke Consulting tem o prazer de anunciar a Vis\u00e3o Geral da Ind\u00fastria de 2019. A Vis\u00e3o Geral da Ind\u00fastria de Sa\u00fade Animal de 2019 ser\u00e1 apresentada duas vezes neste inverno \u2013 uma vez na VMX em Orlando, Fl\u00f3rida, e outra na Western Veterinary Conference em Las Vegas, Nevada. Essas datas s\u00e3o: \u2022 VMX: ter\u00e7a-feira, 22 de janeiro de 2019, das 14h \u00e0s 16h, Rosen Plaza Hotel \u2022 WVC: ter\u00e7a-feira, 19 de fevereiro de 2019, das 14h \u00e0s 16h, Four Seasons. As inscri\u00e7\u00f5es para as Vis\u00e3o Geral da Ind\u00fastria VMX e WVC j\u00e1 est\u00e3o abertas. As vagas s\u00e3o limitadas este ano, ent\u00e3o inscreva-se cedo! Para se registrar, acesse www.brakkeconsulting.com e role at\u00e9 a caixa \u201cNovidades\u201d. O pre\u00e7o \u00e9 $400 por pessoa<\/p>\n<div class=\"view-full-post\"><a href=\"https:\/\/brakkeconsulting.com\/pt\/animal-health-news-notes-for-january-4-2019\/\" class=\"view-full-post-btn\">Ver postagem completa<\/a><\/div>\n<p>;<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"class_list":["post-25934","post","type-post","status-publish","format-standard","hentry","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>News from Brakke Consulting<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/brakkeconsulting.com\/pt\/animal-health-news-notes-for-january-4-2019\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"News from Brakke Consulting\" \/>\n<meta property=\"og:description\" content=\"*********************************** Brakke Consulting&#8217;s Animal Health News &amp; Notes for January 4, 2019 Copyright \u00a9 Brakke Consulting, Inc. Editor: Lynn Fondon DVM MBA ************************************ IN THE NEWS: Brakke Consulting news Animal Health Industry Overview \u2013 register now Recruiting earnings news Neogen Sanderson Farms other news American Regent Animal Health Boehringer Ingelheim CareCredit Covetrus Delta Genomics Centre Elanco Henry Schein (Covetrus) Henry Schein (CareCredit) LifeLearn Luitpold Animal Health Merck Merrick\u2019s Neogen Oxyfresh Pestell Group Pet Supplies Plus PharmaForce PortaCheck Sentinel Capital Partners Sport Endurance Targeted Pet Treats TruPet VetBiotek Vets First Choice Vetsource Vets Plus Wind Point Partners Zhejiang ZhengliAntoo Biotech *********************************** BRAKKE CONSULTING, INC. INDUSTRY OVERVIEWS AT VMX AND WVC REGISTRATION IS NOW OPEN Brakke Consulting is pleased to announce the 2019 Industry Overview. The 2019 Animal Health Industry Overview will be presented twice this winter &#8211; once at the VMX in Orlando, Florida and once at the Western Veterinary Conference in Las Vegas, Nevada. These dates are: \u2022 VMX: Tuesday, January 22, 2019, 2:00 \u2013 4:00 pm, Rosen Plaza Hotel \u2022 WVC: Tuesday, February 19, 2019, 2:00 \u2013 4:00 pm, Four Seasons. Registration for the VMX &amp; WVC Industry Overviews is now open. Seating is limited this year, so register early! To register, go to www.brakkeconsulting.com and scroll down to the &#8220;What&#8217;s New&#8221; box. The price is $400 per personView Full Post;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/brakkeconsulting.com\/pt\/animal-health-news-notes-for-january-4-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"Brakke Consulting Website\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-09T14:57:58+00:00\" \/>\n<meta name=\"author\" content=\"Brakke Consulting\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Brakke Consulting\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/animal-health-news-notes-for-january-4-2019\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/animal-health-news-notes-for-january-4-2019\\\/\"},\"author\":{\"name\":\"Brakke Consulting\",\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/#\\\/schema\\\/person\\\/a5d2c4b59040e54bfe8f4f41f77e04d6\"},\"headline\":\"Animal Health News &#038; Notes for January 4, 2019\",\"datePublished\":\"2019-01-09T14:57:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/animal-health-news-notes-for-january-4-2019\\\/\"},\"wordCount\":1730,\"articleSection\":[\"Newsletter\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/animal-health-news-notes-for-january-4-2019\\\/\",\"url\":\"https:\\\/\\\/brakkeconsulting.com\\\/animal-health-news-notes-for-january-4-2019\\\/\",\"name\":\"News from Brakke Consulting\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/#website\"},\"datePublished\":\"2019-01-09T14:57:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/#\\\/schema\\\/person\\\/a5d2c4b59040e54bfe8f4f41f77e04d6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/animal-health-news-notes-for-january-4-2019\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/brakkeconsulting.com\\\/animal-health-news-notes-for-january-4-2019\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/animal-health-news-notes-for-january-4-2019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/brakkeconsulting.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Animal Health News &#038; Notes for January 4, 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/#website\",\"url\":\"https:\\\/\\\/brakkeconsulting.com\\\/\",\"name\":\"Brakke Consulting Website\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/brakkeconsulting.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/#\\\/schema\\\/person\\\/a5d2c4b59040e54bfe8f4f41f77e04d6\",\"name\":\"Brakke Consulting\",\"url\":\"https:\\\/\\\/brakkeconsulting.com\\\/pt\\\/author\\\/i5ww2018\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Not\u00edcias da Brakke Consulting","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/brakkeconsulting.com\/pt\/animal-health-news-notes-for-january-4-2019\/","og_locale":"pt_PT","og_type":"article","og_title":"News from Brakke Consulting","og_description":"*********************************** Brakke Consulting&#8217;s Animal Health News &amp; Notes for January 4, 2019 Copyright \u00a9 Brakke Consulting, Inc. Editor: Lynn Fondon DVM MBA ************************************ IN THE NEWS: Brakke Consulting news Animal Health Industry Overview \u2013 register now Recruiting earnings news Neogen Sanderson Farms other news American Regent Animal Health Boehringer Ingelheim CareCredit Covetrus Delta Genomics Centre Elanco Henry Schein (Covetrus) Henry Schein (CareCredit) LifeLearn Luitpold Animal Health Merck Merrick\u2019s Neogen Oxyfresh Pestell Group Pet Supplies Plus PharmaForce PortaCheck Sentinel Capital Partners Sport Endurance Targeted Pet Treats TruPet VetBiotek Vets First Choice Vetsource Vets Plus Wind Point Partners Zhejiang ZhengliAntoo Biotech *********************************** BRAKKE CONSULTING, INC. INDUSTRY OVERVIEWS AT VMX AND WVC REGISTRATION IS NOW OPEN Brakke Consulting is pleased to announce the 2019 Industry Overview. The 2019 Animal Health Industry Overview will be presented twice this winter &#8211; once at the VMX in Orlando, Florida and once at the Western Veterinary Conference in Las Vegas, Nevada. These dates are: \u2022 VMX: Tuesday, January 22, 2019, 2:00 \u2013 4:00 pm, Rosen Plaza Hotel \u2022 WVC: Tuesday, February 19, 2019, 2:00 \u2013 4:00 pm, Four Seasons. Registration for the VMX &amp; WVC Industry Overviews is now open. Seating is limited this year, so register early! To register, go to www.brakkeconsulting.com and scroll down to the &#8220;What&#8217;s New&#8221; box. The price is $400 per personView Full Post;","og_url":"https:\/\/brakkeconsulting.com\/pt\/animal-health-news-notes-for-january-4-2019\/","og_site_name":"Brakke Consulting Website","article_published_time":"2019-01-09T14:57:58+00:00","author":"Brakke Consulting","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Brakke Consulting","Tempo estimado de leitura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/brakkeconsulting.com\/animal-health-news-notes-for-january-4-2019\/#article","isPartOf":{"@id":"https:\/\/brakkeconsulting.com\/animal-health-news-notes-for-january-4-2019\/"},"author":{"name":"Brakke Consulting","@id":"https:\/\/brakkeconsulting.com\/#\/schema\/person\/a5d2c4b59040e54bfe8f4f41f77e04d6"},"headline":"Animal Health News &#038; Notes for January 4, 2019","datePublished":"2019-01-09T14:57:58+00:00","mainEntityOfPage":{"@id":"https:\/\/brakkeconsulting.com\/animal-health-news-notes-for-january-4-2019\/"},"wordCount":1730,"articleSection":["Newsletter"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/brakkeconsulting.com\/animal-health-news-notes-for-january-4-2019\/","url":"https:\/\/brakkeconsulting.com\/animal-health-news-notes-for-january-4-2019\/","name":"Not\u00edcias da Brakke Consulting","isPartOf":{"@id":"https:\/\/brakkeconsulting.com\/#website"},"datePublished":"2019-01-09T14:57:58+00:00","author":{"@id":"https:\/\/brakkeconsulting.com\/#\/schema\/person\/a5d2c4b59040e54bfe8f4f41f77e04d6"},"breadcrumb":{"@id":"https:\/\/brakkeconsulting.com\/animal-health-news-notes-for-january-4-2019\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/brakkeconsulting.com\/animal-health-news-notes-for-january-4-2019\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/brakkeconsulting.com\/animal-health-news-notes-for-january-4-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/brakkeconsulting.com\/"},{"@type":"ListItem","position":2,"name":"Animal Health News &#038; Notes for January 4, 2019"}]},{"@type":"WebSite","@id":"https:\/\/brakkeconsulting.com\/#website","url":"https:\/\/brakkeconsulting.com\/","name":"Site da Brakke Consulting","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/brakkeconsulting.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/brakkeconsulting.com\/#\/schema\/person\/a5d2c4b59040e54bfe8f4f41f77e04d6","name":"Brakke Consultoria","url":"https:\/\/brakkeconsulting.com\/pt\/author\/i5ww2018\/"}]}},"_links":{"self":[{"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/posts\/25934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/comments?post=25934"}],"version-history":[{"count":1,"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/posts\/25934\/revisions"}],"predecessor-version":[{"id":25935,"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/posts\/25934\/revisions\/25935"}],"wp:attachment":[{"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/media?parent=25934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/categories?post=25934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/tags?post=25934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}