{"id":25865,"date":"2018-11-02T07:45:47","date_gmt":"2018-11-02T13:45:47","guid":{"rendered":"\/?p=25865"},"modified":"2018-11-02T07:45:47","modified_gmt":"2018-11-02T13:45:47","slug":"animal-health-news-notes-for-november-2-2018","status":"publish","type":"post","link":"https:\/\/brakkeconsulting.com\/pt\/animal-health-news-notes-for-november-2-2018\/","title":{"rendered":"Not\u00edcias e notas sobre sa\u00fade animal de 2 de novembro de 2018"},"content":{"rendered":"<p>***********************************<br \/>\n<strong>Brakke Consulting&#039;s <\/strong><br \/>\n<strong>Not\u00edcias e notas sobre sa\u00fade animal de 2 de novembro de 2018<\/strong><br \/>\nCopyright \u00a9 Brakke Consulting, Inc.<\/p>\n<p>Editor: Lynn Fondon DVM MBA<br \/>\n************************************<br \/>\nNAS NOTICIAS:<\/p>\n<p><span style=\"text-decoration: underline;\">Novidades da Brakke Consulting<\/span><br \/>\nPesquisa de mercado<br \/>\nRelat\u00f3rio dos mercados de controle de pulgas e dirofilariose dos EUA<\/p>\n<p><span style=\"text-decoration: underline;\">not\u00edcias de ganhos<\/span><br \/>\nAlivira Sa\u00fade Animal<br \/>\nAratana Terap\u00eautica<br \/>\nHester Bioci\u00eancias<br \/>\nIDEXX<br \/>\nOrion Sa\u00fade Animal<br \/>\nZenoaq<br \/>\nZoetis<\/p>\n<p><span style=\"text-decoration: underline;\">outras not\u00edcias<\/span><br \/>\nDiagn\u00f3stico Animal Avan\u00e7ado<br \/>\nAnatara Lifesciences<br \/>\nAssis Sa\u00fade Animal<br \/>\nBoehringer Ingelheim Vetmedica<br \/>\nEquiCord-Ymas<br \/>\nEvonik<br \/>\nem ovo<br \/>\nLiiv Org\u00e2nicos<br \/>\nProdutos Monarca para Animais de Estima\u00e7\u00e3o<br \/>\nChega de pulgas, por favor<br \/>\nnutreco<br \/>\nEspecialistas em alimentos para animais de estima\u00e7\u00e3o<br \/>\nFito Sa\u00fade Animal<br \/>\nRoyal De Heus<br \/>\nSleepypod<br \/>\nTropichem<br \/>\nTrupanion<br \/>\nUniversal Agri Bisnisindo<br \/>\nVetio<br \/>\nZoetis \u2013 AAD<br \/>\nZoetis-Anatara<\/p>\n<p>***********************************<br \/>\n<strong>BRAKKE CONSULTING, INC.<\/strong><br \/>\n<strong>RELAT\u00d3RIO DE MERCADOS DE CONTROLE DE PULGAS E HEARTWORM DE 2018<\/strong><br \/>\n<strong>ENCOMENDE ANTES DE 21 DE NOVEMBRO COM DESCONTO<\/strong><\/p>\n<p>Voc\u00ea est\u00e1 por dentro das tend\u00eancias do maior segmento de mercado em sa\u00fade animal de companhia? A Brakke Consulting publicar\u00e1 em breve nosso relat\u00f3rio de 2018 sobre os mercados de controle de pulgas e dirofilariose dos EUA.<\/p>\n<p>O relat\u00f3rio inclui informa\u00e7\u00f5es valiosas sobre o mercado dos EUA para parasiticidas de pequenos animais, incluindo:<br \/>\n\u2013 Descri\u00e7\u00f5es, pre\u00e7os e vendas de produtos para os principais produtos veterin\u00e1rios contra pulgas, carrapatos e dirofilariose<br \/>\n\u2013 uma vis\u00e3o geral dos mercados de controle de pulgas veterin\u00e1rio e OTC<br \/>\n\u2013 discuss\u00e3o de novos produtos contra pulgas e carrapatos<br \/>\n\u2013 Pesquisa de 2018 com 300 veterin\u00e1rios<br \/>\n\u2013 Pesquisa de 2018 com 500 donos de animais de estima\u00e7\u00e3o<\/p>\n<p>O relat\u00f3rio sobre os mercados de controle de pulgas e dirofilariose dos EUA estar\u00e1 dispon\u00edvel por um pre\u00e7o de compra de $7.250 se solicitado at\u00e9 QUARTA-FEIRA, 21 DE NOVEMBRO e $7.750 ap\u00f3s essa data.<\/p>\n<p>Entre em contato com o Dr. Lynn Fondon em (972) 243-4033 ou <a href=\"mailto:lfondon@brakkeconsulting.com\">lfondon@brakkeconsulting.com<\/a> para encomendar o relat\u00f3rio, ou para mais informa\u00e7\u00f5es, visite nosso site.<\/p>\n<p><a href=\"https:\/\/brakkeconsulting.com\/pt\/\">www.BrakkeConsulting.com<\/a><\/p>\n<p>***********************************<br \/>\nRELEASES DE RESULTADOS DA EMPRESA<\/p>\n<p>\u2022 A Zoetis reportou os seus resultados financeiros para o terceiro trimestre de 2018. A empresa reportou receitas de $1,48 mil milh\u00f5es, um aumento de 10% em compara\u00e7\u00e3o com o terceiro trimestre de 2017 (+12%, excluindo o impacto da moeda estrangeira). A receita no segmento dos EUA foi de $757 milh\u00f5es, um aumento de 11%; a receita no segmento Internacional foi de $709 milh\u00f5es, um aumento de 8% em base reportada. O lucro l\u00edquido foi de $347 milh\u00f5es, um aumento de 16% numa base reportada. (comunicado de imprensa da empresa)<\/p>\n<p>\u2022 A IDEXX Laboratories, Inc. divulgou resultados para o terceiro trimestre de 2018. As receitas foram de $545 milh\u00f5es, um aumento de 11% em compara\u00e7\u00e3o com o mesmo per\u00edodo do ano anterior. O lucro l\u00edquido foi de $93 milh\u00f5es em compara\u00e7\u00e3o com o lucro l\u00edquido de $71 milh\u00f5es no terceiro trimestre de 2017. A receita do Companion Animal Group foi de $478 milh\u00f5es, um aumento de 12%. (comunicado de imprensa da empresa)<\/p>\n<p>\u2022 A Nippon Zenyaku Kogyo (Zenoaq) anunciou resultados financeiros para o primeiro semestre do seu ano fiscal de 2018. A empresa reportou vendas no primeiro semestre de 15.711 milh\u00f5es de ienes ($140 milh\u00f5es), um aumento de 2% nas receitas. (Farm\u00e1cia Animal)<\/p>\n<p>\u2022 Aratana Therapeutics, Inc. anunciou seus resultados financeiros do terceiro trimestre de 2018. As receitas l\u00edquidas totais foram de $21,6 milh\u00f5es em compara\u00e7\u00e3o com receitas de $6,2 milh\u00f5es no terceiro trimestre de 2017. O lucro l\u00edquido foi de $8,8 milh\u00f5es em compara\u00e7\u00e3o com um preju\u00edzo l\u00edquido de $(8,9) milh\u00f5es no trimestre compar\u00e1vel do ano anterior. A receita l\u00edquida do trimestre incluiu um marco comercial de $15,0 milh\u00f5es, que resultou em rentabilidade para o trimestre. (comunicado de imprensa da empresa)<\/p>\n<p>\u2022 A Orion Animal Health reportou resultados para o terceiro trimestre de 2018. As receitas foram de 19,2 milh\u00f5es de euros ($21,9 milh\u00f5es), um aumento de 30% em compara\u00e7\u00e3o com o terceiro trimestre de 2017. (Animal Pharm)<\/p>\n<p>\u2022 A Alivira Animal Health reportou resultados para o segundo trimestre do ano fiscal de 2019. As receitas foram de $35,9 milh\u00f5es, um aumento de 27% em compara\u00e7\u00e3o com o trimestre compar\u00e1vel do ano anterior. O lucro operacional foi de $4,6 milh\u00f5es, um aumento de 68% em rela\u00e7\u00e3o ao trimestre do ano anterior. (comunicado de imprensa da empresa)<\/p>\n<p>\u2022 A Hester Biosciences divulgou resultados para o segundo trimestre do ano fiscal de 2019. As vendas foram de INR 425 milh\u00f5es ($5,8 milh\u00f5es), um aumento de 11% em compara\u00e7\u00e3o com o trimestre compar\u00e1vel do ano anterior. O lucro l\u00edquido da empresa foi de INR 99,3 milh\u00f5es ($1,4 milh\u00e3o), um aumento de 12% ano a ano. (Farm\u00e1cia Animal)<\/p>\n<p>**********************************<br \/>\nCOMUNICADOS DE NOT\u00cdCIAS DA EMPRESA<\/p>\n<p>\u2022 A Boehringer Ingelheim Vetmedica anunciou o lan\u00e7amento do Lockout, um novo selante de tetos para preven\u00e7\u00e3o de mastite em latic\u00ednios. Lockout \u00e9 uma pasta n\u00e3o antibi\u00f3tica que cria uma barreira f\u00edsica imediata contra bact\u00e9rias causadoras de mastite durante a secagem ou em novilhas leiteiras pr\u00e9-frescas. (Farm\u00e1cia Animal)<\/p>\n<p>\u2022 A Advanced Animal Diagnostics (AAD) anunciou que celebrou um acordo de licen\u00e7a e comercializa\u00e7\u00e3o com a Zoetis para levar a tecnologia de detec\u00e7\u00e3o de mastite QScout MLD (diferencial de leuc\u00f3citos no leite) da AAD para produtores de latic\u00ednios e veterin\u00e1rios fora dos EUA. O acordo baseia-se num programa piloto de sucesso que foi lan\u00e7ado entre as duas empresas em 2016; Zoetis introduziu a tecnologia QScout MLD nos principais mercados europeus. (PRNewswire)<\/p>\n<p>\u2022 A Tropichem anunciou a unifica\u00e7\u00e3o de seus neg\u00f3cios sob a nova denomina\u00e7\u00e3o social Vetio, com efeito imediato. O novo nome foi escolhido para melhor refletir o foco exclusivo da empresa como Organiza\u00e7\u00e3o de Desenvolvimento e Fabrica\u00e7\u00e3o de Contratos para sa\u00fade animal. (comunicado de imprensa da empresa)<\/p>\n<p>\u2022 Pet Food Experts, Inc., anunciou que adquiriu os ativos operacionais da Monarch Pet Products. O neg\u00f3cio de distribui\u00e7\u00e3o da Monarch Pet Products atende varejistas independentes de animais de estima\u00e7\u00e3o na regi\u00e3o montanhosa desde 2009. Os termos financeiros n\u00e3o foram divulgados. (Neg\u00f3cio de animais de estima\u00e7\u00e3o)<\/p>\n<p>\u2022 A FDA emitiu uma carta de advert\u00eancia \u00e0 No More Fleas Please afirmando que os produtos vendidos sob a marca Queen City Animals s\u00e3o novos medicamentos para animais n\u00e3o aprovados que violam a Lei Federal de Medicamentos e Cosm\u00e9ticos para Alimentos. Os medicamentos citados inclu\u00edam c\u00e1psulas de verm\u00edfugo de t\u00eania de Praziquantel, verm\u00edfugo l\u00edquido com sabor de baunilha (pamoato de pirantel), Lufenuron e c\u00e1psulas para matar pulgas de Nitenpyram. (FDA)<\/p>\n<p>\u2022 A Phyto Animal Health anunciou que assinou um acordo de distribui\u00e7\u00e3o exclusiva com a Liiv Organics para vender seus produtos de canabidiol (CBD) nos EUA. Pelos termos do acordo, a Liiv n\u00e3o vender\u00e1 mais nenhuma outra marca de produtos para animais de estima\u00e7\u00e3o com CBD, al\u00e9m dos produtos da Phyto e de sua pr\u00f3pria linha Pet Calming Blend. (Farm\u00e1cia Animal)<\/p>\n<p>\u2022 A Nutreco anunciou que estabeleceu a divis\u00e3o de investimentos Nutreco NuFrontiers. A Nutreco NuFrontiers concentra-se em alavancar novas tecnologias, ingredientes ou formula\u00e7\u00f5es que possam beneficiar as duas divis\u00f5es da Nutreco \u2013 Trouw Nutrition (nutri\u00e7\u00e3o animal) e Skretting (ra\u00e7\u00e3o para aquicultura). (Farm\u00e1cia Animal)<\/p>\n<p>\u2022 A Assisi Animal Health, em colabora\u00e7\u00e3o com a Sleepypod, lan\u00e7ou o Assisi Loop Lounge, uma cama terap\u00eautica para animais de estima\u00e7\u00e3o alimentada pela tecnologia de campo eletromagn\u00e9tico pulsado direcionado (tPEMFTM) do Assisi Loop. (PRNewswire)<\/p>\n<p>\u2022 Trupanion anunciou a inscri\u00e7\u00e3o do seu 500.000\u00ba animal de estima\u00e7\u00e3o. O marco representa um salto de 18% em menos de 11 meses. (Hoje Neg\u00f3cio Veterin\u00e1rio)<\/p>\n<p>\u2022 AUSTR\u00c1LIA Anatara Lifesciences anunciou que recebeu aprova\u00e7\u00e3o da Autoridade Australiana de Pesticidas e Medicamentos Veterin\u00e1rios (APVMA) para o uso de Detach, uma alternativa antibi\u00f3tica desenvolvida para ajudar no controle de diarr\u00e9ia em leit\u00f5es desmamados a partir das tr\u00eas semanas de idade e para ajudar a aumentar a capacidade de sobreviv\u00eancia de limpeza de leit\u00f5es pr\u00e9-desmame. Anatara possui um acordo mundial exclusivo com Zoetis para Detach. (Farm\u00e1cia Animal)<\/p>\n<p>\u2022 INDON\u00c9SIA A Royal De Heus anunciou a aquisi\u00e7\u00e3o da Universal Agri Bisnisindo, uma empresa privada de alimenta\u00e7\u00e3o animal na Indon\u00e9sia. A Universal tem um volume total de vendas anuais de 300 mil toneladas de ra\u00e7\u00e3o para aves, peixes e camar\u00f5es. Os termos financeiros n\u00e3o foram divulgados. (Farm\u00e1cia Animal)<\/p>\n<p>\u2022 HOLANDA A Evonik anunciou que investiu na start-up de biotecnologia In Ovo por meio de sua unidade de capital de risco e agora det\u00e9m uma participa\u00e7\u00e3o minorit\u00e1ria na empresa. A In Ovo desenvolveu um m\u00e9todo para determinar o sexo em ovos de aves que \u00e9 particularmente r\u00e1pido e confi\u00e1vel e pode ser facilmente integrado ao fluxo de trabalho de grandes incubat\u00f3rios. O primeiro produto comercial dever\u00e1 ser lan\u00e7ado no mercado em 2020. (Ra\u00e7\u00f5es Alimentares)<\/p>\n<p>\u2022 UE O Comit\u00e9 de Medicamentos para Uso Veterin\u00e1rio (CVMP) da Ag\u00eancia Europeia de Medicamentos adoptou um parecer negativo para a aprova\u00e7\u00e3o do HorStem, uma suspens\u00e3o inject\u00e1vel baseada em c\u00e9lulas estaminais desenvolvida pela empresa espanhola EquiCord-Ymas para o tratamento da claudica\u00e7\u00e3o em cavalos. Os fundamentos para o parecer negativo est\u00e3o relacionados com quest\u00f5es de qualidade e efic\u00e1cia. (Farm\u00e1cia Animal)<\/p>\n<p>***********************************<br \/>\nNOT\u00cdCIAS DE SA\u00daDE ANIMAL<\/p>\n<p>\u2022 EUA \u2013 TB BOVINA O Departamento de Agricultura, Com\u00e9rcio e Protec\u00e7\u00e3o do Consumidor de Wisconsin confirmou que um rebanho leiteiro no Condado de Dane, Wisconsin, testou positivo para tuberculose bovina (TB) depois de inspectores de carne identificarem uma carca\u00e7a durante uma inspec\u00e7\u00e3o de rotina no abate. O rebanho de origem foi colocado em quarentena. Wisconsin foi certificado como livre de TB desde 1980 e, com uma investiga\u00e7\u00e3o completa e conten\u00e7\u00e3o do surto, Wisconsin manter\u00e1 seu status de livre de TB junto ao USDA. (Alimentos)<\/p>\n<p>\u2022 EUA \u2013 INOVA\u00c7\u00c3O EM BIOTECNOLOGIA A FDA anunciou o Plano de A\u00e7\u00e3o para Inova\u00e7\u00e3o em Biotecnologia Vegetal e Animal para delinear as principais prioridades que a ag\u00eancia buscar\u00e1 para apoiar a inova\u00e7\u00e3o em biotecnologia vegetal e animal, ao mesmo tempo em que avan\u00e7a a miss\u00e3o de sa\u00fade p\u00fablica da ag\u00eancia. Para ler sobre o Plano de A\u00e7\u00e3o, acesse <a href=\"https:\/\/www.fda.gov\/AnimalVeterinary\/NewsEvents\/CVMUpdates\/ucm624490.htm\">https:\/\/www.fda.gov\/AnimalVeterinary\/NewsEvents\/CVMUpdates\/ucm624490.htm<\/a> . (FDA)<\/p>\n<p>\u2022 EUA \u2013 DIRETRIZES DE ALIMENTA\u00c7\u00c3O DE GATOS A Associa\u00e7\u00e3o Americana de Praticantes de Felinos anunciou a publica\u00e7\u00e3o da Declara\u00e7\u00e3o de Consenso, Programas de Alimenta\u00e7\u00e3o Felina: Abordando Necessidades Comportamentais para Melhorar a Sa\u00fade e o Bem-Estar Felinos, no Journal of Feline Medicine and Surgery (JFMS). A Declara\u00e7\u00e3o de Consenso pode ser lida em <a href=\"https:\/\/www.catvets.com\/guidelines\/practice-guidelines\/how-to-feed\">https:\/\/www.catvets.com\/guidelines\/practice-guidelines\/how-to-feed<\/a> . (comunicado de imprensa da associa\u00e7\u00e3o)<\/p>\n<p>************************************<br \/>\n<strong>BRAKKE CONSULTING, INC.<\/strong><br \/>\n<strong>OLHE ANTES DE PULAR<\/p>\n<p><\/strong>Conte com a Brakke Consulting para atender as necessidades de pesquisa de mercado da sua empresa, sejam elas:<\/p>\n<p>\u2022 Avaliar a viabilidade de um novo produto ou tecnologia<br \/>\n\u2022 Identificar as opini\u00f5es e tend\u00eancias de veterin\u00e1rios, donos de animais ou produtores<br \/>\n\u2022 Determinar o mercado atual de produtos<\/p>\n<p>Com nosso banco de dados interno de veterin\u00e1rios e a capacidade de personalizar pesquisas de uma ampla variedade de p\u00fablicos-alvo, fornecemos informa\u00e7\u00f5es confi\u00e1veis sobre esse setor exclusivo. Tamb\u00e9m produzimos relat\u00f3rios para v\u00e1rios clientes em v\u00e1rias \u00e1reas de mercado de sa\u00fade animal de grande interesse. Para obter mais informa\u00e7\u00f5es, consulte nosso site ou ligue para nosso escrit\u00f3rio em Dallas em 972-243-4033.<\/p>\n<p><a href=\"http:\/\/www.BrakkeConsulting.com\">www.BrakkeConsulting.com<\/a><\/p>\n<p>************************************<br \/>\nPONTO DE VISTA DA BRAKKE CONSULTORIA<\/p>\n<p>Com base nos resultados do terceiro trimestre de duas das principais empresas de sa\u00fade animal, parece que maior pode, na verdade, ser melhor quando se trata de aumentar as receitas. Tr\u00eas das maiores empresas de sa\u00fade animal reportaram um crescimento de dois d\u00edgitos no ano, o que, na nossa opini\u00e3o, \u00e9 impressionante. Frequentemente ouvimos que as empresas maiores n\u00e3o respondem t\u00e3o bem aos clientes e enfrentam desafios para aumentar as receitas numa base percentual a partir desta base de receitas maior. \u00c9 a amplitude das linhas que cada empresa oferece aos consumidores e produtores, ou \u00e9 a massa cr\u00edtica que permite uma maior sensibiliza\u00e7\u00e3o e alavancagem de fundos de marketing? Seja qual for a resposta, parece estar funcionando com bastante sucesso em 2018.<\/p>\n<p>Tamb\u00e9m ouvimos dizer que algumas destas mesmas empresas est\u00e3o a criar metas de crescimento desafiantes para 2019 e al\u00e9m. Est\u00e1 a tornar-se mais \u00f3bvio que a massa cr\u00edtica \u00e9 a chave para poder suportar os custos regulamentares de produtos novos e atuais. O registo de novos produtos e tecnologias est\u00e1 a tornar-se uma barreira \u00e0 entrada de pequenas e m\u00e9dias empresas.<\/p>\n<p>Tenha um \u00f3timo fim de semana!<\/p>\n<p>Ron Brakke<\/p>\n<p>**********************************<br \/>\nProblemas para visualizar esta newsletter? Voc\u00ea pode visualiz\u00e1-lo online em www.BrakkeConsulting.com<\/p>\n<p>Este boletim eletr\u00f4nico \u00e9 propriedade exclusiva da Brakke Consulting, Inc.<br \/>\nQualquer uso do conte\u00fado deste documento deve ser aprovado e devidamente atribu\u00eddo \u00e0 Brakke Consulting, Inc.<\/p>\n<p>Para obter mais informa\u00e7\u00f5es sobre os servi\u00e7os e estudos sindicados da Brakke Consulting, visite nosso website em www.brakkeconsulting.com.<\/p>\n<p>Brakke Consulting, Inc.<br \/>\n12005 Ford Rd., Suite 530<br \/>\nDallas, TX 75234 EUA<\/p>","protected":false},"excerpt":{"rendered":"<p>*********************************** Not\u00edcias e notas sobre sa\u00fade animal da Brakke Consulting de 2 de novembro de 2018 Copyright \u00a9 Brakke Consulting, Inc. Editor: Lynn Fondon DVM MBA ************************************ NAS NOT\u00cdCIAS: Brakke Consulting not\u00edcias Pesquisa de mercado US Flea Control &amp; Heartworm Markets relatam not\u00edcias de ganhos Alivira Sa\u00fade Animal Aratana Therapeutics Hester Biosciences IDEXX Orion Sa\u00fade Animal Zenoaq Zoetis outras not\u00edcias Diagn\u00f3stico Animal Avan\u00e7ado Anatara Lifesciences Assis Sa\u00fade Animal Boehringer Ingelheim Vetmedica EquiCord-Ymas Evonik In Ovo Liiv Organics Monarch Pet Produtos Chega de pulgas, por favor Nutreco Pet Food Experts Phyto Animal Health Royal De Heus Sleepypod Tropichem Trupanion Universal Agri Bisnisindo Vetio Zoetis \u2013 AAD Zoetis \u2013 Anatara ********************** ************* BRAKKE CONSULTING, INC. 2018 RELAT\u00d3RIO DE CONTROLE DE PULGAS E MERCADOS DE HEARTWORM DOS EUA PR\u00c9-ENCOMENDA ANTES DE 21 DE NOVEMBRO PARA DESCONTO Voc\u00ea est\u00e1 por dentro das tend\u00eancias no maior segmento de mercado em sa\u00fade de animais de companhia? A Brakke Consulting publicar\u00e1 em breve nosso relat\u00f3rio de 2018 sobre os mercados de controle de pulgas e dirofilariose dos EUA. O relat\u00f3rio inclui informa\u00e7\u00f5es valiosas sobre o mercado dos EUA para parasiticidas para pequenos animais, incluindo: \u2013 Descri\u00e7\u00f5es de produtos, pre\u00e7os e vendas para os principais produtos veterin\u00e1rios contra pulgas, carrapatos e dirofilariose \u2013 uma vis\u00e3o geral dos mercados veterin\u00e1rios e de controle de pulgas OTC \u2013 discuss\u00e3o sobre novas pulgas e produtos contra carrapatos \u2013 pesquisa de 2018 com 300 veterin\u00e1rios \u2013 pesquisa de 2018 com 500 donos de animais de estima\u00e7\u00e3o O relat\u00f3rio sobre a pulga dos EUA<\/p>\n<div class=\"view-full-post\"><a href=\"https:\/\/brakkeconsulting.com\/pt\/animal-health-news-notes-for-november-2-2018\/\" class=\"view-full-post-btn\">Ver postagem completa<\/a><\/div>\n<p>;<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"class_list":["post-25865","post","type-post","status-publish","format-standard","hentry","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>News from Brakke Consulting<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/brakkeconsulting.com\/pt\/animal-health-news-notes-for-november-2-2018\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"News from Brakke Consulting\" \/>\n<meta property=\"og:description\" content=\"*********************************** Brakke Consulting&#8217;s Animal Health News &amp; Notes for November 2, 2018 Copyright \u00a9 Brakke Consulting, Inc. Editor: Lynn Fondon DVM MBA ************************************ IN THE NEWS: Brakke Consulting news Market research US Flea Control &amp; Heartworm Markets report earnings news Alivira Animal Health Aratana Therapeutics Hester Biosciences IDEXX Orion Animal Health Zenoaq Zoetis other news Advanced Animal Diagnostics Anatara Lifesciences Assisi Animal Health Boehringer Ingelheim Vetmedica EquiCord-Ymas Evonik In Ovo Liiv Organics Monarch Pet Products No More Fleas Please Nutreco Pet Food Experts Phyto Animal Health Royal De Heus Sleepypod Tropichem Trupanion Universal Agri Bisnisindo Vetio Zoetis &#8211; AAD Zoetis &#8211; Anatara *********************************** BRAKKE CONSULTING, INC. 2018 US FLEA CONTROL AND HEARTWORM MARKETS REPORT PREORDER BEFORE NOVEMBER 21 FOR DISCOUNT Are you on top of the trends in the largest market segment in companion animal health? Brakke Consulting will soon be publishing our 2018 report on the US Flea Control and Heartworm Markets. The report includes valuable information on the US market for small animal parasiticides including: &#8211; Product descriptions, prices, and sales for the leading veterinary flea, tick and heartworm products &#8211; an overview of the veterinary and OTC flea control markets &#8211; discussion of new flea and tick products &#8211; 2018 survey of 300 veterinarians &#8211; 2018 survey of 500 pet owners The report on the US FleaView Full Post;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/brakkeconsulting.com\/pt\/animal-health-news-notes-for-november-2-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"Brakke Consulting Website\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-02T13:45:47+00:00\" \/>\n<meta name=\"author\" content=\"Brakke Consulting\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Brakke Consulting\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/ja\\\/animal-health-news-notes-for-november-2-2018\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/ja\\\/animal-health-news-notes-for-november-2-2018\\\/\"},\"author\":{\"name\":\"Brakke Consulting\",\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/ja\\\/#\\\/schema\\\/person\\\/a5d2c4b59040e54bfe8f4f41f77e04d6\"},\"headline\":\"Animal Health News &#038; Notes for November 2, 2018\",\"datePublished\":\"2018-11-02T13:45:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/ja\\\/animal-health-news-notes-for-november-2-2018\\\/\"},\"wordCount\":1733,\"articleSection\":[\"Newsletter\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/ja\\\/animal-health-news-notes-for-november-2-2018\\\/\",\"url\":\"https:\\\/\\\/brakkeconsulting.com\\\/ja\\\/animal-health-news-notes-for-november-2-2018\\\/\",\"name\":\"News from Brakke Consulting\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/ja\\\/#website\"},\"datePublished\":\"2018-11-02T13:45:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/ja\\\/#\\\/schema\\\/person\\\/a5d2c4b59040e54bfe8f4f41f77e04d6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/ja\\\/animal-health-news-notes-for-november-2-2018\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/brakkeconsulting.com\\\/ja\\\/animal-health-news-notes-for-november-2-2018\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/ja\\\/animal-health-news-notes-for-november-2-2018\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/brakkeconsulting.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Animal Health News &#038; Notes for November 2, 2018\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/ja\\\/#website\",\"url\":\"https:\\\/\\\/brakkeconsulting.com\\\/ja\\\/\",\"name\":\"Brakke Consulting Website\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/brakkeconsulting.com\\\/ja\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/ja\\\/#\\\/schema\\\/person\\\/a5d2c4b59040e54bfe8f4f41f77e04d6\",\"name\":\"Brakke Consulting\",\"url\":\"https:\\\/\\\/brakkeconsulting.com\\\/pt\\\/author\\\/i5ww2018\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Not\u00edcias da Brakke Consulting","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/brakkeconsulting.com\/pt\/animal-health-news-notes-for-november-2-2018\/","og_locale":"pt_PT","og_type":"article","og_title":"News from Brakke Consulting","og_description":"*********************************** Brakke Consulting&#8217;s Animal Health News &amp; Notes for November 2, 2018 Copyright \u00a9 Brakke Consulting, Inc. Editor: Lynn Fondon DVM MBA ************************************ IN THE NEWS: Brakke Consulting news Market research US Flea Control &amp; Heartworm Markets report earnings news Alivira Animal Health Aratana Therapeutics Hester Biosciences IDEXX Orion Animal Health Zenoaq Zoetis other news Advanced Animal Diagnostics Anatara Lifesciences Assisi Animal Health Boehringer Ingelheim Vetmedica EquiCord-Ymas Evonik In Ovo Liiv Organics Monarch Pet Products No More Fleas Please Nutreco Pet Food Experts Phyto Animal Health Royal De Heus Sleepypod Tropichem Trupanion Universal Agri Bisnisindo Vetio Zoetis &#8211; AAD Zoetis &#8211; Anatara *********************************** BRAKKE CONSULTING, INC. 2018 US FLEA CONTROL AND HEARTWORM MARKETS REPORT PREORDER BEFORE NOVEMBER 21 FOR DISCOUNT Are you on top of the trends in the largest market segment in companion animal health? Brakke Consulting will soon be publishing our 2018 report on the US Flea Control and Heartworm Markets. The report includes valuable information on the US market for small animal parasiticides including: &#8211; Product descriptions, prices, and sales for the leading veterinary flea, tick and heartworm products &#8211; an overview of the veterinary and OTC flea control markets &#8211; discussion of new flea and tick products &#8211; 2018 survey of 300 veterinarians &#8211; 2018 survey of 500 pet owners The report on the US FleaView Full Post;","og_url":"https:\/\/brakkeconsulting.com\/pt\/animal-health-news-notes-for-november-2-2018\/","og_site_name":"Brakke Consulting Website","article_published_time":"2018-11-02T13:45:47+00:00","author":"Brakke Consulting","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Brakke Consulting","Tempo estimado de leitura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/brakkeconsulting.com\/ja\/animal-health-news-notes-for-november-2-2018\/#article","isPartOf":{"@id":"https:\/\/brakkeconsulting.com\/ja\/animal-health-news-notes-for-november-2-2018\/"},"author":{"name":"Brakke Consulting","@id":"https:\/\/brakkeconsulting.com\/ja\/#\/schema\/person\/a5d2c4b59040e54bfe8f4f41f77e04d6"},"headline":"Animal Health News &#038; Notes for November 2, 2018","datePublished":"2018-11-02T13:45:47+00:00","mainEntityOfPage":{"@id":"https:\/\/brakkeconsulting.com\/ja\/animal-health-news-notes-for-november-2-2018\/"},"wordCount":1733,"articleSection":["Newsletter"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/brakkeconsulting.com\/ja\/animal-health-news-notes-for-november-2-2018\/","url":"https:\/\/brakkeconsulting.com\/ja\/animal-health-news-notes-for-november-2-2018\/","name":"Not\u00edcias da Brakke Consulting","isPartOf":{"@id":"https:\/\/brakkeconsulting.com\/ja\/#website"},"datePublished":"2018-11-02T13:45:47+00:00","author":{"@id":"https:\/\/brakkeconsulting.com\/ja\/#\/schema\/person\/a5d2c4b59040e54bfe8f4f41f77e04d6"},"breadcrumb":{"@id":"https:\/\/brakkeconsulting.com\/ja\/animal-health-news-notes-for-november-2-2018\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/brakkeconsulting.com\/ja\/animal-health-news-notes-for-november-2-2018\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/brakkeconsulting.com\/ja\/animal-health-news-notes-for-november-2-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/brakkeconsulting.com\/"},{"@type":"ListItem","position":2,"name":"Animal Health News &#038; Notes for November 2, 2018"}]},{"@type":"WebSite","@id":"https:\/\/brakkeconsulting.com\/ja\/#website","url":"https:\/\/brakkeconsulting.com\/ja\/","name":"Site da Brakke Consulting","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/brakkeconsulting.com\/ja\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/brakkeconsulting.com\/ja\/#\/schema\/person\/a5d2c4b59040e54bfe8f4f41f77e04d6","name":"Brakke Consultoria","url":"https:\/\/brakkeconsulting.com\/pt\/author\/i5ww2018\/"}]}},"_links":{"self":[{"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/posts\/25865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/comments?post=25865"}],"version-history":[{"count":1,"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/posts\/25865\/revisions"}],"predecessor-version":[{"id":25866,"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/posts\/25865\/revisions\/25866"}],"wp:attachment":[{"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/media?parent=25865"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/categories?post=25865"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/tags?post=25865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}