{"id":25847,"date":"2018-10-05T07:36:20","date_gmt":"2018-10-05T13:36:20","guid":{"rendered":"\/?p=25847"},"modified":"2018-10-12T08:15:04","modified_gmt":"2018-10-12T14:15:04","slug":"animal-health-news-notes-for-october-5-2018","status":"publish","type":"post","link":"https:\/\/brakkeconsulting.com\/pt\/animal-health-news-notes-for-october-5-2018\/","title":{"rendered":"Not\u00edcias e notas de sa\u00fade animal de 5 de outubro de 2018"},"content":{"rendered":"<p>***********************************<br \/>\n<strong>Brakke Consulting&#039;s <\/strong><br \/>\n<strong>Not\u00edcias e notas de sa\u00fade animal de 5 de outubro de 2018<\/strong><br \/>\nCopyright \u00a9 Brakke Consulting, Inc.<\/p>\n<p>Editor: Lynn Fondon DVM MBA<br \/>\n************************************<br \/>\nNAS NOTICIAS:<\/p>\n<p><span style=\"text-decoration: underline;\">Novidades da Brakke Consulting<\/span><br \/>\nAssist\u00eancia \u00e0 Transa\u00e7\u00e3o<\/p>\n<p><span style=\"text-decoration: underline;\">outras not\u00edcias<\/span><br \/>\nAgriLabs<br \/>\nAlivira Sa\u00fade Animal<br \/>\nAmazonas<br \/>\nAssocia\u00e7\u00e3o Americana de Hospitais de Animais<br \/>\nvanguarda americana<br \/>\nAmeri-Pac<br \/>\nrefer\u00eancia<br \/>\nbiovet<br \/>\nBoehringer Ingelheim<br \/>\ndatamars<br \/>\nEurophartech<br \/>\nHuvepharma<br \/>\nIshihara Sangyo Kaisha<br \/>\nInd\u00fastrias Kemin<br \/>\nManna Pro<br \/>\nMicronutrientes EUA<br \/>\nMS Biotech Participa\u00e7\u00f5es<br \/>\nNAVC<br \/>\nPetIQ<br \/>\nProdutos de resposta<br \/>\nRoyal Canin<br \/>\nTeste Verdadeiro<br \/>\nTyraTech<br \/>\nVetFolio<br \/>\nVidentis<br \/>\nVirbac<br \/>\nVontade Rx<br \/>\nAlimenta\u00e7\u00e3o Wilbur-Ellis<br \/>\nZENOAQ<\/p>\n<p>***********************************<br \/>\n<strong>BRAKKE CONSULTING, INC.<\/strong><br \/>\n<strong>ASSIST\u00caNCIA \u00c0 TRANSA\u00c7\u00c3O<\/strong><\/p>\n<p>Deixe a Brakke Consulting fornecer assist\u00eancia para todas as suas transa\u00e7\u00f5es.<\/p>\n<p>A Brakke Consulting tem sido o localizador de registro, agente de registro ou consultor para uma s\u00e9rie de projetos conclu\u00eddos com sucesso. Auxiliamos nas avalia\u00e7\u00f5es e fornecemos a devida dilig\u00eancia em transa\u00e7\u00f5es confidenciais, al\u00e9m de oferecer consultoria executiva em v\u00e1rias transa\u00e7\u00f5es em potencial.<\/p>\n<p>A Brakke Consulting tem experi\u00eancia, vis\u00e3o, capacidade e contatos para fornecer aos clientes servi\u00e7os da mais alta qualidade nos mercados de sa\u00fade animal, pet, veterin\u00e1rio e produtos qu\u00edmicos especiais. Entre em contato com qualquer um de nossos escrit\u00f3rios para uma consulta confidencial.<\/p>\n<p><a href=\"https:\/\/brakkeconsulting.com\/pt\/\">www.BrakkeConsulting.com<\/a><\/p>\n<p>**********************************<br \/>\nCOMUNICADOS DE NOT\u00cdCIAS DA EMPRESA<\/p>\n<p>\u2022 A Boehringer Ingelheim Animal Health anunciou o lan\u00e7amento do Semintra (telmisartan solu\u00e7\u00e3o oral), a primeira solu\u00e7\u00e3o l\u00edquida aprovada pela FDA para o controle da hipertens\u00e3o sist\u00eamica felina. (comunicado de imprensa da empresa)<\/p>\n<p>\u2022 A Huvepharma anunciou o lan\u00e7amento de uma vacina com licen\u00e7a condicional para a preven\u00e7\u00e3o da conjuntivite causada por Moraxella bovoculi em bovinos. A nova Bacterina Moraxella bovoculi oferece prote\u00e7\u00e3o superior com oito isolados espec\u00edficos e um adjuvante de f\u00e1cil aplica\u00e7\u00e3o por seringa. A vacina ser\u00e1 apoiada pela AgriLabs, uma empresa da Huvepharma. (comunicado de imprensa da empresa)<\/p>\n<p>\u2022 A Manna Pro anunciou a aquisi\u00e7\u00e3o da Rocking S. Inc., dba como Response Products, fabricantes do Cetyl M. Os termos financeiros n\u00e3o foram divulgados. (Not\u00edcias de produtos para animais de estima\u00e7\u00e3o)<\/p>\n<p>\u2022 A Royal Canin anunciou o lan\u00e7amento do Pill Assist para ajudar os donos de animais de estima\u00e7\u00e3o a administrar medicamentos usando uma guloseima para disfar\u00e7ar a p\u00edlula. O Pill Assist pode ser usado em conjunto com v\u00e1rias dietas veterin\u00e1rias exclusivas da Royal Canin sem comprometer sua efic\u00e1cia e est\u00e1 dispon\u00edvel em cl\u00ednicas veterin\u00e1rias. (PRNewswire)<\/p>\n<p>\u2022 A Kemin Industries e a Micronutrients USA anunciaram uma parceria para lan\u00e7ar o IntelliBond VITAL 5 CR, um novo pacote de aditivo mineral para gado. O IntelliBond VITAL 5 CR cont\u00e9m seis oligoelementos essenciais \u2013 zinco, mangan\u00eas, cobre, cobalto, iodo e KemTRACE Chromium da Kemin, que \u00e9 a primeira fonte de propionato de cromo aprovada pela FDA. (Farm\u00e1cia Animal)<\/p>\n<p>\u2022 A Wilbur-Ellis Feed LLC anunciou a aquisi\u00e7\u00e3o dos ativos da Ameri-Pac Inc., fabricante de produtos especializados em nutri\u00e7\u00e3o e sa\u00fade animal para as ind\u00fastrias de alimentos para animais de estima\u00e7\u00e3o, animais de companhia, pecu\u00e1ria e aquicultura. Os termos financeiros n\u00e3o foram divulgados. (alimentos)<\/p>\n<p>\u2022 A Paine Schwartz Partners, LLC anunciou que fez um investimento estrat\u00e9gico na MS Biotech Holdings, Inc., fornecedora de produtos naturais propriet\u00e1rios que maximizam o desempenho e aumentam a lucratividade nos mercados de confinamento de bovinos e latic\u00ednios. Os termos financeiros n\u00e3o foram divulgados. (PRNewswire)<\/p>\n<p>\u2022 A VolitionRx Ltd. anunciou que est\u00e1 entrando no mercado veterin\u00e1rio ap\u00f3s resultados preliminares \u201cmuito encorajadores\u201d de um estudo usando seus exames de sangue NuQ para diagn\u00f3stico de c\u00e2ncer canino. (Not\u00edcias da Pr\u00e1tica Veterin\u00e1ria)<\/p>\n<p>\u2022 A Amazon ampliou a gama de ra\u00e7\u00f5es exclusivas para c\u00e3es e outros produtos para animais vendidos no site de varejo na Internet, adicionando mais duas marcas de ra\u00e7\u00e3o para c\u00e3es: a ra\u00e7\u00e3o seca Solimo, a um pre\u00e7o mais baixo que o Wag, e a ra\u00e7\u00e3o \u00famida Simply Perfection, a um pre\u00e7o mais alto. Wag \u00e9 a ra\u00e7\u00e3o seca para c\u00e3es de marca pr\u00f3pria que a Amazon lan\u00e7ou em maio. (Ind\u00fastria de Alimentos para Animais de Estima\u00e7\u00e3o)<\/p>\n<p>\u2022 A FDB (First Databank, Inc.), fornecedora l\u00edder de conhecimento sobre medicamentos e dispositivos m\u00e9dicos, e a PetIQ, Inc. anunciaram sua parceria para o pr\u00f3ximo lan\u00e7amento do primeiro banco de dados de medicamentos veterin\u00e1rios da ind\u00fastria para uma variedade de esp\u00e9cies de animais de estima\u00e7\u00e3o. O banco de dados veterin\u00e1rio fornecer\u00e1 informa\u00e7\u00f5es codificadas e atualizadas sobre medicamentos para animais de estima\u00e7\u00e3o, estruturadas para f\u00e1cil integra\u00e7\u00e3o em sistemas de farm\u00e1cias e fluxos de trabalho existentes para apoiar o com\u00e9rcio de medicamentos para animais de estima\u00e7\u00e3o e a distribui\u00e7\u00e3o de medicamentos. (fio comercial)<\/p>\n<p>\u2022 A Comunidade Veterin\u00e1ria da Am\u00e9rica do Norte (NAVC) anunciou que recuperou a propriedade de sua plataforma de aprendizado on-line, VetFolio. Originalmente fundada em 2014 pelo NAVC, a VetFolio tem sido propriedade conjunta do NAVC e da American Animal Hospital Association (AAHA) nos \u00faltimos tr\u00eas anos e meio. O VetFolio continuar\u00e1 a ser um benef\u00edcio valioso para os membros credenciados pela AAHA. (comunicado de imprensa da empresa)<\/p>\n<p>\u2022 A Virbac da UE anunciou que a Ag\u00eancia Europeia de Medicamentos concedeu uma imunidade de 3 anos para o componente de leucemia felina das vacinas Leucogen e Leucofeligen, quando administradas ap\u00f3s o ciclo prim\u00e1rio e o primeiro refor\u00e7o anual. Leucogen \u00e9 uma vacina de subunidade recombinante contendo ant\u00edgeno de envelope p45 FeLV purificado; Leucofeligen \u00e9 uma vacina combinada para FeLV, rinotraque\u00edte, caliciv\u00edrus e v\u00edrus da panleucopenia felina. (vetsurgeon.org)<\/p>\n<p>\u2022 JAP\u00c3O Ishihara Sangyo Kaisha, LTD anunciou que BRENDA (fuzapladib hidrato de s\u00f3dio) foi aprovado pelo Minist\u00e9rio da Agricultura, Silvicultura e Pesca do Jap\u00e3o (JMAFF) para uso por veterin\u00e1rios no Jap\u00e3o para a redu\u00e7\u00e3o dos sinais cl\u00ednicos associados \u00e0 pancreatite aguda em c\u00e3es. BRENDA ser\u00e1 distribu\u00eddo no Jap\u00e3o pela ZENOAQ (Nippon Zenyaku Kogyo Co., LTD.). A ISK tamb\u00e9m est\u00e1 buscando a aprova\u00e7\u00e3o do FDA nos Estados Unidos. (comunicado de imprensa da empresa)<\/p>\n<p>\u2022 A Alivira Animal Health da UE anunciou que obteve a aprova\u00e7\u00e3o do CEP para o Febantel, um anti-helm\u00edntico de amplo espectro usado para o tratamento e controle de lombrigas gastrointestinais, vermes pulmonares e t\u00eanias. (comunicado de imprensa da empresa)<\/p>\n<p>\u2022 NOVA ZEL\u00c2NDIA A Datamars anunciou a conclus\u00e3o da aquisi\u00e7\u00e3o de uma parte importante dos neg\u00f3cios da Tru-Test ap\u00f3s receber autoriza\u00e7\u00e3o do Escrit\u00f3rio de Investimentos no Exterior da Nova Zel\u00e2ndia. A aquisi\u00e7\u00e3o inclui a divis\u00e3o Tru-Test Retail Solutions e a linha de produtos Milk Meters, juntamente com a marca Tru-Test e ativos de marcas associadas. (scoop.co.nz)<\/p>\n<p>\u2022 CANAD\u00c1 Biovet anunciou o lan\u00e7amento de um novo ensaio qPCR duplex para a detec\u00e7\u00e3o simult\u00e2nea de Circov\u00edrus su\u00edno tipo 2 (PCV2) e tipo 3 (PCV3). O PCV3 foi identificado nos EUA em 2016 e foi confirmado em v\u00e1rios outros pa\u00edses, incluindo China, Canad\u00e1 e v\u00e1rios pa\u00edses europeus. (site da companhia)<\/p>\n<p>\u2022 NORUEGA A Aquaculture Health Specialist Benchmark concordou em adquirir todo o capital social emitido da Videntis por um valor inicial de GBP 150.000 ($172.000) e um valor total de at\u00e9 GBP 300.000 ($345.000). A Videntis fornece tecnologia para aquicultura e agricultura projetada para permitir a captura de dados em tempo real e feedback sobre efici\u00eancia alimentar, bem-estar e qualidade do produto. (Farm\u00e1cia Animal)<\/p>\n<p>\u2022 A UK American Vanguard anunciou que vai adquirir as a\u00e7\u00f5es em circula\u00e7\u00e3o da TyraTech que ainda n\u00e3o possu\u00eda por 3,15p ($0,04) cada, um pr\u00eamio de 40-50% sobre o pre\u00e7o m\u00e9dio de negocia\u00e7\u00e3o da TyraTech nas \u00faltimas semanas. A TyraTech teve perdas de $4,35 milh\u00f5es no final de 2017 e ativos totais de cerca de $16,3 milh\u00f5es. (Farm\u00e1cia Animal)<\/p>\n<p>\u2022 EU Europhartech anunciou que lan\u00e7ar\u00e1 uma linha de mastiga\u00e7\u00e3o suave projetada para a produ\u00e7\u00e3o de medicamentos para sa\u00fade animal e suplementos alimentares. A Europhartech planeja desenvolver a linha como um servi\u00e7o especializado, desde a formula\u00e7\u00e3o at\u00e9 o produto acabado. (Farm\u00e1cia Animal)<\/p>\n<p>***********************************<br \/>\nNOT\u00cdCIAS DE SA\u00daDE ANIMAL<\/p>\n<p>\u2022 AM\u00c9RICA DO NORTE \u2013 NAFTA Os Estados Unidos, Canad\u00e1 e M\u00e9xico chegaram a um acordo para atualizar o Acordo de Livre Com\u00e9rcio da Am\u00e9rica do Norte, o pacto de 1994 que rege mais de $1,2 trilh\u00f5es de com\u00e9rcio entre as tr\u00eas na\u00e7\u00f5es. O novo acordo ser\u00e1 conhecido como Acordo Estados Unidos-M\u00e9xico-Canad\u00e1, ou USMCA. De acordo com o Washington Post, o Canad\u00e1 est\u00e1 mantendo a maior parte de seu sistema complexo, mas est\u00e1 dando maior participa\u00e7\u00e3o de mercado aos produtores de leite dos EUA. (Vantagem Veterin\u00e1ria \u2013 Washington Post)<\/p>\n<p>\u2022 UE \u2013 PESQUISA DA PSA A Comiss\u00e3o Europ\u00e9ia est\u00e1 solicitando propostas de pesquisa para abordar as etapas necess\u00e1rias para o desenvolvimento de vacinas seguras contra a peste su\u00edna africana (PSA) para su\u00ednos dom\u00e9sticos e javalis. A chamada ser\u00e1 aberta oficialmente em 16 de outubro deste ano, com prazo para inscri\u00e7\u00f5es de 23 de janeiro de 2019. (Animal Pharm)<\/p>\n<p>************************************<br \/>\nPONTO DE VISTA DA BRAKKE CONSULTORIA<\/p>\n<p>Estou um tanto surpreso com os artigos de not\u00edcias desta semana. Embora alguns dos principais fabricantes reconhecidos de produtos de sa\u00fade animal, como Virbac, BIAH, Huvepharma e Royal Canin, sejam mencionados, fiquei impressionado com artigos relacionados \u00e0 Kemin Industries, Wilbur-Ellis Feed, Ameri-Pac, Paine Schwartz Partners, MS Biotech Holdings, Amazon, Pet IQ, American Vanguard, Videntis, TyraTech e VolitionRx. Este \u00e9 um boletim semanal de sa\u00fade animal. A ind\u00fastria de sa\u00fade animal como a conhecemos est\u00e1 mudando bem debaixo de nossos narizes? \u00c9 poss\u00edvel que algumas dessas empresas rec\u00e9m-mencionadas estejam impulsionando o crescimento futuro da ind\u00fastria? Em alguns casos, eles j\u00e1 est\u00e3o impulsionando o crescimento em \u00e1reas de produtos n\u00e3o tradicionais, mas como s\u00e3o privados e\/ou n\u00e3o est\u00e3o em nossas telas de radar, negligenciamos o impacto que est\u00e3o tendo nos segmentos de animais de companhia e de alimenta\u00e7\u00e3o.<\/p>\n<p>Tenha um bom fim de semana!<\/p>\n<p>Ron Brakke<\/p>\n<p>**********************************<br \/>\nEste boletim eletr\u00f4nico \u00e9 propriedade exclusiva da Brakke Consulting, Inc.<br \/>\nQualquer uso do conte\u00fado deste documento deve ser aprovado e devidamente atribu\u00eddo \u00e0 Brakke Consulting, Inc.<\/p>\n<p>Para obter mais informa\u00e7\u00f5es sobre os servi\u00e7os e estudos sindicados da Brakke Consulting, visite nosso website em www.brakkeconsulting.com.<\/p>\n<p>Brakke Consulting, Inc.<br \/>\n12005 Ford Rd., Suite 530<br \/>\nDallas, TX 75234 EUA<\/p>","protected":false},"excerpt":{"rendered":"<p>*********************************** Not\u00edcias e notas sobre sa\u00fade animal da Brakke Consulting para 5 de outubro de 2018 Copyright \u00a9 Brakke Consulting, Inc. Editor: Lynn Fondon DVM MBA ************************************ NAS NOT\u00cdCIAS: Brakke Consulting not\u00edcias Transaction Assistance outras not\u00edcias AgriLabs Alivira Sa\u00fade Animal Amazon American Animal Hospital Association American Vanguard Ameri-Pac Benchmark Biovet Boehringer Ingelheim Datamars Europhartech Huvepharma Ishihara Sangyo Kaisha Kemin Industries Manna Pro Micronutrients EUA MS Biotech Holdings NAVC PetIQ Response Products Royal Canin Tru-Test TyraTech VetFolio Videntis Virbac VolitionRx Wilbur-Ellis Feed ZENOAQ *********************************** BRAKKE CONSULTING, INC. ASSIST\u00caNCIA Deixe a Brakke Consulting prestar assist\u00eancia em todas as suas transa\u00e7\u00f5es. A Brakke Consulting tem sido a localizadora, agente de registro ou consultora de v\u00e1rios projetos conclu\u00eddos com sucesso. Ajudamos com avalia\u00e7\u00f5es e prestamos a devida dilig\u00eancia em transa\u00e7\u00f5es confidenciais, bem como oferecemos aconselhamento executivo em diversas transa\u00e7\u00f5es potenciais. A Brakke Consulting tem experi\u00eancia, vis\u00e3o, capacidade e contatos para fornecer aos clientes servi\u00e7os da mais alta qualidade nos mercados de sa\u00fade animal, animais de estima\u00e7\u00e3o, veterin\u00e1rios e especialidades qu\u00edmicas. Entre em contato com qualquer um de nossos escrit\u00f3rios para uma consulta confidencial. www.BrakkeConsulting.com ********************************** COMUNICADOS DE NOT\u00cdCIAS DA EMPRESA \u2022 Boehringer Ingelheim Animal Health anunciou o lan\u00e7amento do Semintra (solu\u00e7\u00e3o oral de telmisartan), a primeira solu\u00e7\u00e3o l\u00edquida aprovada pela FDA para o controle da hipertens\u00e3o sist\u00eamica felina. (comunicado \u00e0 imprensa da empresa) \u2022 Huvepharma anunciou o lan\u00e7amento de uma vacina com licen\u00e7a condicional para a preven\u00e7\u00e3o de<\/p>\n<div class=\"view-full-post\"><a href=\"https:\/\/brakkeconsulting.com\/pt\/animal-health-news-notes-for-october-5-2018\/\" class=\"view-full-post-btn\">Ver postagem completa<\/a><\/div>\n<p>;<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"class_list":["post-25847","post","type-post","status-publish","format-standard","hentry","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>News from Brakke Consulting<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/brakkeconsulting.com\/pt\/animal-health-news-notes-for-october-5-2018\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"News from Brakke Consulting\" \/>\n<meta property=\"og:description\" content=\"*********************************** Brakke Consulting&#8217;s Animal Health News &amp; Notes for October 5, 2018 Copyright \u00a9 Brakke Consulting, Inc. Editor: Lynn Fondon DVM MBA ************************************ IN THE NEWS: Brakke Consulting news Transaction Assistance other news AgriLabs Alivira Animal Health Amazon American Animal Hospital Association American Vanguard Ameri-Pac Benchmark Biovet Boehringer Ingelheim Datamars Europhartech Huvepharma Ishihara Sangyo Kaisha Kemin Industries Manna Pro Micronutrients USA MS Biotech Holdings NAVC PetIQ Response Products Royal Canin Tru-Test TyraTech VetFolio Videntis Virbac VolitionRx Wilbur-Ellis Feed ZENOAQ *********************************** BRAKKE CONSULTING, INC. TRANSACTION ASSISTANCE Let Brakke Consulting provide assistance for all your transactions. Brakke Consulting has been the finder of record, agent of record or consultant for a number of successfully completed projects. We assist with valuations and provide due diligence on confidential transactions as well as offering executive counsel on a number of potential transactions. Brakke Consulting has the experience, insight, ability and contacts to provide clients with the highest quality services in the animal health, pet, veterinary and specialty chemicals markets. Please contact any of our offices for a confidential consultation. www.BrakkeConsulting.com ********************************** COMPANY NEWS RELEASES \u2022 Boehringer Ingelheim Animal Health announced the launch of Semintra (telmisartan oral solution), the first FDA-approved liquid solution for the control of feline systemic hypertension. (company press release) \u2022 Huvepharma announced the release of a conditionally-licensed vaccine for the prevention ofView Full Post;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/brakkeconsulting.com\/pt\/animal-health-news-notes-for-october-5-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"Brakke Consulting Website\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-05T13:36:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-12T14:15:04+00:00\" \/>\n<meta name=\"author\" content=\"Brakke Consulting\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Brakke Consulting\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/pt\\\/animal-health-news-notes-for-october-5-2018\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/pt\\\/animal-health-news-notes-for-october-5-2018\\\/\"},\"author\":{\"name\":\"Brakke Consulting\",\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/ja\\\/#\\\/schema\\\/person\\\/a5d2c4b59040e54bfe8f4f41f77e04d6\"},\"headline\":\"Animal Health News &#038; Notes for October 5, 2018\",\"datePublished\":\"2018-10-05T13:36:20+00:00\",\"dateModified\":\"2018-10-12T14:15:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/pt\\\/animal-health-news-notes-for-october-5-2018\\\/\"},\"wordCount\":1419,\"articleSection\":[\"Newsletter\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/pt\\\/animal-health-news-notes-for-october-5-2018\\\/\",\"url\":\"https:\\\/\\\/brakkeconsulting.com\\\/pt\\\/animal-health-news-notes-for-october-5-2018\\\/\",\"name\":\"News from Brakke Consulting\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/ja\\\/#website\"},\"datePublished\":\"2018-10-05T13:36:20+00:00\",\"dateModified\":\"2018-10-12T14:15:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/ja\\\/#\\\/schema\\\/person\\\/a5d2c4b59040e54bfe8f4f41f77e04d6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/pt\\\/animal-health-news-notes-for-october-5-2018\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/brakkeconsulting.com\\\/pt\\\/animal-health-news-notes-for-october-5-2018\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/pt\\\/animal-health-news-notes-for-october-5-2018\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/brakkeconsulting.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Animal Health News &#038; Notes for October 5, 2018\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/ja\\\/#website\",\"url\":\"https:\\\/\\\/brakkeconsulting.com\\\/ja\\\/\",\"name\":\"Brakke Consulting Website\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/brakkeconsulting.com\\\/ja\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/brakkeconsulting.com\\\/ja\\\/#\\\/schema\\\/person\\\/a5d2c4b59040e54bfe8f4f41f77e04d6\",\"name\":\"Brakke Consulting\",\"url\":\"https:\\\/\\\/brakkeconsulting.com\\\/pt\\\/author\\\/i5ww2018\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Not\u00edcias da Brakke Consulting","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/brakkeconsulting.com\/pt\/animal-health-news-notes-for-october-5-2018\/","og_locale":"pt_PT","og_type":"article","og_title":"News from Brakke Consulting","og_description":"*********************************** Brakke Consulting&#8217;s Animal Health News &amp; Notes for October 5, 2018 Copyright \u00a9 Brakke Consulting, Inc. Editor: Lynn Fondon DVM MBA ************************************ IN THE NEWS: Brakke Consulting news Transaction Assistance other news AgriLabs Alivira Animal Health Amazon American Animal Hospital Association American Vanguard Ameri-Pac Benchmark Biovet Boehringer Ingelheim Datamars Europhartech Huvepharma Ishihara Sangyo Kaisha Kemin Industries Manna Pro Micronutrients USA MS Biotech Holdings NAVC PetIQ Response Products Royal Canin Tru-Test TyraTech VetFolio Videntis Virbac VolitionRx Wilbur-Ellis Feed ZENOAQ *********************************** BRAKKE CONSULTING, INC. TRANSACTION ASSISTANCE Let Brakke Consulting provide assistance for all your transactions. Brakke Consulting has been the finder of record, agent of record or consultant for a number of successfully completed projects. We assist with valuations and provide due diligence on confidential transactions as well as offering executive counsel on a number of potential transactions. Brakke Consulting has the experience, insight, ability and contacts to provide clients with the highest quality services in the animal health, pet, veterinary and specialty chemicals markets. Please contact any of our offices for a confidential consultation. www.BrakkeConsulting.com ********************************** COMPANY NEWS RELEASES \u2022 Boehringer Ingelheim Animal Health announced the launch of Semintra (telmisartan oral solution), the first FDA-approved liquid solution for the control of feline systemic hypertension. (company press release) \u2022 Huvepharma announced the release of a conditionally-licensed vaccine for the prevention ofView Full Post;","og_url":"https:\/\/brakkeconsulting.com\/pt\/animal-health-news-notes-for-october-5-2018\/","og_site_name":"Brakke Consulting Website","article_published_time":"2018-10-05T13:36:20+00:00","article_modified_time":"2018-10-12T14:15:04+00:00","author":"Brakke Consulting","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Brakke Consulting","Tempo estimado de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/brakkeconsulting.com\/pt\/animal-health-news-notes-for-october-5-2018\/#article","isPartOf":{"@id":"https:\/\/brakkeconsulting.com\/pt\/animal-health-news-notes-for-october-5-2018\/"},"author":{"name":"Brakke Consulting","@id":"https:\/\/brakkeconsulting.com\/ja\/#\/schema\/person\/a5d2c4b59040e54bfe8f4f41f77e04d6"},"headline":"Animal Health News &#038; Notes for October 5, 2018","datePublished":"2018-10-05T13:36:20+00:00","dateModified":"2018-10-12T14:15:04+00:00","mainEntityOfPage":{"@id":"https:\/\/brakkeconsulting.com\/pt\/animal-health-news-notes-for-october-5-2018\/"},"wordCount":1419,"articleSection":["Newsletter"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/brakkeconsulting.com\/pt\/animal-health-news-notes-for-october-5-2018\/","url":"https:\/\/brakkeconsulting.com\/pt\/animal-health-news-notes-for-october-5-2018\/","name":"Not\u00edcias da Brakke Consulting","isPartOf":{"@id":"https:\/\/brakkeconsulting.com\/ja\/#website"},"datePublished":"2018-10-05T13:36:20+00:00","dateModified":"2018-10-12T14:15:04+00:00","author":{"@id":"https:\/\/brakkeconsulting.com\/ja\/#\/schema\/person\/a5d2c4b59040e54bfe8f4f41f77e04d6"},"breadcrumb":{"@id":"https:\/\/brakkeconsulting.com\/pt\/animal-health-news-notes-for-october-5-2018\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/brakkeconsulting.com\/pt\/animal-health-news-notes-for-october-5-2018\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/brakkeconsulting.com\/pt\/animal-health-news-notes-for-october-5-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/brakkeconsulting.com\/"},{"@type":"ListItem","position":2,"name":"Animal Health News &#038; Notes for October 5, 2018"}]},{"@type":"WebSite","@id":"https:\/\/brakkeconsulting.com\/ja\/#website","url":"https:\/\/brakkeconsulting.com\/ja\/","name":"Site da Brakke Consulting","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/brakkeconsulting.com\/ja\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/brakkeconsulting.com\/ja\/#\/schema\/person\/a5d2c4b59040e54bfe8f4f41f77e04d6","name":"Brakke Consultoria","url":"https:\/\/brakkeconsulting.com\/pt\/author\/i5ww2018\/"}]}},"_links":{"self":[{"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/posts\/25847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/comments?post=25847"}],"version-history":[{"count":1,"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/posts\/25847\/revisions"}],"predecessor-version":[{"id":25848,"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/posts\/25847\/revisions\/25848"}],"wp:attachment":[{"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/media?parent=25847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/categories?post=25847"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/brakkeconsulting.com\/pt\/wp-json\/wp\/v2\/tags?post=25847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}